{"id":1918,"date":"2026-07-03T12:45:12","date_gmt":"2026-07-03T12:45:12","guid":{"rendered":"https:\/\/integrativer-kiga-bayreuth.de\/?page_id=1918"},"modified":"2026-07-14T11:04:44","modified_gmt":"2026-07-14T11:04:44","slug":"konzept","status":"publish","type":"page","link":"https:\/\/integrativer-kiga-bayreuth.de\/en\/konzept\/","title":{"rendered":"Concept"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1918\" class=\"elementor elementor-1918\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39ca75d e-flex e-con-boxed e-con e-parent\" data-id=\"39ca75d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e403a1 elementor-widget elementor-widget-heading\" data-id=\"9e403a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Konzept<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e8700 elementor-widget elementor-widget-heading\" data-id=\"c7e8700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wie wir die<br>Kinder betreuen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-641bf74 e-flex e-con-boxed e-con e-parent\" data-id=\"641bf74\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73ffc14 e-grid e-con-full e-con e-child\" data-id=\"73ffc14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-cb302f9 e-con-full e-flex e-con e-child\" data-id=\"cb302f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#grundkonzept\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a3e869 elementor-widget elementor-widget-image\" data-id=\"9a3e869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_house.svg\" class=\"attachment-large size-large wp-image-447\" alt=\"Icon Haus f\u00fcr den Bereich Unser Haus und Geb\u00e4ude\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6545117 elementor-position-inline-end elementor-mobile-position-block-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6545117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><defs><clipPath id=\"clippath\"><rect x=\"14.96\" y=\"34.98\" width=\"70.08\" height=\"30.03\" style=\"fill: none;\"><\/rect><\/clipPath><\/defs><circle cx=\"50\" cy=\"50\" r=\"50\" style=\"fill: #ffeb8b;\"><\/circle><g style=\"clip-path: url(#clippath);\"><path d=\"M65.68,34.98l19.36,14.73-19.6,15.3,3.56-10.2-53.92,3.17-.12-15.87,54.16,3.17-3.44-10.31Z\" style=\"fill: #56431a; fill-rule: evenodd;\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGrundkonzept<br>&amp; Gruppen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-601d477 e-con-full e-flex e-con e-child\" data-id=\"601d477\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#tagesablauf\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a341b2d elementor-widget elementor-widget-image\" data-id=\"a341b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_time.svg\" class=\"attachment-large size-large wp-image-448\" alt=\"Icon Uhr f\u00fcr \u00d6ffnungszeiten und Tagesablauf des Kindergartens\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7447cb6 elementor-position-inline-end elementor-mobile-position-block-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7447cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><defs><clipPath id=\"clippath\"><rect x=\"14.96\" y=\"34.98\" width=\"70.08\" height=\"30.03\" style=\"fill: none;\"><\/rect><\/clipPath><\/defs><circle cx=\"50\" cy=\"50\" r=\"50\" style=\"fill: #ffeb8b;\"><\/circle><g style=\"clip-path: url(#clippath);\"><path d=\"M65.68,34.98l19.36,14.73-19.6,15.3,3.56-10.2-53.92,3.17-.12-15.87,54.16,3.17-3.44-10.31Z\" style=\"fill: #56431a; fill-rule: evenodd;\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTagesablauf\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-5eb2a25 e-con-full e-flex e-con e-child\" data-id=\"5eb2a25\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#ernaehrung\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d72a3f4 elementor-widget elementor-widget-image\" data-id=\"d72a3f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_boy_balloon.svg\" class=\"attachment-large size-large wp-image-451\" alt=\"Icon Junge mit Luftballon als verspieltes Dekorationselement\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b99954 elementor-position-inline-end elementor-mobile-position-block-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2b99954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><defs><clipPath id=\"clippath\"><rect x=\"14.96\" y=\"34.98\" width=\"70.08\" height=\"30.03\" style=\"fill: none;\"><\/rect><\/clipPath><\/defs><circle cx=\"50\" cy=\"50\" r=\"50\" style=\"fill: #ffeb8b;\"><\/circle><g style=\"clip-path: url(#clippath);\"><path d=\"M65.68,34.98l19.36,14.73-19.6,15.3,3.56-10.2-53.92,3.17-.12-15.87,54.16,3.17-3.44-10.31Z\" style=\"fill: #56431a; fill-rule: evenodd;\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tErn\u00e4hrung &amp;<br>Bewegung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-5a4a890 e-con-full e-flex e-con e-child\" data-id=\"5a4a890\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#elternarbeit\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d23c855 elementor-widget elementor-widget-image\" data-id=\"d23c855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_love.svg\" class=\"attachment-large size-large wp-image-449\" alt=\"Icon Herz als Symbol f\u00fcr Geborgenheit und liebevolle Betreuung im Kindergarten\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7343dbf elementor-position-inline-end elementor-mobile-position-block-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7343dbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><defs><clipPath id=\"clippath\"><rect x=\"14.96\" y=\"34.98\" width=\"70.08\" height=\"30.03\" style=\"fill: none;\"><\/rect><\/clipPath><\/defs><circle cx=\"50\" cy=\"50\" r=\"50\" style=\"fill: #ffeb8b;\"><\/circle><g style=\"clip-path: url(#clippath);\"><path d=\"M65.68,34.98l19.36,14.73-19.6,15.3,3.56-10.2-53.92,3.17-.12-15.87,54.16,3.17-3.44-10.31Z\" style=\"fill: #56431a; fill-rule: evenodd;\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tElternarbeit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc18f16 e-flex e-con-boxed e-con e-parent\" data-id=\"fc18f16\" data-element_type=\"container\" data-e-type=\"container\" id=\"grundkonzept\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;waves&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M790.5,93.1c-59.3-5.3-116.8-18-192.6-50c-29.6-12.7-76.9-31-100.5-35.9c-23.6-4.9-52.6-7.8-75.5-5.3\n\tc-10.2,1.1-22.6,1.4-50.1,7.4c-27.2,6.3-58.2,16.6-79.4,24.7c-41.3,15.9-94.9,21.9-134,22.6C72,58.2,0,25.8,0,25.8V100h1000V65.3\n\tc0,0-51.5,19.4-106.2,25.7C839.5,97,814.1,95.2,790.5,93.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10a7f80 e-con-full e-flex e-con e-child\" data-id=\"10a7f80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-56928a3 e-con-full e-flex e-con e-child\" data-id=\"56928a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8ba8c3 elementor-widget elementor-widget-heading\" data-id=\"c8ba8c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Grundkonzept<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cc3359 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8cc3359\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Grundprinzipien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4249347 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4249347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Unsere grunds\u00e4tzliche Haltung ist es, jeden Menschen so anzunehmen wie er ist. Jedes Kind wird mit seinen individuellen F\u00e4higkeiten und Bed\u00fcrfnissen akzeptiert, gesch\u00e4tzt und respektiert und hat das Recht in der Gemeinschaft zu leben, zu spielen und zu lernen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9fce9 elementor-widget elementor-widget-n-accordion\" data-id=\"3f9fce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;multiple&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6670\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6670\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Inklusion<\/div><div class=\"more\">Mehr \u00fcber Inklusion erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6670\" class=\"elementor-element elementor-element-96e9af0 e-con-full e-flex e-con e-child\" data-id=\"96e9af0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f90a07 elementor-widget elementor-widget-text-editor\" data-id=\"5f90a07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u201eEs ist normal, verschieden zu sein.\u201c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a035e elementor-widget elementor-widget-text-editor\" data-id=\"04a035e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Alle Kinder haben aufgrund spezifischer Entwicklungsverl\u00e4ufe besondere St\u00e4rken und Schw\u00e4chen. Sie ben\u00f6tigen je nach Auspr\u00e4gung eine individuelle Unterst\u00fctzung und ein differenziertes Lernziel.<\/p><p>Seit mehr als 45 Jahren ist uns deshalb die Inklusion von Kindern mit Beeintr\u00e4chtigung in die Gemeinschaft ein wesentliches Anliegen. Dabei legen wir gro\u00dfen Wert auf die gemeinsame F\u00f6rderung innerhalb der Gemeinschaft unter Ber\u00fccksichtigung der individuellen Voraussetzungen und Bed\u00fcrfnisse jedes einzelnen Kindes.<\/p><p>Geistig, seelisch und\/oder k\u00f6rperlich beeintr\u00e4chtigte Kinder tragen zu einer wesentlichen Bereicherung des sozialen Lernens in der Gruppe bei und werden wiederum von der Gruppe stark gef\u00f6rdert. Im Spiel lernen alle Kinder den vorurteilsfreien Umgang miteinander. Gemeinsamkeiten werden in den Vordergrund gestellt und Verschiedenheiten anerkannt.<\/p><p>Die p\u00e4dagogische wie auch heilp\u00e4dagogische F\u00f6rderung erfolgt in der Gesamtgruppe oder in Kleingruppen. Dem Kind mit F\u00f6rderbedarf kann dabei ein pers\u00f6nlicher Assistent zur Seite gestellt werden, der auch Ansprechpartner f\u00fcr alle anderen Kinder ist. Wo es sinnvoll ist, besteht auch die M\u00f6glichkeit der Einzelf\u00f6rderung.<\/p><p>Mit dieser Arbeit in unserem Kindergarten sehen wir uns als Baustein f\u00fcr das Ziel einer inklusiven Gesellschaft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6671\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6671\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Montessori-P\u00e4dagogik<\/div><div class=\"more\">Mehr \u00fcber Montessori-P\u00e4dagogik erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6671\" class=\"elementor-element elementor-element-2810785 e-con-full e-flex e-con e-child\" data-id=\"2810785\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0109171 elementor-widget elementor-widget-text-editor\" data-id=\"0109171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die p\u00e4dagogische Arbeit basiert auf reform- und heilp\u00e4dagogischen Grundlagen, insbesondere auf der P\u00e4dagogik nach Maria Montessori. Durch das Prinzip der vorbereiteten Umgebung, mit den besonderen didaktischen Materialien, die die Lernbed\u00fcrfnisse der sensiblen Phasen des Kindes ber\u00fccksichtigen, wird es zu selbstst\u00e4ndigem und verantwortungsbewusstem Handeln angeregt. Die Achtung der Pers\u00f6nlichkeit und die freie Entfaltung der sch\u00f6pferischen Gaben des Kindes haben in unserer Einrichtung einen besonderen Stellenwert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56bb55a elementor-widget elementor-widget-text-editor\" data-id=\"56bb55a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u201eHilf mir, es selbst zu tun.\u201c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41c6e00 elementor-widget elementor-widget-text-editor\" data-id=\"41c6e00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Diesen Spruch eines Kindes machte Maria Montessori, die Begr\u00fcnderin der Reformp\u00e4dagogik, zu ihrem Leitsatz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c192c elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"43c192c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_2\" data-name=\"Ebene 2\" viewBox=\"0 0 500 500\"><path d=\"M212.44,226.69s.03-7.3.03-7.3c-.09-.85.23-5.02-.26-5.48-1.07-1.02-2.71-1.07-4.3-1.23-1.9-.12-3.77-.05-5.47.92-1.64.86-3.43,2.53-5.62,4.06-2.18,1.55-4.76,2.88-7.4,3.65-17.06,5.18-34.62-5.04-36.39-23.21-1.19-11.27,5.53-22.72,15.95-27.26,7.7-3.41,16.75-3.19,24.57-.22,4.22,1.58,6.25,4.41,10.11,4.6,1.5,0,3.21-.13,4.62-.36,1.16-.24,2.23-.38,2.85-.95.01-.04-.2.09-.34.37-.09.16-.17.42-.19.54-.57-12.89-1.58-25.78-1.92-38.67-.34-9.73-.18-19.47-.17-29.2,0,0,6.96,6.96,6.96,6.96-51.52-.3-125.69-1.87-177.93-2.9,0,0,4.06-4.06,4.06-4.06-.29,26.42-1.61,62.97-1.38,88.97.11,29.65,1.72,59.31,1.45,88.97,0,0-4.13-4.13-4.13-4.13l67.87-.24c1.06-.04,1.98.39,2.79.98,5.12,3.83,6.85,10.54,6.33,16.63-.25,3.78-2.76,7.44-4.47,10.23-2.04,3.58-2.54,7.22-2.59,11.52-.04,2.68.41,5.15,1.36,7.54,2.78,7.2,10.23,12.2,17.95,11.97,9.74.04,18.4-8.36,18.64-18.09.12-4.73-.57-9.23-3.19-13.03-2.48-3.43-6.12-7.35-6.52-12.18-.69-6.37.97-15.75,7.71-15.82,0,0,72.05.13,72.05.13,0,0-4.48,4.33-4.48,4.33.71-12.06,1.68-25.14,1.59-37.16,0,0,0-12.44,0-12.44-.02-1.6,1.28-2.92,2.89-2.92,1.53,0,2.78,1.2,2.88,2.7l.79,12.48c.54,8.29.77,16.81.78,25.13,0,0,.03,12.51.03,12.51,0,2.39-1.93,4.33-4.31,4.33-.75.04-71.88.12-72.6.12.87.1,1.93-.17,2.48-.8-.37.78-.69,3.08-.67,4.58-.12,2.54.42,3.68,2.06,5.85,2,2.51,4.45,5.79,5.65,9.05,3.98,10.66,2.42,23.13-5.5,31.44-10.51,11.57-29.68,11.87-40.52.57-5.3-5.28-8.32-12.97-8.07-20.4,0-5.13,1.06-11.19,3.87-15.83,1.45-2.62,3.08-4.2,3.42-6.8.23-2.94-.33-6.56-2.65-8.55-.02-.01,0,0,0,0h0s.11.07.11.07c0,0,2.19.59,2.19.59,0,0-67.87-.24-67.87-.24-2.28,0-4.14-1.85-4.13-4.13-.27-29.66,1.33-59.31,1.45-88.97-.15-25.88-.72-62.76-1.38-88.97-.05-2.26,1.81-4.11,4.06-4.06,52.55-.6,126.15-3,177.93-2.89,3.84,0,6.96,3.11,6.96,6.96,0,9.73.16,19.47-.18,29.2-.34,12.78-1.34,25.55-1.91,38.33-.02,1.29-.21,2.56-.8,3.76-3.05,5.97-10.73,5.95-16.36,5.8-2.39-.15-5.11-1.02-7.04-2.19-2.58-1.54-4.11-2.75-5.92-3.54-5.55-2.29-12.55-2.74-18.17-.45-7.7,3.11-12.81,11.37-12.15,19.7,1.19,14.18,14.64,21.57,27.79,17.86,6.09-1.35,9.67-7.64,16.3-8.61,6.37-.8,14.98.73,14.46,8.93,0,0,0,3.65,0,3.65l.03,7.3c-.11,4.02-5.95,3.99-6.04,0h0Z\"><\/path><path d=\"M220.93,284.54c1.16,23.8,1.46,48.06,1.52,71.9,0,0,0,.05,0,.05,0-.02,0,.13,0-.07.02-.21-.05-.5-.06-.71-.09-.95-.78-2.33-1.3-2.78-.6-.57-.8-.62-.74-.59,1.08.37,2.72.45,4.06.48.77.02,1.32-.04,2.03-.34,2.7-1.39,4.82-3.75,8.43-5.54,10.45-5.21,23.91-4.47,33.23,2.6,22.39,17.06,11.2,52.58-17.17,52.83-6.55.16-14.12-1.69-19.36-5.54-1.95-1.22-3.05-1.9-5.22-1.79-2.19.04-4.54.53-6.12,2.01-.14.14-.22.22-.31.34,0,0-.02.02,0,0l.02-.03s.09-.15.09-.15c0,0,.71-2.64.71-2.64l.06,67.89-5.34-5.34c56.76-.11,121.23,0,177.93,1.26,0,0-4.07,4.07-4.07,4.07.27-14.83.45-29.66.47-44.48.29-14.84-.9-29.66-1.35-44.48-.15-25.25-.37-63.37-.4-88.97,0,0,5.35,5.35,5.35,5.35-.11,0-67.88.23-67.98.23-1.49.02-2.74-.67-3.84-1.55-3.4-2.69-5.47-7.03-6.12-11.13-.78-4.17-.29-9.22,1.9-12.82,1.01-1.8,1.89-3.02,2.5-4.13,1.96-3.43,2.41-6.77,2.48-10.96.08-20.32-27.27-25.6-34.72-6.63-1.64,4.49-1.28,10.32.29,14.56,1.02,2.62,2.44,4.19,4.3,6.66,1.72,2.1,3.75,5.9,4.01,9.09.31,5.09.18,11.36-4.05,15.18-1.5,1.3-3.88,2.11-5.92,1.62-8.75-1.83-18.18-2.97-27.08-2.66-9.3.42-18.89,1.36-28.13,2.6-7.14.75-8.64-9.55-1.52-10.83,14.64-1.91,29.61-3.96,44.33-2.37,5.07.53,9.83,1.23,14.88,2.3-.43-.07-1.06-.17-1.49-.13-1.05.04-2.2.53-2.75,1.33.5-1.24.66-4.08.52-5.66-.5-2.9-3.1-4.87-4.86-7.71-3.9-5.53-5.21-12.79-4.93-19.23.78-19.96,21.76-33.37,40.22-25.67,11,4.36,18.51,15.85,18.11,27.67-.04,3.5-.39,7.2-1.59,10.99-.84,3.14-3.34,6.96-4.82,9.37-.81,1.51-.91,2.28-.84,3.89.05,1.94.55,4,1.71,5.43.17.19.32.38.48.5,0,0-.21-.13-.21-.13l-2.8-.75s67.87.23,67.91.23c2.95,0,5.33,2.41,5.32,5.35,0,0-.15,44.48-.15,44.48-.19,21.56.23,45.31-1.23,66.72-.84,22.24-.16,44.48.1,66.72.04,2.26-1.81,4.11-4.07,4.07-56.69,1.28-121.19,1.34-177.94,1.26-2.95,0-5.33-2.39-5.33-5.34,0,0,.07-67.89.07-67.89-.04-1.2.39-2.27,1.06-3.19,4.85-6.56,14.81-8.52,22.17-5.59,3.31,1.44,5.95,3.8,8.9,4.72,6.85,2.12,15.46,1.62,20.89-3.64,8.41-7.49,7.59-21.67-1.97-27.76-5.82-3.85-13.98-3.71-19.93-.43-2.47,1.45-5.52,4.63-8.88,6.23-2.06,1.05-4.53,1.69-6.86,1.78-3.42.11-6.72-.08-10.13-1.26-3.5-1.14-7.23-4.79-6.97-9.17.08-23.79.35-47.99,1.52-71.74.54-6.9,10.39-6.87,10.93,0h0Z\"><\/path><path d=\"M311.93,196.9c-.25-.14-1-.35-1.3-.18,1.72-1.18,3.15-3.92,4.06-5.92.61-1.76.54-3.12.18-5.23-.6-3.17-1.27-6.92-.86-10.31.39-4.16,1.85-7.81,3.57-11.31,1.47-2.76,3.37-5.4,5.7-7.49,22.77-20.01,55.48,5.29,41.66,32.31-2.27,4.45-5.74,9.03-10.16,11.78-2.53,1.7-4.98,2.55-6.56,4.92-1.27,2.02-2.31,4.84-2.25,7.26,0,1.07.25,2.25.63,3.05,0,0-1.11-1.01-1.11-1.01.01,0,60.3,31.16,60.31,31.17,0,0-3.51,1.13-3.51,1.13,22.88-45.9,48.44-98.68,70.62-145,1.33-3.46,2.02-7.26,3.99-10.45,0,0,2.61-4.91,2.61-4.91,0,0,3,9.27,3,9.27-22.56-12.1-55.44-29.88-78.21-42.46-25.71-14.09-52.61-28.32-78.59-41.71,0,0,4.51-1.46,4.51-1.46-9.22,17.96-22.23,42.56-31.21,60.27-.24.49-.62.9-1.05,1.16-6.83,3.73-16.76.49-20.92-5.8-1.83-2.8-2.83-5.1-5.09-7.27-3.86-3.69-9.42-6.85-14.91-7.35-8.31-.88-16.78,3.87-20.35,11.42-4.29,8.4-1.72,19.33,5.7,25.07,4.75,3.45,10.7,5.66,16.51,4.91,3.29-.41,6.5-1.56,10.18-1.08,5.78.79,15.78,6.91,12.91,12.93,0,0-16.21,32.17-16.21,32.17-5.32,10.77-9.9,21.92-14.94,32.82,0,0-1.82-6.75-1.82-6.75,4.15,2.48,8.27,4.98,12.31,7.63,4.07,2.72,7.91,5.68,11.12,9.48,1.3,1.57,1.08,3.9-.49,5.2-.95.79-2.21,1.01-3.32.72-9.57-2.79-17.42-9.03-25.58-14.48-2.13-1.47-2.74-4.32-1.5-6.53,2.95-5.24,6-10.42,9.05-15.6,3.03-5.2,6-10.42,8.82-15.72,0,0,16.6-31.98,16.6-31.98,0,0,.14-.24.14-.24-.19.3-.35.69-.36,1.03,0,.17.03.33.03.36-.17-.33-.47-.67-.98-1.12-1.48-1.24-3.85-2.73-5.81-3.27-1.49-.38-2.71-.26-4.54.04-3.14.6-6.89,1.26-10.25.84-5.43-.62-10.3-2.68-14.64-5.67-10.44-7.19-14.2-22.18-8.35-33.43,6.39-13.36,23.53-18.69,36.44-11.53,4.45,2.24,9.05,5.68,11.81,10.08.96,1.45,1.73,2.9,2.47,3.99,2.22,3.92,9.6,5.8,12.7,4.08l-1.05,1.16c5.14-10.08,10.27-20.16,15.34-30.27l15.27-30.31c.83-1.64,2.83-2.31,4.48-1.48,19.87,10.03,39.76,20.02,59.79,29.72,12.85,6.16,46.96,22.46,60.23,28.77,13.4,6.37,26.73,12.85,40.04,19.41,3.36,1.66,4.74,5.73,3.09,9.09,0,0-.09.18-.09.18l-2.45,4.99c-1.44,3.46-4.12,6.25-6.14,9.35-16.38,30.05-39.29,72.44-55.45,102.79-6.95,13.1-13.92,26.19-20.79,39.33-.65,1.29-2.23,1.81-3.51,1.13,0,0-60.57-30.67-60.57-30.67-1.07-.52-1.51-1.68-1.89-2.65-1.82-5.12-.41-10.55,2.34-15.06,1.87-3.08,5.48-4.96,8.21-6.66,3.63-2.37,6.01-5.68,8.04-9.63,2.65-4.93,3.17-10.75,1.48-15.99-4.44-14.11-22.53-18.79-33.22-8.61-1.75,1.58-3.14,3.59-4.24,5.67-2.06,4.16-3.32,8.39-2.71,12.91.5,3.69,1.86,7.74.79,11.77-.93,3.37-2.46,5.91-4.68,8.7-.79.97-2.1,2.14-3.49,2.77-3.31,1.64-8.05-.53-6.4-4.66.86-1.82,3.09-2.54,4.85-1.59h0Z\"><\/path><path d=\"M43.49,285.11c.55,14.78.12,29.57-.3,44.33-.82,29.56-.81,58.94-.36,88.5,0,0,.66,44.33.66,44.33,0,0-5.84-5.76-5.84-5.76,49.28.91,98.62,1.99,147.9,1.3,6.35-.19,12.73-.2,18.99-.96,0,0,.43-.07.43-.07.05-.02.11-.03.16-.03,0,0,1.42-.12,1.42-.12,7.96-.26,8.77,10.79.75,11.87-7.13,1.11-14.36,1.02-21.5,1.26-21.24.39-42.46.22-63.68.04-30.1-.3-60.18-.81-90.27-1.45-.86-16.69-1.58-33.41-2.09-50.1-1.14-44.48-2.03-89.19,1.8-133.56.97-7.28,11.5-6.97,11.93.44h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVerschiedene Materialien\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMaria Montessori hat vielf\u00e4ltige Materialien entwickelt und sie in unterschiedlichen Bereichen zugeteilt. Dazu geh\u00f6ren \u00dcbungen des t\u00e4glichen Lebens, Sinnesmaterialien, Materialien f\u00fcr Sprache, Mathematik und die kosmische Erziehung. Jedes Material hat einen hohen Aufforderungscharakter und leitet die Kinder zum selbst\u00e4ndigen Handeln an.  Alle Materialien k\u00f6nnen in unterschiedlichen Schwierigkeitsgraden genutzt werden und geben dem Kind die M\u00f6glichkeit zur eigenen Fehlerkontrolle.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fea4959 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fea4959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_2\" data-name=\"Ebene 2\" viewBox=\"0 0 500 500\"><path d=\"M458.67,106.95c1.89,87.39,2.05,178.49,1.57,265.91-.41,25.78-.39,63.14-1.11,88.64,0,2.27-1.86,4.13-4.12,4.13,0,0-406.67,0-406.67,0-2.27,0-4.11-1.83-4.12-4.09l-3.25-412.55c-.02-2.23,1.78-4.06,4.01-4.08,0-.02,410.02.09,410.03.08,2.14-.1,3.98,1.59,3.97,3.75.1.04-1.59,27.16-1.52,27.26-.27,3.11-4.67,3-4.89,0,0,0-1.52-27.05-1.52-27.05,0,0,3.96,3.96,3.96,3.96,0,0-410,.08-410,.08,0,0,4.04-4.08,4.04-4.08l3.41,412.55s-4.12-4.09-4.12-4.09h406.67s-4.13,4.12-4.12,4.12c-.85-42.58-1.24-90.36-1.29-132.96-.23-56.56.17-120.78.9-177.27.29-14.77.46-29.55.84-44.32.18-4.6,7.05-4.83,7.33,0h0Z\"><\/path><path d=\"M144.24,467c-.06,0-.12,0-.18,0-3.04-.1-5.42-2.64-5.32-5.68.03-1.02,3.38-103.49,3.38-206.09s-3.34-172.95-3.38-173.65c-.15-3.03,2.19-5.61,5.23-5.76,3.02-.17,5.61,2.19,5.76,5.23.03.7,3.39,71.34,3.39,174.18s-3.35,205.43-3.39,206.46c-.1,2.97-2.54,5.32-5.49,5.32Z\"><\/path><path d=\"M312.07,472.28c-3.04,0-5.5-2.46-5.5-5.5V53.67c0-3.04,2.46-5.5,5.5-5.5s5.5,2.46,5.5,5.5v413.12c0,3.04-2.46,5.5-5.5,5.5Z\"><\/path><path d=\"M430.91,186.04s-.09,0-.14,0c-1.35-.03-136.03-3.27-180.77-3.27s-203.29,3.24-204.89,3.27c-.04,0-.08,0-.11,0-2.99,0-5.44-2.39-5.5-5.39-.06-3.04,2.35-5.55,5.39-5.61,1.6-.03,160.24-3.27,205.11-3.27s179.68,3.24,181.04,3.27c3.04.07,5.44,2.59,5.37,5.63-.07,2.99-2.52,5.37-5.5,5.37Z\"><\/path><path d=\"M455,347.19c-.09,0-.18,0-.28,0-1.06-.05-106.7-5.27-178.33-5.27s-229.63,5.22-231.22,5.27c-3.04.09-5.58-2.28-5.68-5.31-.1-3.04,2.28-5.58,5.31-5.68,1.59-.05,159.72-5.28,231.58-5.28s177.81,5.23,178.87,5.28c3.03.15,5.37,2.73,5.22,5.77-.15,2.94-2.58,5.23-5.49,5.23Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tVorbereitete Umgebung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDie vorbereitete Umgebung ist eine wichtige S\u00e4ule in der Montessori-P\u00e4dagogik.<br>\nDie Strukturierung des Raumes und die Anordnung der Materialien ist eine zentrale Aufgabe der P\u00e4dagogin. Jedes Material ist nur einmal vorhanden und hat seinen festen Platz. Das bietet den Kindern Orientierung und Sicherheit und fordert zum selbstt\u00e4tigen Handeln auf. Diese \u00e4u\u00dferen Prinzipien von Struktur und Ordnung helfen dem Kind zur inneren Ordnung zu gelangen.<br>\nIn offenen Regalen, auf Augenh\u00f6he und Reichweite der Kinder stehen die Materialien bereit und sind frei zug\u00e4nglich. Die Materialien werden von uns sorgf\u00e4ltig gepflegt, immer wieder erweitert und den Erfordernissen der heutigen Zeit, sowie den individuellen Bed\u00fcrfnissen der Kinder angepasst.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5768c0 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f5768c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_2\" data-name=\"Ebene 2\" viewBox=\"0 0 500 500\"><path d=\"M17.59,486.14c-5.14-23.05-8.89-46.3-8.9-70.02.09-9.64,1.65-19.35,2.47-28.92.73-8.08,1.31-16.17,1.57-24.27.08-2.66.14-5.43.1-7.94-.25-2.8,1.82-4.55,4.49-4.6,23.27-2.46,46.58-1.25,69.91-1.34,22.66.19,47.34.58,69.91,1.34,0,0-4.49,4.56-4.49,4.56-.09-40.67-.89-81.25.71-121.92.26-4.7.88-9.72.87-14.38.62,3.17,4.97,3.78,6.5,1.01.04-.07.09-.19.11-.22l.03-.06c.04-.12,0,0-.03.1-.07.25-.14.59-.19.87-1.05,4.61-7.74,3.25-7.01-1.33.2-1.04.39-2.36,1.21-3.39,2.16-2.61,6.37-1.29,6.54,2.42.12,2.24-.04,4.56-.14,6.76-.64,8.62-.86,17.16-.88,25.86-.09,34.7.59,69.44,1.27,104.14.06,2.51-1.99,4.57-4.49,4.56-5.83.22-11.65.35-17.48.5-16.13.48-36.21.65-52.43.84-23.33-.08-46.64,1.12-69.91-1.34,0,0,4.5-4.61,4.49-4.59.05,17.99-2.17,35.73-4.05,53.56,0,0-.18,1.96-.18,1.96l-.07,1.98c-.1,1.86-.19,6.06-.14,7.96.29,21.38,3.75,43.09,8.3,63.98,1.18,5.2-6.56,7.4-8.07,1.92h0Z\"><\/path><path d=\"M172.5,192.39c30.19.82,61.12,1.34,91.37,1.07,18.42-.05,36.74.28,55.17,1.19,0,0-4.26,4.05-4.26,4.05-.41-43.68-.28-87.46-1.7-131.11,0-7.99,1.58-16.37,5.97-23.24,1.07-1.84,3.13-3.18,5.22-3.12.5.15,156.64-.11,157.12,0,3.23.02,5.8,2.77,5.61,6,0,0-2.15,37.59-2.15,37.59-.12,2.13-1.94,3.75-4.07,3.63-1.98-.11-3.52-1.7-3.63-3.63,0,0-2.15-37.59-2.15-37.59,0,0,6.01,6.01,6,6,0,0-156.64,0-156.64,0l4.69-2.25s0,0,0,0c.07-.09.03-.03,0,0-.27.37-.5.74-.74,1.16-2.94,5.3-3.89,11.61-3.75,17.68.1,3,.1,11.33.1,14.46-.24,38.19-1,76.32-1.69,114.49-.04,2.28-1.93,4.1-4.21,4.06-23.93-.58-49.03-.02-73.04.82-24.48.6-48.9.76-73.39.75-7.97-.29-7.96-11.9.18-12h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGruppenarbeit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEinzeln oder in der Kleingruppe wird das Kind durch die Erzieherin in das Material eingef\u00fchrt. Die Vorstellung erfolgt durch die Drei-Stufen-Lektion nach der die Kinder selbst in der Lage sind die Gegenst\u00e4nde zu erkennen und zu benennen. So werden Eigenschaften der Materialien wie z.B. Farbe, Form, Gr\u00f6\u00dfe, Gewicht, und Klang dargestellt.<br>\nIn der Freispielzeit besteht f\u00fcr die Kinder die M\u00f6glichkeit \u00dcbungen zu wiederholen. Das Kind bekommt Raum, um seine eigenen Erfahrungen zu machen, Fehler zu korrigieren und Erlerntes in anderen Bereichen anzuwenden.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6672\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6672\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Vorbereitung auf die Schule und das Leben<\/div><div class=\"more\">Mehr \u00fcber Vorbereitung erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6672\" class=\"elementor-element elementor-element-8ffdda6 e-con-full e-flex e-con e-child\" data-id=\"8ffdda6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad3da74 elementor-widget elementor-widget-text-editor\" data-id=\"ad3da74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Vorbereitung beginnt bereits mit der Geburt. Damit ein Kind ein stabiles Fundament f\u00fcr sein Leben entwickeln kann, ben\u00f6tigt es vielf\u00e4ltige Kompetenzen. Deren F\u00f6rderung und Ausbau gelingt am besten in gemeinsamer Zusammenarbeit mit Familie und P\u00e4dagogen (\u201eErziehungspartnerschaft\u201c, siehe Elternarbeit).<\/p><p>Unsere Aufgabe als Erzieherin ist es, das Kind entwicklungsangemessen anzuregen und zu unterst\u00fctzen. Eine wichtige Rolle spielen dabei die Verbindung von Spielen und Lernen und das Lernen mit allen Sinnen. Das Montessori-Material ist als konkretes Erfahrungsmaterial besonders geeignet, um vielf\u00e4ltige F\u00e4higkeiten, Fertigkeiten, vorschulische Basiskompetenzen sowie fundiertes Wissen und K\u00f6nnen zu erlangen.<\/p><p>Einzeln oder in der Kleingruppe wird das Kind durch die Erzieherin in das Material (z. B. mit der Drei-Stufen-Lektion) eingef\u00fchrt. In der Freispielzeit wiederholt es seine selbst ausgesuchte \u00dcbung und vervollkommnet sein Tun. Das Kind bekommt Raum, um seine eigenen Erfahrungen zu machen, ebenso wie Zeit dabei zur Selbstst\u00e4ndigkeit zu gelangen. Die Erziehung zur Selbst\u00e4ndigkeit durch Selbstt\u00e4tigkeit steht daher im Vordergrund.<\/p><p>Ziel soll es sein, das Kind mit Lust und Neugier, Ausdauer und Vertrauen, Eigenverantwortung sowie sozialer Sensibilit\u00e4t( Gemeinschaftsf\u00e4higkeit) auf ein lebenslanges Lernen und verantwortungsvolles Handeln in sozialen Kontexten vorzubereiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-304432d e-flex e-con-boxed e-con e-parent\" data-id=\"304432d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-32ef518 e-con-full e-flex e-con e-child\" data-id=\"32ef518\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab1862a elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ab1862a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"127\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/kiga_team_children.svg\" class=\"attachment-large size-large wp-image-270\" alt=\"Illustration einer Gruppe spielender Kinder als grafisches Element auf der Konzeptseite des Integrativen Montessori Kindergartens Bayreuth\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5f3fe2 e-con-full e-flex e-con e-child\" data-id=\"c5f3fe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3914856 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3914856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kindergarten&shy;gruppe<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49d9434 e-con-full e-flex e-con e-child\" data-id=\"49d9434\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9f610f elementor-view-stacked elementor-widget__width-initial elementor-mobile-position-inline-start elementor-widget-mobile__width-inherit elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b9f610f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M80.31,67.88c-.88-.79-1.94-1.4-2.87-2.13-.94-.74-1.84-1.52-2.71-2.34-1.77-1.69-3.39-3.54-4.82-5.54-1.39-1.94-2.6-4-3.64-6.15-.53-1.09-1.01-2.2-1.44-3.33-.44-1.16-.75-2.38-1.25-3.52-.11-.25-.57-.25-.53.09.28,2.35,1.38,4.74,2.37,6.87,1.05,2.28,2.32,4.45,3.77,6.5,1.4,1.98,2.95,3.86,4.65,5.58.87.89,1.78,1.74,2.72,2.56.95.82,1.96,1.77,3.09,2.34.57.29,1.15-.49.66-.93Z\"><\/path><path d=\"M48.2,49.86c-.05-.06-.15-.06-.17.03-.25,1.12.3,2.58.54,3.68.28,1.31.55,2.62.82,3.93.56,2.8,1.08,5.61,1.58,8.42.5,2.83.95,5.66,1.37,8.5.41,2.82.7,5.67,1.15,8.48.11.67,1.15.69,1.09-.03-.48-5.58-1.57-11.19-2.59-16.69-.51-2.74-1.06-5.48-1.65-8.21-.31-1.42-.62-2.85-.95-4.26-.27-1.18-.41-2.88-1.19-3.84Z\"><\/path><path d=\"M79.24,68.51c-.64,1.28-1.4,2.77-2.81,3.33-1.25.49-2.66.07-3.85.82-.9.57-1.38,1.54-2.04,2.34-1.1,1.33-2.59.9-4.11,1.15-1.29.21-2.5.77-3.5,1.62-1.03.87-1.7,2.45-3.09,2.79-1.34.33-2.63,0-3.92.64-.99.49-1.95,1.32-2.24,2.42-.07.28.29.45.48.26,1.09-1.12,2.02-2.08,3.67-2.2,1.28-.1,2.51.07,3.57-.79,1.07-.86,1.67-2.09,2.86-2.84.66-.41,1.39-.71,2.16-.85.81-.15,1.63-.05,2.45-.14,1.16-.13,1.97-.72,2.66-1.63.86-1.14,1.44-2.08,2.99-2.24,1.33-.13,2.45-.21,3.52-1.11.95-.81,1.6-1.94,2.21-3.02.36-.64-.68-1.19-1.01-.53Z\"><\/path><path d=\"M70.09,60.04c-2.78,2.1-5.77,3.95-8.98,5.33-1.57.68-3.17,1.26-4.81,1.76-1.63.49-3.32.78-4.93,1.32-.2.07-.16.38.06.38,1.72-.03,3.44-.52,5.09-.99,1.7-.48,3.36-1.08,4.98-1.77,3.23-1.38,6.31-3.08,9.12-5.19.51-.38-.02-1.23-.54-.84Z\"><\/path><path d=\"M44.38,11.6c-1.27,0-2.64.65-3.76,1.22-1.24.63-2.41,1.39-3.5,2.26-2.11,1.68-3.89,3.75-5.21,6.1-2.76,4.94-3.17,10.59-1.81,16.01.13.5.93.26.77-.24-1.61-5.02-.85-10.84,1.69-15.42,1.29-2.33,3.07-4.4,5.16-6.05,1.02-.8,2.1-1.49,3.24-2.1,1.12-.6,2.39-.97,3.44-1.67.05-.03.02-.1-.03-.1Z\"><\/path><path d=\"M33.04,38.87c-1.25.19-1.87,2.13-3.38,1.64-.79-.26-1.02-1.3-.64-1.97.44-.77,1.35-.86,2.08-1.17.09-.04.14-.16.05-.23-.83-.67-2.11-.22-2.75.52-.72.83-.8,2.1-.18,3.02.6.9,1.76,1.14,2.74.81.88-.29,2.48-1.19,2.46-2.27,0-.18-.18-.39-.38-.36Z\"><\/path><path d=\"M69.89,23.09c-2.7-4.39-6.73-8.5-11.36-10.82-4.28-2.14-10.14-3.19-14.51-.69-.19.11-.04.4.16.35,2.62-.71,5.12-1.3,7.86-.96,2.29.29,4.51,1.05,6.53,2.16,2.16,1.17,4.09,2.73,5.8,4.49,1.8,1.85,3.18,3.93,4.66,6.02.38.54,1.22.02.87-.55Z\"><\/path><path d=\"M73.46,23.76c-.48-.94-1.49-1.49-2.54-1.26-.78.17-1.87.91-1.6,1.84.03.1.17.13.24.05.45-.51.76-.96,1.5-1.02.81-.06,1.44.43,1.64,1.21.49,1.88-1.41,2.94-3.01,2.91-.82-.01-.78,1.34.04,1.27,2.41-.19,5.08-2.38,3.73-5Z\"><\/path><path d=\"M42.54,12.42c-.58-.57-1.51-.74-2.15-1.29-.7-.59-1.22-1.34-1.61-2.17-.13-.28-.53-.05-.46.21.25,1.04.79,1.95,1.6,2.66.64.57,1.62,1.3,2.51,1.08.23-.06.27-.35.11-.5Z\"><\/path><path d=\"M43.64,11.28c-.34-.61-1.05-.98-1.56-1.43-.61-.55-1.21-1.21-1.59-1.94-.06-.12-.26-.03-.22.1.47,1.35,1.44,3.65,3.15,3.7.22,0,.32-.25.23-.43Z\"><\/path><path d=\"M44.67,6.2c-.46.57-.67,1.29-.77,2.01-.09.65-.25,1.47.28,1.96.13.13.38.13.5-.02.41-.49.27-1.12.29-1.72.03-.69.14-1.4.08-2.09-.01-.18-.26-.3-.39-.14Z\"><\/path><path d=\"M45.07,14.48c-.18-.22-.48-.23-.64.02-.41.67-.15,1.73-.2,2.5-.06,1.01-.21,2.02-.44,3-.46,1.91-1.19,3.81-2.09,5.55-.07.13.12.28.22.16,1.35-1.57,2.29-3.33,2.83-5.34.27-.98.44-1.97.53-2.97.08-.84.35-2.23-.22-2.92Z\"><\/path><path d=\"M46.55,16.11c-.14-.27-.64-.27-.76.03-.25.67-.12,1.38-.13,2.09-.02.78-.05,1.57-.15,2.34-.19,1.54-.55,3.06-.81,4.59-.03.15.16.22.24.09.87-1.38,1.34-2.99,1.6-4.6.12-.76.21-1.53.24-2.3.03-.75.13-1.56-.23-2.24Z\"><\/path><path d=\"M48.41,17.59c-.16-.24-.52-.23-.66.03-.51.91-.17,2.33-.16,3.35.01,1.28.04,2.56.13,3.84.01.15.21.16.25.03.38-1.21.6-2.45.68-3.72.07-1.04.37-2.63-.24-3.52Z\"><\/path><path d=\"M44.38,14.95c-.48.65-.58,1.54-.83,2.31-.31.94-.67,1.86-1.09,2.77-.81,1.76-1.8,3.43-2.95,4.98-1.1,1.47-2.34,2.82-3.68,4.08-1.46,1.37-3.09,2.49-4.65,3.74-.09.07-.03.25.09.2,3.57-1.36,6.64-4.41,8.9-7.4,1.16-1.53,2.17-3.17,3.01-4.9.43-.88.81-1.79,1.14-2.71.31-.84.85-1.92.72-2.82-.04-.29-.44-.55-.67-.25Z\"><\/path><path d=\"M68.71,21.96c-3.68.49-7.22.73-10.87-.2-1.78-.45-3.5-1.12-5.12-1.99-.78-.42-1.55-.87-2.28-1.37-.67-.46-1.34-1.23-2.15-1.39-.19-.04-.4.14-.32.34.28.74,1.07,1.18,1.7,1.62.8.56,1.64,1.08,2.51,1.52,1.7.86,3.5,1.51,5.35,1.94,3.58.83,7.72,1.06,11.2-.27.1-.04.09-.21-.03-.2Z\"><\/path><path d=\"M38.66,29.76c-.64.79-.77,1.86-.34,2.78.35.75,1.29,1.7,2.17,1.14.16-.1.22-.33.11-.49-.28-.4-.75-.58-1.03-.98-.4-.57-.32-1.28.15-1.78,1.1-1.17,2.73-.37,3.67.57.16.16.43-.02.37-.23-.67-2.25-3.62-2.82-5.11-.99Z\"><\/path><path d=\"M60.2,25.79c-.35-.85-1.12-1.55-2.03-1.71-1.8-.32-3.63,1.67-2.82,3.41.12.24.49.09.48-.15-.03-1.18,1.01-2.82,2.38-2.17.5.24.85.75.96,1.28.12.52-.19,1.03.07,1.5.1.17.31.22.49.18.93-.21.72-1.72.45-2.35Z\"><\/path><path d=\"M59.79,33.12c-.14-.29-.59-.29-.79-.07-.43.48-.4,1.16-.59,1.76-.23.71-.57,1.39-.98,2.01-.78,1.17-1.87,2.14-3.13,2.77-2.85,1.41-5.99.88-8.66-.65-.23-.13-.45.2-.27.38,2.38,2.32,6.36,2.76,9.32,1.39,1.47-.68,2.74-1.76,3.67-3.09.73-1.04,2.05-3.21,1.42-4.49Z\"><\/path><path d=\"M70.31,17.79c-1.1-1.41-4.05-.94-5.32-.03-.25.18-.08.66.24.53.82-.34,1.63-.62,2.53-.59.83.02,1.55.45,2.35.47.18,0,.32-.23.2-.38Z\"><\/path><path d=\"M72.63,15.35c-.15-.18-.41-.2-.54.02-.27.48-.21,1.01-.29,1.55-.11.68-.32,1.32-.66,1.92-.74,1.31-1.71,1.85-2.95,2.57-.12.07-.05.26.08.25,1.38-.05,2.77-1.19,3.54-2.27.67-.93,1.71-2.98.83-4.04Z\"><\/path><path d=\"M70.56,13.94c-1.31.65-2.27,2.1-2.13,3.58.03.34.58.44.63.06.16-1.21.65-2.39,1.85-2.9.58-.25,1.26-.3,1.88-.17.48.1.86.38,1.35.35.17-.01.36-.2.28-.39-.57-1.29-2.82-1.05-3.85-.53Z\"><\/path><path d=\"M77.44,12.25c-.15-.17-.45-.13-.59.02-.33.36-.28.8-.43,1.24-.19.58-.57,1.13-1.03,1.53-.44.38-.97.65-1.54.76-.47.1-.92.04-1.32.33-.06.05-.08.12-.04.19.7,1.2,2.86.1,3.62-.5.86-.67,2.3-2.52,1.34-3.59Z\"><\/path><path d=\"M75.39,9.98c-1.16.58-2.67,2.77-1.64,4,.05.06.16.04.2,0,.41-.46.48-1.11.78-1.65.32-.59.74-1,1.25-1.43.54-.44.05-1.24-.58-.92Z\"><\/path><path d=\"M30.89,25.45c-.46-.88-2.03-1.03-2.92-.96-1.19.09-2.04.62-2.72,1.58-.09.12.06.28.18.17.67-.67,1.75-1.05,2.67-1.07.49-.01.96.07,1.4.3.36.18.61.44,1,.54.33.09.53-.29.39-.55Z\"><\/path><path d=\"M30.1,28.85c-.51-.02-.99.17-1.5.18-.6,0-1.19-.11-1.74-.35-1.07-.46-1.78-1.31-2.4-2.26-.1-.15-.38-.09-.35.11.19,1.33,1.17,2.35,2.33,2.96,1.04.55,2.91,1.06,3.94.26.38-.29.22-.88-.27-.89Z\"><\/path><path d=\"M23.96,23.77c-1.42.08-2.55.72-3.3,1.92-.05.07.07.15.12.09.82-.9,2.17-1.33,3.37-1.21.56.06,1.11.23,1.59.53.42.26.68.61,1.18.65.19.02.34-.19.34-.36-.02-1.32-2.32-1.69-3.3-1.63Z\"><\/path><path d=\"M24.81,27.34c-.95.61-2.21.75-3.3.49-.48-.12-.96-.28-1.38-.53-.51-.3-.81-.76-1.27-1.12-.41-.32-1.11.02-.92.58.44,1.27,2.13,2.05,3.38,2.16,1.42.12,2.66-.35,3.65-1.37.1-.11-.04-.28-.17-.2Z\"><\/path><path d=\"M18.92,22.49c-1.2-.05-3.21.39-3.42,1.84-.03.22.15.41.38.35,1.11-.29,1.85-1.02,3.07-.97,1.05.05,2.05.55,2.92,1.1.15.1.33-.08.28-.23-.43-1.41-1.85-2.03-3.24-2.09Z\"><\/path><path d=\"M18.72,26.9c-.37,0-.74-.05-1.11-.05-.41,0-.83-.04-1.2-.23-.26-.14-.48-.36-.61-.63-.11-.23-.14-.41-.28-.56-.03-.06-.06-.12-.1-.19-.1-.14-.28-.18-.43-.09-.94.52-.27,1.85.52,2.34.47.29,1.02.4,1.57.35.68-.06,1.15-.3,1.74-.6.17-.09.06-.33-.1-.33Z\"><\/path><path d=\"M56.36,47.96c-1.14.26-2.2.77-3.35,1.02-1.19.27-2.45.41-3.68.44-2.37.05-4.78-.34-6.98-1.22-2.04-.81-3.92-2-5.53-3.48-.8-.74-1.54-1.55-2.18-2.42-.34-.46-.66-.94-.96-1.43-.28-.46-.47-.96-.89-1.31-.36-.3-.98-.08-.96.44.05,1.08,1,2.21,1.63,3.05.72.97,1.53,1.88,2.42,2.7,1.74,1.6,3.79,2.86,6.01,3.68,2.38.87,4.94,1.22,7.47,1.01,1.27-.11,2.49-.34,3.71-.71,1.16-.35,2.45-.74,3.4-1.52.11-.09.04-.27-.11-.24Z\"><\/path><path d=\"M69.36,28.56c-.1.45-.01.87-.01,1.33,0,.54-.03,1.08-.08,1.62-.09,1.08-.27,2.15-.53,3.21-.49,2.01-1.27,3.94-2.35,5.7-1.14,1.84-2.67,3.53-4.43,4.78-.87.62-1.82,1.15-2.8,1.56-1.02.43-2.11.62-3.13,1.02-.2.08-.16.36.06.38,2.11.12,4.45-1.11,6.16-2.23,1.89-1.24,3.51-2.8,4.79-4.67,1.24-1.82,2.13-3.87,2.69-6,.3-1.14.51-2.31.64-3.48.11-1,.38-2.28.12-3.25-.15-.57-1-.51-1.13.04Z\"><\/path><path d=\"M58.45,47.8c-.35-.6-1.27-.02-.91.58.71,1.16.11,2.88-1.27,3.2-1.49.35-2.4-.95-2.69-2.21-.07-.28-.51-.26-.57.02-.34,1.86,1.88,3.48,3.6,3.1,2.04-.45,2.85-2.99,1.84-4.69Z\"><\/path><path d=\"M76.83,8.39c-.68.14-2.07,1.28-1.06,1.93.03.02.08.03.12.03.22.96.48,2.1,1.59,2.15,1.18.06,1.67-1.44,1.52-2.39-.17-1.07-1.03-1.96-2.17-1.72ZM78.28,10.28c.15.76-.5,2.25-1.36,1.33-.4-.43-.47-1.04-.64-1.6.17-.21.32-.44.59-.57.66-.31,1.28.16,1.41.83Z\"><\/path><path d=\"M76.13,8.65c-.77-.54-1.61-.95-2.43-1.4-.37-.2-.74-.42-1.1-.65-.4-.25-.67-.53-1.16-.47-.31.03-.51.29-.43.6.21.83,1.53,1.31,2.23,1.68.87.45,1.78.78,2.76.88.38.04.38-.47.15-.64Z\"><\/path><path d=\"M75.45,2.56c-.14-.16-.37-.06-.46.08-.51.76-.08,2.01.08,2.86.21,1.1.51,2.21,1.07,3.19.16.28.7.15.64-.2-.17-1.06-.48-2.08-.68-3.13-.17-.88-.03-2.1-.65-2.8Z\"><\/path><path d=\"M75.68,2.33c-.87.27-1.55,1.18-2.2,1.79-.82.76-1.71,1.5-2.4,2.38-.18.23.07.59.35.41.87-.57,1.63-1.3,2.4-2,.7-.62,1.82-1.32,2.18-2.2.09-.21-.08-.47-.33-.4Z\"><\/path><path d=\"M78.56,11.08c-.05-.3-.47-.31-.48.01-.05,1.22.14,2.41.44,3.58.25.97.52,2.37,1.27,3.07.15.14.41.02.4-.18-.05-.97-.69-1.98-.95-2.93-.32-1.16-.49-2.36-.68-3.55Z\"><\/path><path d=\"M81.12,12.83c-.77-.55-1.57-1.05-2.4-1.51-.26-.15-.5.21-.3.42.71.72,1.46,1.41,2.25,2.05.6.48,1.22,1.21,2.02,1.24.23,0,.39-.24.32-.45-.24-.79-1.26-1.28-1.91-1.74Z\"><\/path><path d=\"M83.32,13.63c-.85.14-1.44.73-2.06,1.3-.73.67-1.34,1.37-1.77,2.27-.09.19.12.39.3.28.74-.46,1.36-1.02,2.02-1.58.64-.55,1.43-1.02,1.8-1.8.09-.19-.04-.51-.29-.47Z\"><\/path><path d=\"M84.57,0c-.9-.02-1.77,1.03-2.34,1.6-1.49,1.49-3.18,3.6-3.56,5.74-.05.29.34.56.55.29.94-1.2,1.63-2.57,2.62-3.75.48-.57,1-1.11,1.55-1.62.31-.29.64-.66,1.01-.87.11-.08.24-.13.38-.16.03,0,.05,0,.07-.01.17.11.44.07.53-.13.25-.56-.21-1.08-.8-1.09Z\"><\/path><path d=\"M86.44,3.39c-1.02-.6-2.8.63-3.64,1.22-1.05.74-2.22,1.78-2.5,3.08-.03.13.11.22.22.16,1.11-.61,2-1.59,3.09-2.26.57-.35,1.17-.65,1.8-.89.5-.19.92-.3,1.19-.8.1-.19.02-.41-.16-.52Z\"><\/path><path d=\"M86.97,7.06c-.9-.35-1.78-.02-2.64.33-.91.37-1.85.85-2.46,1.64-.21.27,0,.76.39.62.83-.31,1.59-.79,2.42-1.1.77-.29,1.65-.33,2.31-.85.2-.15.26-.53-.03-.64Z\"><\/path><path d=\"M15.38,23.8c-.69-1.26-2.46-1.01-3.18.07-.75,1.13-.51,2.84.93,3.22.59.16,1.2.04,1.65-.39.36-.35.68-.95.47-1.44.26-.44.34-1.06.12-1.46ZM13.64,26.5c-.91-.03-1.2-1.07-.95-1.8.23-.68.88-1.2,1.61-.94,1.08.39.47,1.43-.27,1.76-.06.02-.07.09-.01.13.2.13.38.17.56.15-.16.39-.36.72-.93.7Z\"><\/path><path d=\"M14.72,18.04c-.19.03-.31.22-.37.39-.32.99-.52,2-.59,3.04-.04.65-.2,1.69.41,2.11.04.03.1,0,.13-.02.39-.33.33-.86.39-1.34.09-.79.18-1.56.36-2.34.13-.54.78-2.04-.33-1.84Z\"><\/path><path d=\"M18.59,20.15c-.77.33-1.37,1.07-1.95,1.67-.73.75-1.39,1.55-2.05,2.36-.06.08.03.2.12.14.76-.57,1.5-1.14,2.21-1.77.67-.6,1.56-1.25,1.95-2.06.08-.16-.08-.42-.27-.33Z\"><\/path><path d=\"M17.58,18.59c-.8-.63-1.76-.97-2.78-.81-.28.04-.39.47-.06.54.82.16,1.64.47,2.28,1.03.53.47.76,1.36,1.35,1.69.14.08.37.02.43-.13.35-.85-.61-1.84-1.22-2.32Z\"><\/path><path d=\"M12.39,26.36c-.92.79-1.46,1.83-1.96,2.92-.37.81-1.12,2.01-.85,2.91.04.15.24.23.37.14.79-.58.96-1.9,1.35-2.77.46-1.03.99-2,1.25-3.1.02-.1-.1-.15-.16-.09Z\"><\/path><path d=\"M14.05,29.67c-.28-.98-.48-1.99-.64-3-.02-.12-.21-.17-.23-.02-.14.98-.13,1.95.05,2.93.17.88.37,2.15,1.1,2.74.19.15.46.03.47-.21.02-.8-.52-1.66-.74-2.43Z\"><\/path><path d=\"M14.8,31.7c-.77-.18-1.6.15-2.37.23-.87.09-1.75.11-2.63.1-.25,0-.26.34-.04.41.93.29,1.89.42,2.86.39.8-.03,1.72-.05,2.34-.59.19-.17.05-.48-.16-.53Z\"><\/path><path d=\"M10.95,23.47c-.82-.9-1.77-1.63-2.73-2.37-.86-.66-1.79-1.57-2.8-1.97-.61-.24-1.09.43-.65.92.72.82,1.87,1.39,2.79,1.99,1.01.66,2.01,1.32,3.13,1.8.25.11.45-.18.27-.38Z\"><\/path><path d=\"M9.88,24.02c-.89-.48-1.84-.69-2.82-.89-.69-.14-1.75-.6-2.28.03-.07.09-.11.21-.07.32.29.79,1.36.71,2.08.82,1.01.15,1.98.28,3,.13.21-.03.31-.31.1-.42Z\"><\/path><path d=\"M10.03,25.69c-.89-.2-1.79-.17-2.7-.21-.88-.04-1.88-.29-2.7.09-.21.1-.32.36-.12.54.72.64,1.78.59,2.69.59,1.01,0,2-.1,2.91-.55.2-.1.12-.41-.08-.46Z\"><\/path><path d=\"M82.85,34.66c-.72.5-1.21,1.29-1.8,1.92-.68.72-1.39,1.4-2.14,2.06-1.5,1.32-3.1,2.5-4.83,3.51-3.28,1.92-6.75,3.09-10.42,3.93l.2.64c3.68-.58,7.29-2.01,10.51-3.82,1.76-1,3.48-2.13,5.05-3.41.76-.62,1.5-1.27,2.21-1.95.68-.66,1.55-1.33,1.97-2.2.21-.44-.29-.99-.74-.68Z\"><\/path><path d=\"M87.37,36.2c-.8.62-1.41,1.44-2.14,2.14-.86.83-1.76,1.63-2.69,2.38-1.72,1.39-3.55,2.64-5.45,3.75-1.92,1.12-3.93,2.09-6,2.91-2.1.83-4.36,1.28-6.42,2.17-.19.08-.17.39.06.39,2.24-.06,4.54-.96,6.61-1.74,2.1-.8,4.13-1.77,6.08-2.89,2.01-1.15,3.93-2.46,5.73-3.91.87-.7,1.72-1.43,2.54-2.19.81-.75,1.72-1.47,2.32-2.41.24-.37-.29-.86-.64-.59Z\"><\/path><path d=\"M84.62,33.44c-1.16-1.56-2.79-2.77-4.52-3.64-.28-.14-.59.12-.51.42.56,2.07,2.02,4.35,4.21,4.93.1.03.17-.11.09-.17-1.41-1.25-2.65-2.4-3.33-4.1,1.33.82,2.43,1.84,3.5,3.02.27.3.8-.13.55-.46Z\"><\/path><path d=\"M91.21,25.23c-1.55,1-2.95,2.21-4.13,3.64-1.03,1.24-2.34,2.95-2.62,4.57-.04.23.28.47.45.24.44-.61.71-1.33,1.09-1.98.48-.82,1.03-1.59,1.64-2.32.86-1.03,1.83-1.95,2.9-2.75-.31.64-.67,1.26-1.09,1.84-.63.88-1.42,1.59-2.15,2.38-.27.29.11.78.46.55,1.92-1.3,3.25-3.63,4.04-5.76.12-.33-.32-.59-.59-.42Z\"><\/path><path d=\"M93.79,27.72c-1.14.38-2.24.84-3.3,1.39-1,.52-2.2,1.12-2.87,2.05-.1.14,0,.38.2.31.99-.34,1.86-1.05,2.79-1.54.74-.39,1.5-.73,2.29-1.02-.45.57-.97,1.07-1.58,1.49-.65.44-1.72.58-2.12,1.27-.06.1-.01.24.09.29.84.42,2.08-.51,2.74-1,.95-.71,1.7-1.6,2.27-2.64.17-.31-.15-.7-.49-.59Z\"><\/path><path d=\"M95.16,30.99c-1.9.13-4.01.33-5.76,1.15-.23.11-.09.49.14.46,1.68-.15,3.32-.54,4.99-.72-.74,1.32-2.54,1.37-3.93,1.51-.55.06-.54.87.02.87,1.97-.03,4.38-.59,4.95-2.75.07-.26-.15-.53-.42-.52Z\"><\/path><path d=\"M90.9,34.21s-.08.04-.05.08c.26.35,2.02,1.9,1.86,2.22-.15.29-.86-.27-.96-.38-.17-.17-.32-.33-.52-.46-.25-.17-.54-.28-.84-.34-1.37-.27-3.61.57-3.84,2.09-.04.23.14.38.36.34,1.26-.24,1.74-1.8,3.15-1.8,1.1,0,1.56,1.51,2.66,1.27,1.86-.41-1.05-2.82-1.83-3.02Z\"><\/path><path d=\"M49,53.82c-.91,0-1.89.66-2.66,1.1-.98.56-1.91,1.21-2.78,1.93-1.41,1.17-2.75,2.62-2.94,4.52-.17,1.66.46,3.38,1.75,4.46,1.02.86,2.95,1.59,4.22.86.07-.04.05-.16-.03-.17-.72-.18-1.45-.14-2.16-.43-.59-.24-1.19-.62-1.64-1.07-1.12-1.12-1.49-2.86-.99-4.36.55-1.64,2.08-2.87,3.44-3.83.63-.45,1.29-.87,1.97-1.24.7-.38,1.54-.6,2.12-1.16.24-.24.02-.63-.29-.63Z\"><\/path><path d=\"M46.66,66.08c-.48.39-.65.9-1.3,1.13-.76.27-1.6.12-2.38,0-.3-.05-.42.41-.11.47.94.19,1.95.39,2.88.03.57-.22,1.37-.74,1.28-1.43-.02-.16-.21-.33-.37-.2Z\"><\/path><path d=\"M48.22,51.55c-4.91,1.32-8.91,5.13-10.27,10.06-.65,2.35-.75,4.86-.52,7.28.22,2.37.67,4.82,1.67,6.98.04.09.16.01.15-.07-.43-2.31-1.09-4.56-1.28-6.92-.18-2.25-.05-4.52.58-6.7,1.38-4.79,5.08-8.53,9.95-9.73.59-.14.31-1.05-.27-.9Z\"><\/path><path d=\"M39.26,69.25c-.12-.13-.33-.06-.41.07-.49.84-.04,2.21.02,3.14.07,1.12-.02,2.33.29,3.42.06.2.33.17.39-.01.35-1.14.21-2.43.18-3.61-.03-.94.18-2.26-.47-3.01Z\"><\/path><path d=\"M40.75,68.88c-.14-.29-.62-.06-.52.24.64,1.92,1.17,3.76,1.35,5.76-1.22-1.51-1.85-3.23-2.28-5.17-.05-.21-.35-.14-.36.06-.01,2.32,1.2,4.57,2.79,6.21.19.19.53.02.52-.24-.08-2.31-.49-4.77-1.51-6.86Z\"><\/path><path d=\"M42,67.91c-.25-.41-.89,0-.63.4,1.08,1.68,1.91,3.44,2.51,5.32-1.56-1.11-2.47-2.83-2.81-4.74-.03-.19-.31-.12-.32.05-.07,2.41,1.44,4.54,3.52,5.67.25.13.52-.11.45-.37-.6-2.23-1.52-4.37-2.73-6.34Z\"><\/path><path d=\"M44.61,69c-.48-.79-1.12-1.88-2.02-2.23-.37-.14-.68.19-.5.54.39.81,1.28,1.42,1.84,2.13.43.55.78,1.15,1.07,1.78-1.35-.87-2.23-2.1-3.07-3.54-.09-.16-.32-.03-.28.13.41,2,2.13,3.61,3.9,4.49.25.13.59-.11.49-.4-.36-1.02-.85-1.97-1.41-2.9Z\"><\/path><path d=\"M61.66,80.3c-.16-.18-.48-.09-.58.1-.28.54-.11.99-.02,1.57.11.74.18,1.49.23,2.24.1,1.44.12,2.88-.18,4.29-.25,1.18-.7,2.32-1.37,3.34-.76,1.14-1.76,1.81-2.84,2.6-.2.15-.06.45.18.39,2.4-.58,3.99-3.44,4.61-5.62.41-1.46.55-3.02.54-4.53,0-.83-.07-1.65-.14-2.48-.05-.71.04-1.35-.44-1.9Z\"><\/path><path d=\"M59.16,95.04c-.37-.12-.74.21-1.11-.04-.3-.2-.33-.74-.16-1.03.06-.1-.08-.25-.18-.17-.25.21-.42.36-.47.71-.05.37.05.76.31,1.04.26.28.64.44,1.02.41.36-.03.84-.23.81-.66,0-.13-.09-.23-.22-.27Z\"><\/path><path d=\"M64.41,77.75c-.38-.64-1.35-.02-.97.62,1.8,3.03,1.13,6.62.18,9.82-.42,1.39-.88,2.77-1.64,4.02-.79,1.3-1.85,2.04-3.07,2.9-.16.12-.1.4.12.39,3.06-.18,4.66-4.35,5.44-6.78,1.12-3.5,1.92-7.62-.07-10.97Z\"><\/path><path d=\"M61.62,96.59c-.45-.16-.91-.22-1.38-.31-.64-.12-1.14-.35-1.72-.63-.3-.14-.76.14-.6.5.39.89,1.33,1.06,2.22,1.14.66.06,1.62.07,1.98.75.47.89-.65,1.13-1.3,1.07-1.3-.11-2.58-.94-3.45-1.88-.44-.48-.83-1.05-1.06-1.65-.11-.29-.25-.7-.15-1.01.21-.7.79-.57,1.14-.17.12.14.35.04.38-.12.16-.63-.49-1.04-1.07-1.02-.8.02-1.29.71-1.32,1.46-.1,2.05,1.99,4.02,3.7,4.79,1.23.55,3.98,1.05,4.2-.97.11-.98-.74-1.66-1.57-1.96Z\"><\/path><path d=\"M86.15,88.38c-2.99-1.25-5.5-2.97-7.85-5.21-1.2-1.15-2.4-2.31-3.49-3.56-1.37-1.57-2.24-3.17-2.74-5.19-.07-.3-.55-.22-.53.09.17,3.62,3.72,6.59,6.15,8.9,2.32,2.21,5.11,4.7,8.42,5.07.05,0,.09-.07.04-.09Z\"><\/path><path d=\"M86.21,86.46c-.45-.61-1.23-.98-1.84-1.39-.91-.61-1.78-1.26-2.62-1.97-1.57-1.32-3-2.83-4.18-4.51-1.2-1.72-1.98-3.66-2.65-5.63-.19-.57-1.06-.31-.9.28.81,2.97,2.67,5.69,4.71,7.95,1.09,1.21,2.31,2.32,3.61,3.31.59.45,1.2.88,1.83,1.28.62.4,2.91,1.74,1.1,2.45-.15.06-.21.3-.04.38.46.21.87.02,1.13-.41.35-.56.23-1.22-.15-1.73Z\"><\/path><path d=\"M88.88,81.59c-.81.2-1.2.98-1.45,1.71-.22.63-.34,1.29-.55,1.93-.21.67-.47,1.29-.57,1.99-.09.6.76.81.92.22.33-1.23.41-2.49.75-3.72.09-.32.17-.69.35-.98.43-.7,1.22-.91,1.54.22.13.48,0,1.23-.07,1.69-.18,1.09-.61,2.12-1.27,3.01-.4.55-.92,1.15-1.59,1.36-.93.29-1.48-.36-1.56-1.2-.01-.12-.17-.2-.25-.1-.36.45-.16,1.01.21,1.39.51.52,1.23.6,1.89.35,1.72-.64,2.77-2.88,3.1-4.55.22-1.11.45-3.79-1.45-3.33Z\"><\/path><path d=\"M53.08,55.51c-.49.16-.87.58-1.04,1.06-.16.46-.03,1.05.48,1.21,0,0,0,0,0,0,.2.25.48.44.77.53.88.24,1.56-.53,1.53-1.37-.03-.9-.8-1.74-1.75-1.43ZM54.26,56.92c.06.5-.29,1.04-.85.89-.23-.07-.42-.22-.55-.42.03-.12.08-.25.13-.36.07-.19.17-.35.34-.48.41-.32.87-.15.93.38Z\"><\/path><path d=\"M61.28,51.3c-.88.19-1.91,1.43-1.03,2.21.08.07.18.07.25.03.15.32.43.59.77.73.9.37,1.68-.41,1.73-1.28.06-.99-.67-1.92-1.72-1.69ZM62.33,52.88c.05.5-.31,1.02-.86.89-.32-.07-.6-.33-.74-.63.14-.32.36-.65.67-.8.44-.22.88.06.93.54Z\"><\/path><path d=\"M57.78,58.24c-.94.17-1.91,1.46-1.09,2.29.15.15.4.05.45-.13.14.25.37.47.63.6.81.4,1.59-.27,1.63-1.1.05-.92-.62-1.83-1.61-1.66ZM58.9,59.78c.04.53-.36,1.07-.93.84-.33-.13-.59-.47-.64-.82.11-.26.28-.49.56-.63.49-.25.97.09,1.01.61Z\"><\/path><path d=\"M65.67,58.58c-.53-.07-1.14.19-1.25.75-.01.07.08.13.13.07.21-.28.58-.49.95-.42.37.07.59.45.47.8-.11.33-.41.42-.71.29-.13-.06-.24-.15-.36-.23-.04-.03-.08-.06-.13-.09.04.03.05.03.02-.02-.06-.07-.12-.15-.18-.21-.09-.09-.29-.09-.36.02-.5.7.27,1.54,1,1.6.75.06,1.32-.51,1.37-1.24.05-.61-.29-1.22-.94-1.31Z\"><\/path><path d=\"M56.66,63.42c-.42-.29-.95-.32-1.41-.13-.14.06-.28.15-.4.26-.04,0-.08,0-.12.03-.09.05-.17.14-.23.21-.15.17-.24.36-.29.58-.1.45-.03.96.24,1.34.55.79,1.72.79,2.41.18.77-.67.64-1.93-.19-2.49ZM56.23,65.39c-.39.28-1.01.25-1.24-.23-.09-.19-.1-.39-.06-.59.34-.27.76-.76,1.25-.46.48.29.49.98.05,1.29Z\"><\/path><path d=\"M46.48,38c-.5.14-.81.53-1.23.82-.39.27-.82.45-1.25.64,0-.03,0-.05,0-.08,0-.03-.04-.05-.05-.03-.11.09-.21.18-.32.27-.2.1-.07.39.12.4,1.01.04,2.82-.6,3.01-1.74.03-.17-.12-.33-.3-.28Z\"><\/path><path d=\"M61.34,32.71c-.35-.29-.79-.07-1.2-.04-.49.04-.96-.03-1.44-.04-.21,0-.35.32-.17.45.45.33,1.01.45,1.56.46.47,0,1.19-.01,1.34-.55.03-.1-.01-.22-.09-.29Z\"><\/path><path d=\"M54.31,31.48c-2.55,1.19-5.04-.82-5.06-3.47,0-.11-.17-.13-.19-.02-.44,2.94,2.5,5.01,5.14,4.08-.02.64-.28,1.22-.73,1.69-.41.43-.97.59-1.4.98-.18.16-.07.52.17.55,1.77.21,2.63-2.21,2.47-3.61-.02-.21-.21-.29-.39-.21Z\"><\/path><path d=\"M59.46,35.95c-.11.02-.23.12-.18.25.23.54.76.84,1.04,1.37.4.77.46,1.7.05,2.48-.43.82-1.31,1.21-2.2,1.22-.99,0-1.64-.47-2.35-1.09-.05-.05-.16,0-.13.08.76,1.92,3.79,1.77,4.95.38.63-.76.77-1.82.57-2.76-.16-.77-.79-2.07-1.75-1.92Z\"><\/path><path d=\"M59.01,39.21c-.19.04-.33-.07-.49-.19-.19-.13-.33-.38-.55-.47-.18-.07-.48-.02-.5.23-.05.44.32.76.72.86.15.04.34.07.5.03.02,0,.07-.02.07-.03.04,0,.08-.01.12-.02.08-.03.16-.06.24-.08.22-.07.11-.38-.1-.33Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAlter der Kinder\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tca. 3 Jahre bis Schuleintritt\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3317b98 elementor-view-stacked elementor-widget__width-initial elementor-mobile-position-inline-start elementor-widget-mobile__width-inherit elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3317b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M30.61,16.95c-1.95.68-3.84,1.58-5.74,2.4.26-.93,1.52-1.49,2.33-1.85.97-.43,1.98-.74,3.01-.95.09-.02.07-.16-.02-.16-1.4-.02-2.72.27-3.96.91-.99.51-2.14,1.28-2.02,2.54.02.17.19.38.39.3,2.07-.87,4.22-1.66,6.23-2.66.29-.14.09-.63-.22-.52Z\"><\/path><path d=\"M30.08,16.24c-1.15-2.56-3.09-4.69-5.1-6.6-.25-.24-.5-.48-.7-.76-.15-.17-.26-.37-.33-.59.23-.29.45-.25.65.11.57.51,1.08,1.12,1.6,1.68,1.13,1.22,2.22,2.47,3.29,3.74.21.25.57-.11.36-.36-1.1-1.31-2.25-2.59-3.43-3.83-.63-.67-1.73-2.4-2.83-2-.09.03-.18.12-.17.22.11,1.59,1.82,2.59,2.81,3.66,1.4,1.5,2.5,3.17,3.64,4.86.09.13.27.02.2-.12Z\"><\/path><path d=\"M30.32,10.13c-.27-.89-.56-1.78-.87-2.65-.19-.55-.79-3.34-1.87-2.65-.4.26-.33.79-.29,1.2.09.87.24,1.74.43,2.59.41,1.79,1.07,3.49,2.04,5.06.05.08.19.03.15-.06-.49-1.23-.93-2.48-1.3-3.75-.2-.66-.36-1.34-.49-2.02-.06-.31-.12-.63-.16-.94-.04-.26-.25-.97-.14-1.19.31-.64.5.31.58.53.12.31.23.62.34.92.22.62.44,1.24.64,1.87.4,1.22.58,2.7,1.2,3.81.1.17.37.09.37-.1,0-.86-.38-1.79-.63-2.61Z\"><\/path><path d=\"M31.7,5.3c-.11-.07-.32-.03-.37.1-.45,1.02-.53,2.07-.55,3.17-.03,1.22-.25,2.74.16,3.9.01.04.06.04.08,0,.38-.98.26-2.21.29-3.24.02-1.09,0-2.2.38-3.24.68.75.38,2.27.34,3.17-.05,1.25-.14,2.51-.14,3.77,0,.35.51.34.54,0,.13-1.7.18-3.43.21-5.14.02-.94-.06-1.94-.93-2.49Z\"><\/path><path d=\"M40.41,37.55c.14-.08.28-.15.43-.22-.13-2.27-.72-4.59-1.26-6.79-.59-2.38-1.31-4.73-2.17-7.03-1.66-4.45-4.52-9.34-3.14-14.23.04-.15-.14-.32-.28-.22-1.25.95-2,2.49-1.67,4.06.03.14.26.11.25-.03-.05-1.27.3-2.45,1.18-3.33-1.05,4.57,1.24,8.94,2.86,13.12.9,2.34,1.67,4.73,2.29,7.16.64,2.48.94,5.01,1.5,7.5Z\"><\/path><path d=\"M39.16,38.25c-.66-3.77-1.95-7.5-3.32-11.06-.66-1.7-1.38-3.38-2.16-5.02-.8-1.68-1.58-3.58-2.77-5.03-.05-.06-.15,0-.12.07.6,1.69,1.62,3.26,2.39,4.88.85,1.8,1.64,3.64,2.34,5.51,1.35,3.57,2.25,7.23,3.2,10.92.15-.09.29-.18.44-.27Z\"><\/path><path d=\"M44.67,92.92c-.23-.07-.31.23-.15.36.72.54,1.53.94,2.24,1.49.39.3.77.63,1.12.97.1.1.38.3.43.43.18.56-.29.36-.58.22-1.54-.74-2.62-2.16-3.83-3.33-.05-.05-.15.01-.1.08.71,1.12,1.54,2.14,2.6,2.96.49.38,1.63,1.31,2.32.92,1.52-.87-3.37-3.88-4.05-4.1Z\"><\/path><path d=\"M45.21,75.1c.21,2.66.35,5.3.26,7.99-.05,1.65-.15,3.3-.31,4.95-.07.79-.16,1.59-.26,2.38-.1.79-.28,1.59-.16,2.38,0,.04.06.04.08,0,.63-1.27.62-3.02.77-4.43.18-1.7.3-3.41.36-5.12.1-2.77.11-5.61-.09-8.4-.21.08-.42.16-.64.24Z\"><\/path><path d=\"M43.83,82.72c-.04-1.68-.09-3.36-.15-5.04-.02-.71-.03-1.44-.05-2.17-.23.03-.45.04-.66.02.05.84.11,1.68.14,2.5.06,1.62.1,3.24.14,4.86.04,1.62.08,3.24.1,4.86.02,1.6-.07,3.31.19,4.89.01.09.17.09.18,0,.27-1.57.17-3.3.16-4.89,0-1.68-.02-3.36-.06-5.04Z\"><\/path><path d=\"M43.88,92.5c-1.15-.74-2.66-.99-3.99-1.22-1.39-.23-2.79-.34-4.2-.31-.12,0-.24.08-.27.2-.23,1.04,1.17,1.1,1.85,1.2.81.12,1.62.25,2.43.36.76.11,1.58.33,2.34.23.17-.02.32-.3.1-.39-.83-.35-1.82-.36-2.72-.48-.35-.05-2.72-.21-3.33-.57,1.33,0,2.66.1,3.97.33,1.26.22,2.48.7,3.75.85.12.02.15-.16.06-.22Z\"><\/path><path d=\"M41.9,92.97c-2.85-.83-6.29-.7-8.98.57-.22.1-.16.47.07.52,1.29.29,2.61.46,3.92.51,1.19.04,2.53.06,3.63-.43.2-.09.08-.37-.1-.38-1.16-.09-2.36.17-3.53.18-.97,0-1.92-.08-2.86-.25,2.55-.89,5.12-.45,7.82-.53.11,0,.13-.16.03-.2Z\"><\/path><path d=\"M44.06,93.13c-2.72,1.92-5.87,3.15-9.18,3.48.46-.75,1.47-1.1,2.26-1.35,1.04-.33,2.12-.5,3.15-.83.12-.04.09-.2-.03-.21-1.4-.17-2.88.22-4.17.75-.91.37-1.66.9-1.94,1.89-.05.16.09.37.27.35,3.59-.3,6.99-1.46,9.96-3.52.35-.24.01-.81-.33-.57Z\"><\/path><path d=\"M34.37,59.31c-.11-2.42-1.88-4.79-4.23-5.44-.52-.14-.73.64-.22.8,2.12.69,3.79,2.44,3.86,4.76.03,1.03-.28,2.07-.83,2.94-.6.94-1.46,1.43-2.24,2.18-.05.05-.02.17.07.16,2.29-.24,3.68-3.39,3.59-5.41Z\"><\/path><path d=\"M31.36,59.55c-.07-1.87-.4-3.72-.95-5.5-.1-.34-.64-.2-.54.15.54,1.74.86,3.53.95,5.36.04.87.02,1.73-.03,2.6-.05.85-.27,1.73-.21,2.57,0,.08.12.13.16.04.35-.68.41-1.54.5-2.29.12-.97.14-1.95.11-2.92Z\"><\/path><path d=\"M30.61,52.97c-.03-.14-.17-.18-.29-.17-.37.05-.54.52-.67.82-.16.37-.26.77-.24,1.17.02.32.42.35.53.07.13-.35.23-.7.39-1.04.14-.28.36-.54.28-.86Z\"><\/path><path d=\"M31.63,65.71c-.1-.36-.41-.65-.64-.94-.24-.3-.44-.61-.77-.83-.04-.03-.1.01-.1.06-.02.42.18.78.4,1.13.21.32.48.7.87.82.14.04.28-.1.24-.24Z\"><\/path><path d=\"M23.8,51.51c-.37-.71-1.48-.6-2.1-.35-.73.29-1.32.92-1.43,1.72-.11.83.32,1.69.99,2.18.5.36,1.61.71,2,.01.02-.04,0-.08-.04-.09-.52-.16-1.01-.03-1.49-.36-.54-.36-.9-1.05-.77-1.7.12-.59.61-1.02,1.18-1.17.53-.15.96.1,1.48.09.17,0,.27-.18.19-.33Z\"><\/path><path d=\"M23.27,67.36c-.56.24-1,.69-1.67.48-.68-.21-1.03-1.07-.74-1.71.27-.59.97-.84,1.56-.98.07-.02.85-.08.76-.32-.23-.61-1.64-.18-2.04.03-.78.42-1.25,1.25-1.09,2.14.15.85.8,1.54,1.67,1.64.73.09,1.79-.25,1.86-1.1.01-.17-.18-.23-.31-.18Z\"><\/path><path d=\"M32.15,43.62c-2.35-1.39-5.03-2.11-7.76-2.12-3.04-.01-6.34.63-9.01,2.1-.08.04-.02.16.06.14,2.9-.54,5.65-1.52,8.63-1.56,2.67-.04,5.31.62,7.62,1.97,2.23,1.3,4.08,3.18,5.33,5.44,1.33,2.42,1.76,4.96,1.77,7.68,0,.48.7.47.73,0,.44-5.43-2.76-10.91-7.37-13.64Z\"><\/path><path d=\"M39.43,56.5c-.09-.39-.59-.25-.63.09-.19,1.51-.1,3.01-.41,4.52-.29,1.4-.75,2.76-1.36,4.05-1.22,2.56-3.04,4.91-5.32,6.62-2.28,1.7-4.98,2.81-7.78,3.26-3.08.5-5.9-.02-8.91-.62-.14-.03-.24.17-.1.24,2.05,1.06,4.61,1.3,6.88,1.21,2.37-.1,4.71-.64,6.88-1.6,4.36-1.92,7.74-5.55,9.51-9.95.51-1.27.88-2.59,1.11-3.94.21-1.24.42-2.62.14-3.86Z\"><\/path><path d=\"M24.94,38.48c-.65-.65-1.59-.8-2.38-.3-.91.57-1.21,1.65-1.22,2.67,0,.48.18,1.88.97,1.37.07-.05.07-.17-.02-.19-.6-.14-.38-1.61-.28-2.02.16-.65.56-1.33,1.26-1.51,1.78-.46,1.88,1.96,1.74,3.06-.04.33.51.4.57.08.22-1.07.19-2.32-.63-3.15Z\"><\/path><path d=\"M28.06,74.25c.11.4.21.78.14,1.25-.1.73-.51,1.35-1.16,1.7-1.47.77-2.69-.4-2.73-1.86,0-.12-.2-.2-.25-.07-.72,1.66,1.26,3.06,2.77,2.62,1.54-.45,2.58-2.54,1.83-4-.19.13-.39.26-.59.37Z\"><\/path><path d=\"M14.86,74.36c-.24-2.16-1.64-4.11-2.91-5.79-1.62-2.14-3.23-4.28-4.87-6.41-.3-.39-.84.02-.53.41,1.22,1.57,2.48,3.11,3.7,4.68,1.13,1.45,2.32,2.9,3.18,4.54.41.79.84,1.73.9,2.63.1,1.6-1.4,1.47-2.49,1.14-1.8-.53-3.37-1.67-4.49-3.17-.18-.24-.59-.02-.41.24,1.46,2.26,4.24,3.98,4.49,6.84-3.59-.1-6.16-3.78-7.78-6.58-1.83-3.18-2.96-6.85-3.38-10.49,0-.08-.12-.08-.12,0,.14,4,1.33,7.8,3.41,11.23,1.74,2.87,4.4,6.38,8.12,6.32.12,0,.24-.1.23-.23-.06-1.9-1.14-3.28-2.33-4.62.66.41,1.37.74,2.13.97,1.49.46,3.39.29,3.17-1.72Z\"><\/path><path d=\"M19.11,59.66c-.29-1.15-.95-2.26-1.53-3.28-.62-1.1-1.33-2.15-2.1-3.15-1.64-2.13-3.59-4.05-5.8-5.59-.37-.26-.72.34-.35.61,3.55,2.56,6.43,5.79,8.39,9.71.32.65,1.39,2.39.74,3.1-1.08,1.18-2.67-.8-3.32-1.53-1.72-1.93-3.44-3.86-5.15-5.79-.27-.3-.69.14-.44.44,1.2,1.45,2.38,2.91,3.52,4.41.54.71,1.08,1.43,1.61,2.16.53.72,1.23,1.48,1.62,2.29.11.14.15.31.15.49.19.35.07.51-.35.47-.48.12-.45.1-.79-.14-.39-.28-.76-.57-1.13-.87-.62-.51-1.21-1.05-1.78-1.62-1.22-1.23-2.3-2.59-3.24-4.05-.21-.33-.72-.04-.53.31,1.46,2.69,3.78,4.83,5.07,7.62.35.74.61,1.53.75,2.34.05.31.12.77.1,1.11-.07.77-.73.98-1.36.75-1.43-.52-2.56-1.59-3.35-2.86-.04-.06-.15-.02-.12.05.55,1.44,1.68,2.57,3.1,3.17.52.22,1.31.55,1.83.15.52-.39.45-1.3.41-1.86-.12-2.01-1.01-3.73-2.11-5.36.74.68,1.55,1.42,2.42,1.91.51.29,1.15.36,1.54-.15.45-.59.2-1.32-.15-1.89-.33-.54-.7-1.06-1.08-1.57.15.13.3.25.46.37.66.5,1.69.92,2.46.39.7-.48.7-1.38.51-2.12Z\"><\/path><path d=\"M14.07,43.24s-.09-.03-.13-.05c1.25-.52,2.24-1.25,1.55-2.57-.53-1.01-2.07-.76-2.99-.71-1.3.08-2.61.29-3.81.81-2.48,1.07-4.21,3.4-5.52,5.68-1.39,2.42-2.34,5.08-2.82,7.82-.27,1.55-.39,3.12-.35,4.7.04,1.42.09,3.04.68,4.35.02.04.07.02.07-.02.03-1.44-.31-2.88-.33-4.33-.02-1.53.1-3.07.37-4.58.52-2.94,1.58-5.79,3.16-8.33,1.68-2.72,3.83-4.94,7.1-5.48.78-.13,1.57-.18,2.36-.19.59,0,1.47-.11,1.72.65.16.48-.09,1.15-.43,1.5-.29.29-.65.47-1.04.61-1.05-.23-2.17.26-2.94.97-.18.17.08.42.27.27.39-.32,1.28-.57,2.19-.88.24.01.48.06.72.16.83.36,1.42,1.5.9,2.35-.49.8-1.87,1.06-2.72,1.2-1.05.17-2.12.14-3.16-.01-.41-.06-.6.56-.17.63,1.53.28,3.04.14,4.5-.39,1.01-.37,2.17-.86,2.19-2.1.01-.88-.56-1.74-1.36-2.08Z\"><\/path><path d=\"M39.01,55.03c.01.23.03.45.05.68.71.05,1.42-.1,2.13.03.92.17,1.96.89,1.9,1.94-.06,1-1.15,1.7-2,1.97-.68.21-1.4.06-2.07.27-.03,0-.04.05-.02.07.7.66,2.03.32,2.8-.04.87-.41,1.76-1.18,1.85-2.19.19-2.27-2.83-3.16-4.63-2.73Z\"><\/path><path d=\"M39.54,47.24c-.26-1.37-.51-2.73-.71-4.11-.12-.77-.23-1.55-.32-2.32-.08-.63-.05-1.29-.37-1.84-.1-.17-.36-.13-.41.05-.31,1.02.17,2.56.33,3.61.21,1.38.45,2.75.72,4.11.27,1.35.56,2.69.8,4.05.26,1.45.3,2.9.45,4.36,0,.08.14.12.16.02.52-2.55-.15-5.42-.63-7.94Z\"><\/path><path d=\"M40.62,67.26c-.04-1.22-.1-2.44-.17-3.66-.07-1.14-.04-2.41-.4-3.51-.02-.07-.14-.08-.15,0-.19,1.13,0,2.36.06,3.51.06,1.22.1,2.44.13,3.66.06,2.51-.03,5-.05,7.51,0,.43.65.43.67,0,.09-2.5,0-5.01-.09-7.51Z\"><\/path><path d=\"M48.43,73.63c-.66.11-1.26.49-1.9.7-.64.22-1.3.39-1.97.5-1.44.24-2.73.12-4.15-.1-.05,0-.11.03-.09.08.43,1.11,2.8.89,3.71.8,1.46-.14,3.58-.44,4.69-1.48.24-.23-.02-.56-.3-.51Z\"><\/path><path d=\"M48.61,69.73c-.03-1.38.13-2.77.08-4.15,0-.12-.17-.14-.21-.03-.45,1.32-.51,2.8-.51,4.18,0,1.37.02,2.9.42,4.22.09.31.59.26.58-.08-.06-1.38-.33-2.75-.36-4.14Z\"><\/path><path d=\"M47.81,35.54c-.04-.42-.64-.43-.66,0-.15,3.08.07,6.3.43,9.36.01.1.15.1.16,0,.24-3.07.34-6.29.07-9.36Z\"><\/path><path d=\"M47.61,35.45c-1.65-.42-3.85.17-5.4.74-1.63.6-3.5,1.48-4.58,2.88-.12.15.03.4.22.29,1.57-.92,2.91-1.99,4.68-2.56.8-.26,1.63-.45,2.47-.56.87-.12,1.76-.03,2.61-.17.33-.05.29-.55,0-.63Z\"><\/path><path d=\"M89.73,42.02c-9.39,8.51-19.78,15.9-31.61,20.64-1.65.66-3.33,1.28-5.02,1.84-1.54.51-3.12.94-4.64,1.52-.01.08-.02.16-.03.24,2.94-.41,5.83-1.53,8.59-2.58,2.93-1.11,5.82-2.39,8.63-3.79,5.77-2.89,11.22-6.43,16.32-10.37,2.85-2.2,5.65-4.51,8.26-6.99.33-.32-.17-.81-.5-.5Z\"><\/path><path d=\"M59.72,17.02c-.11-.45-.78-.26-.69.19,1.07,5.49-.24,11.17-2.18,16.34-1.74,4.63-4.66,8.57-9.17,10.74,0,.06,0,.12,0,.18,4.78-1.31,7.88-5.93,9.65-10.3,1.09-2.71,1.9-5.58,2.41-8.46.5-2.85.68-5.85-.02-8.69Z\"><\/path><path d=\"M68.27,17.27c-1.29-.9-3.12-.88-4.62-.81-.85.04-1.7.12-2.55.2-.75.07-1.54.04-2.24.33-.27.12-.19.57.08.63.75.16,1.56-.04,2.32-.12.74-.08,1.49-.16,2.24-.22,1.62-.12,3.1.11,4.7.29.18.02.2-.22.08-.3Z\"><\/path><path d=\"M68.44,17.06c-.06-.4-.69-.24-.61.17.66,3.44.84,6.95.6,10.45-.11,1.74-.31,3.47-.64,5.18-.16.87-.35,1.73-.56,2.58-.18.74-.5,1.5-.5,2.27,0,.05.07.07.1.03.43-.64.58-1.46.77-2.2.24-.9.44-1.82.62-2.74.33-1.7.57-3.41.7-5.13.26-3.55.05-7.11-.48-10.62Z\"><\/path><path d=\"M83.93,35.95c-1.1.47-2.06,1.34-2.99,2.09-1.07.87-2.15,1.72-3.29,2.49-2.16,1.45-4.52,2.49-6.79,3.75-.06.04-.02.13.05.12,2.47-.6,4.77-1.92,6.89-3.3,1.02-.67,1.99-1.39,2.95-2.15,1.13-.9,2.31-1.66,3.48-2.49.31-.22.05-.65-.29-.5Z\"><\/path><path d=\"M90.04,42.4c-.32-1.54-1.29-2.86-2.36-3.99-1.04-1.1-2.36-2.26-3.79-2.8-.45-.17-.66.49-.31.73,1.27.88,2.53,1.61,3.62,2.75,1,1.05,1.75,2.29,2.65,3.42.08.1.21-.01.19-.11Z\"><\/path><path d=\"M69.25,40.43c-.52-.68-1.06-1.33-1.61-1.98-.58-.68-1.13-1.46-1.89-1.95-.04-.03-.1.02-.08.06.54,1.4,1.82,2.6,2.73,3.78.48.62.94,1.26,1.33,1.94.44.77.64,1.56.9,2.39.1.34.67.29.64-.09-.11-1.53-1.11-2.97-2.01-4.15Z\"><\/path><path d=\"M67.81,58.28c-.4-1.88-1.31-3.75-2.22-5.43-.97-1.8-2.1-3.49-3.34-5.11-1.18-1.54-2.44-3.02-3.75-4.45-.7-.76-1.42-1.51-2.14-2.25-.68-.7-1.34-1.49-2.17-2.03-.08-.05-.18.05-.13.13.47.76,1.14,1.38,1.75,2.02.68.72,1.35,1.44,2.01,2.17,1.37,1.51,2.71,3.06,3.95,4.68,1.15,1.51,2.21,3.08,3.12,4.74,1.01,1.82,1.67,3.72,2.4,5.66.12.32.59.2.52-.14Z\"><\/path><path d=\"M98.06,33.07c-2.26-.02-4.61.55-6.7,1.37-1.87.73-3.78,1.71-5.23,3.13.1.06.19.13.28.2,1.7-1.05,3.35-2.11,5.24-2.83,2.09-.79,4.2-1.11,6.41-1.3.36-.03.38-.57,0-.57Z\"><\/path><path d=\"M96.78,35.43c-.66-.39-1.38-.15-2.07.06-1.04.31-2.07.66-3.08,1.05-.88.34-1.76.69-2.61,1.09-.46.21-1.49.45-1.54,1.06,0,.03.03.07.06.08.13.03.1.03.22-.05,0,0,0-.01,0-.02,0-.02-.01-.05-.02-.07,0-.01-.01-.01-.02,0,.11-.23,3.97-1.51,4.37-1.65.72-.25,1.44-.48,2.17-.71.77-.24,1.51-.54,2.32-.34.3.08.49-.35.21-.5Z\"><\/path><path d=\"M99.95,38.67c-.15-1.9-.68-3.76-1.49-5.48-.17-.36-.73-.04-.54.32,1.36,2.53,2.11,5.95,1.32,8.79-.04.16-.25.74-.43.82-.62.27-.71-.68-.78-.97-.17-.7-.32-1.4-.46-2.1-.29-1.49-.31-3.11-.76-4.55-.05-.16-.25-.11-.27.04-.13,1,.06,2.05.2,3.04.16,1.09.35,2.18.6,3.26.14.6.2,1.49.76,1.86.42.28.88.13,1.2-.22.42-.46.48-1.11.56-1.7.14-1.02.17-2.06.08-3.09Z\"><\/path><path d=\"M97.27,33.19c-.07-.1-.28-.05-.22.09.15.41.18.85.04,1.27-.13.37-.45.61-.55.98-.02.09.04.17.13.17.5.01.8-.59.9-1.02.12-.53.03-1.06-.3-1.49Z\"><\/path><path d=\"M59.67,16.74c-.44-1.87-1.47-3.69-2.47-5.31-1.01-1.63-2.1-3.41-3.51-4.72-.04-.04-.1,0-.08.06.84,1.69,2.13,3.15,3.11,4.76,1.05,1.71,1.75,3.47,2.43,5.35.12.32.6.2.52-.14Z\"><\/path><path d=\"M61.27,16.73c-.64-3.24-2.04-6.89-4.36-9.31-.05-.05-.12.01-.09.07.78,1.47,1.68,2.87,2.37,4.4.72,1.6,1.22,3.27,1.62,4.97.07.31.53.18.47-.13Z\"><\/path><path d=\"M65.78,4.6c-.09-.82-.79-1.32-1.53-1.53-1.95-.58-4.31-.21-6.17.5-.97.37-1.88.87-2.72,1.49-.7.52-1.53,1.14-1.88,1.96-.02.04.03.07.06.05.66-.41,1.17-1.06,1.79-1.52.7-.53,1.47-.95,2.27-1.3,1.6-.69,3.35-1.01,5.09-.89.47.03.97.08,1.42.23.32.11.57.22.79.48.44.49.38,1.21-.27,1.43-.77.26-1.77.1-2.57.19-1.8.2-3.52.74-5.13,1.57-.34.17-.04.68.3.51,1.26-.64,2.6-1.12,3.99-1.38,1.1-.21,2.26-.07,3.34-.31.72-.15,1.3-.67,1.21-1.46Z\"><\/path><path d=\"M57.43,7.44c-.67-.55-1.57-.96-2.41-.48-.5.29-1.09,1.17-.46,1.62.11.08.24-.01.28-.12.19-.47.18-.91.8-1.05.52-.11,1.15.1,1.66.22.1.02.21-.12.11-.19Z\"><\/path><path d=\"M28.27,57.97c-.14-.15-.42-.08-.46.12-.17.73.13,1.5.2,2.23.02.21.11.62.07.84-.15.77-.85.39-1.31.25-.7-.2-1.38-.44-2.05-.7-.73-.27-1.59-.49-2.27-.85-.08-.04-.14.07-.07.11.53.33.96.76,1.53,1.07.44.24.89.44,1.35.62.75.3,2,.93,2.83.7.65-.18.81-.83.84-1.43.04-.91-.02-2.28-.65-2.98Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGruppengr\u00f6\u00dfe\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tbis zu 19 Kinder\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67dde2b elementor-view-stacked elementor-widget__width-initial elementor-mobile-position-inline-start elementor-widget-mobile__width-inherit elementor-shape-circle elementor-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"67dde2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 500 500\"><path d=\"M207.43,33.68c-6.32,0-13.16,3.23-18.73,6.05-6.17,3.13-12.01,6.93-17.42,11.24-10.5,8.36-19.39,18.66-25.94,30.39-13.73,24.58-15.8,52.75-8.99,79.72.63,2.5,4.64,1.29,3.85-1.18-8.01-25.02-4.24-54.01,8.4-76.81,6.43-11.6,15.3-21.91,25.71-30.12,5.06-3.99,10.47-7.44,16.15-10.47,5.57-2.98,11.89-4.86,17.13-8.31.23-.15.12-.51-.15-.51Z\"><\/path><path d=\"M150.91,169.5c-6.21.95-9.33,10.59-16.83,8.17-3.95-1.27-5.1-6.47-3.21-9.82,2.18-3.85,6.74-4.28,10.38-5.82.44-.18.7-.79.26-1.14-4.14-3.35-10.52-1.08-13.72,2.59-3.61,4.15-3.98,10.47-.92,15.05,3,4.47,8.75,5.69,13.66,4.05,4.38-1.46,12.37-5.93,12.25-11.29-.02-.9-.91-1.93-1.89-1.78Z\"><\/path><path d=\"M352.22,94.23c-2.4-4.69-7.4-7.42-12.64-6.27-3.9.86-9.31,4.52-7.97,9.15.15.51.84.67,1.19.27,2.26-2.55,3.78-4.81,7.49-5.1,4.03-.31,7.16,2.13,8.17,6.03,2.42,9.37-7.03,14.62-15,14.5-4.09-.06-3.89,6.65.18,6.34,12.01-.93,25.28-11.84,18.59-24.91Z\"><\/path><path d=\"M284.16,140.87c-.72-1.46-2.95-1.45-3.93-.35-2.14,2.4-1.98,5.76-2.94,8.75-1.13,3.54-2.83,6.93-4.89,10.01-3.88,5.83-9.32,10.68-15.59,13.79-14.18,7.03-29.85,4.39-43.12-3.22-1.16-.66-2.25.97-1.33,1.87,11.85,11.54,31.7,13.75,46.43,6.93,7.34-3.4,13.63-8.78,18.28-15.39,3.65-5.19,10.2-16.01,7.08-22.38Z\"><\/path><path d=\"M331.84,118.14c-.52,2.26-.07,4.33-.07,6.63,0,2.69-.17,5.4-.39,8.08-.45,5.38-1.35,10.73-2.62,15.97-2.42,9.99-6.31,19.64-11.72,28.38-5.66,9.15-13.28,17.6-22.08,23.82-4.36,3.07-9.04,5.72-13.97,7.77-5.08,2.12-10.51,3.1-15.61,5.1-1.02.4-.78,1.81.31,1.87,10.5.6,22.15-5.52,30.69-11.11,9.44-6.18,17.5-13.94,23.86-23.27,6.19-9.08,10.61-19.28,13.42-29.89,1.51-5.69,2.54-11.5,3.2-17.34.56-5,1.9-11.35.62-16.2-.75-2.83-4.99-2.56-5.62.19Z\"><\/path><path d=\"M217.87,165.15c-2.48.72-4.02,2.66-6.11,4.07-1.95,1.33-4.07,2.27-6.21,3.19.02-.13.03-.26.04-.4.05-.15-.17-.27-.27-.15-.53.45-1.07.89-1.6,1.34-1.02.52-.35,1.93.61,1.98,5.05.2,14.03-2.96,15.01-8.66.15-.86-.59-1.63-1.47-1.38Z\"><\/path><path d=\"M291.87,138.83c-1.73-1.47-3.94-.36-5.98-.21-2.42.18-4.76-.15-7.18-.19-1.06-.01-1.77,1.58-.84,2.25,2.23,1.63,5.01,2.26,7.75,2.3,2.34.04,5.92-.07,6.68-2.73.14-.49-.05-1.1-.44-1.42Z\"><\/path><path d=\"M256.88,132.69c-12.7,5.92-25.12-4.07-25.22-17.27,0-.53-.85-.64-.93-.1-2.21,14.66,12.45,24.93,25.6,20.3-.12,3.17-1.41,6.07-3.66,8.44-2.05,2.16-4.83,2.95-6.99,4.89-.88.79-.35,2.6.84,2.74,8.83,1.05,13.11-11,12.32-17.96-.12-1.05-1.05-1.47-1.96-1.04Z\"><\/path><path d=\"M199.02,31.36c-2.87-2.86-7.52-3.7-10.72-6.41-3.48-2.95-6.09-6.66-8.01-10.79-.64-1.37-2.63-.26-2.31,1.07,1.25,5.17,3.95,9.73,7.96,13.26,3.19,2.82,8.05,6.47,12.51,5.38,1.14-.29,1.32-1.76.57-2.51Z\"><\/path><path d=\"M204.51,25.64c-1.7-3.01-5.24-4.86-7.79-7.13-3.06-2.73-6.01-6.01-7.94-9.65-.32-.6-1.31-.14-1.09.5,2.32,6.7,7.16,18.17,15.69,18.41,1.11.03,1.62-1.26,1.13-2.12Z\"><\/path><path d=\"M209.64.37c-2.27,2.86-3.32,6.45-3.83,10.03-.45,3.23-1.25,7.32,1.38,9.77.67.63,1.88.63,2.49-.1,2.03-2.44,1.34-5.59,1.46-8.58.15-3.45.7-6.96.42-10.41-.07-.88-1.28-1.52-1.92-.72Z\"><\/path><path d=\"M211.64,41.61c-.9-1.08-2.39-1.14-3.17.12-2.05,3.32-.76,8.63-.97,12.43-.28,5.03-1.02,10.04-2.19,14.95-2.27,9.53-5.92,18.96-10.43,27.66-.35.66.58,1.37,1.1.77,6.72-7.82,11.39-16.59,14.1-26.57,1.32-4.86,2.19-9.8,2.64-14.81.37-4.18,1.76-11.11-1.08-14.55Z\"><\/path><path d=\"M219.01,49.72c-.72-1.36-3.21-1.36-3.78.15-1.27,3.34-.6,6.86-.67,10.4-.08,3.89-.27,7.79-.74,11.66-.92,7.69-2.76,15.22-4.06,22.85-.13.74.81,1.08,1.21.45,4.34-6.89,6.67-14.91,7.97-22.89.62-3.8,1.05-7.64,1.19-11.47.13-3.73.64-7.79-1.14-11.16Z\"><\/path><path d=\"M228.27,57.07c-.81-1.19-2.59-1.16-3.3.13-2.52,4.55-.83,11.63-.78,16.7.06,6.38.2,12.76.64,19.12.05.72,1.03.8,1.24.13,1.87-6.03,2.97-12.23,3.41-18.52.36-5.16,1.83-13.11-1.21-17.55Z\"><\/path><path d=\"M208.19,43.94c-2.41,3.25-2.9,7.69-4.15,11.51-1.53,4.69-3.36,9.29-5.42,13.77-4.01,8.75-8.96,17.1-14.7,24.82-5.46,7.32-11.65,14.05-18.31,20.3-7.28,6.84-15.38,12.39-23.15,18.6-.45.36-.17,1.24.46,1,17.76-6.78,33.07-21.94,44.34-36.83,5.77-7.62,10.8-15.79,14.97-24.39,2.13-4.4,4.02-8.9,5.7-13.49,1.52-4.17,4.22-9.57,3.57-14.05-.21-1.43-2.2-2.75-3.31-1.24Z\"><\/path><path d=\"M329.34,78.88c-18.35,2.44-35.97,3.63-54.14-1-8.86-2.26-17.42-5.58-25.47-9.92-3.89-2.08-7.7-4.34-11.34-6.83-3.34-2.27-6.67-6.11-10.71-6.95-.95-.2-1.99.72-1.61,1.71,1.41,3.7,5.35,5.87,8.47,8.06,3.99,2.81,8.15,5.38,12.51,7.58,8.45,4.26,17.45,7.51,26.66,9.65,17.81,4.14,38.43,5.26,55.8-1.32.5-.19.43-1.06-.16-.99Z\"><\/path><path d=\"M337.79,90.58c-13.44-21.87-33.54-42.32-56.59-53.86-21.34-10.68-50.49-15.87-72.27-3.43-.96.55-.22,1.99.79,1.72,13.07-3.54,25.51-6.5,39.15-4.77,11.43,1.45,22.44,5.25,32.55,10.74,10.75,5.85,20.35,13.61,28.86,22.37,8.95,9.21,15.84,19.55,23.18,29.99,1.89,2.68,6.07.08,4.33-2.75Z\"><\/path><path d=\"M300.44,46.51c-.19-.26-.29-.8-.16-1.15,0,0,.02-.07.02-.07l.05-.13.1-.27c2.01-5.41,4.58-10.6,7.68-15.48,6.26-10.06,17-19.91,29.82-16.64,21.03,4.91,40.83,30.15,48.93,49.32,1.83,5.23,4.03,10.32,4.5,15.89.08,1.98-1.78,3.34-3.45,2.01,1.26.79-17.71-10.07-17.39-9.87-.78-.45-2.59-1.47-3.34-1.9.05.03-.15-.09.1.05.37.17.73.25,1.29.1.55-.2.76-.43,1-.83-.11,2.47.42,11.92.61,15.24,0,1.89.34,3.66-.18,5.57-.19.41-.21.52-.62.92-.67.65-1.86.75-2.62.26-.79-.51-1.1-1.08-1.55-1.66-.47-.65-1.71-2.54-2.17-3.24-2.08-3.1-3.97-6.45-6.23-9.1.02.02.05.04.07.05l.11.07c.61.39,1.77.32,2.36-.21.34-.28.48-.48.63-.8.01-.05,0,0,0-.02-.04.13-.11.54-.15.9-.36,3.34-.55,7.82-.78,11.24-.27,2.16-.08,4.26-1.13,6.34-.94,1.55-3.22,1.6-4.26.11-.82-1.15-1.53-3.16-2.13-4.42-4.52-10.68-9.01-21.82-15.03-31.66-1.58-2.42-3.52-5.4-5.93-6.74-2.74-1.28-5.99-1.97-9.22-2.46-6.32-.96-12.89-1.11-19.3-1,0,0-.31,0-.31,0h-.08c-.39.06-.99-.18-1.23-.44h0ZM302.28,45.08c-.09-.26-.47-.5-.76-.47,0,0,.08,0,.08,0,3.24-.29,6.66-.47,9.9-.48,3.42-.02,6.84.08,10.29.44,5.04.55,11.61,1.71,14.89,6.11,5.61,6.66,9.25,14.57,12.96,22.33,2.68,5.61,5.09,11.78,7.84,17.35-.8-1.2-3.11-1.03-3.69.39,0,.02.04-.12.07-.26l.09-.5c.58-4.33.65-9.36,1.07-13.73.14-1.13.17-2.28.63-3.44.73-1.78,2.92-2.09,4.26-.82.54.49.98,1.08,1.34,1.58,2.56,3.65,4.55,7.2,6.85,10.81,0,0,.66,1,.66,1l.31.44c.07.11.26.29.07.13-.12-.12-.33-.2-.49-.27-1.07-.49-2.5.28-2.71,1.27.14-1.31.09-2.71.09-4.06l-.21-10.12c.01-1.97-.13-3.99.2-6.11.03-.25.22-.82.51-1.17.54-.76,1.86-.94,2.58-.41,1.95,1.19,18.96,11.31,20.71,12.39-.37-.27-1.32-.05-1.53.46-.04.04-.07.1-.07.15,0-.04.02-.09.02-.21-1.53-10.77-6.16-20.95-12.06-30.07-9.11-13.7-22.27-28.65-38.74-32.77-15.11-3.61-25.81,11.17-31.62,23.15-1.21,2.51-2.33,5.1-3.28,7.72l-.04.12s-.02.06,0,0c.12-.3-.02-.76-.23-.96h0Z\"><\/path><path d=\"M143.88,80.57c-6.68-4.58-13.3-9.15-20.33-13.07-6.43-3.52-13.58-7.36-20.99-5.47-12.24,2.5-24.23,9.79-30.67,20.68-3.66,6.69-5.76,14.62-7.15,22.12-.53,3.53-1.14,7.32-.57,10.74-.2-.53-1.15-1.17-1.91-1.18-.51-.03-1.02.11-1.18.22,2.51-2,4.71-4.58,7.01-6.99,3.37-3.61,7.7-8.55,11.18-12.02,1.04-.92,2.18-2.41,3.91-2.35.86.01,1.73.62,2.09,1.25.46.77.54,1.46.67,2.09,1.37,8.62,1.23,17.44,4.06,25.62.21.5.48.98.65,1.16.08.09.1.07-.08.01-.21-.06-.34-.02-.43.02.7-.71,1.43-2.53,1.9-3.9,1.7-5,3.19-10.39,5.46-15.49,4.22-10.48,13.37-19.04,24.61-21.53,5.49-1.21,11.42-1.04,16.56,1.42.33.16.46.56.29.89-.16.32-.54.45-.86.31-10.01-3.65-21.32.42-28.88,7.38-3.79,3.46-6.41,8.09-8.41,12.94-2.04,4.89-3.32,10.04-4.98,15.36-.58,1.7-1.21,3.75-2.56,5.31-2.67,2.92-5.98.91-7.16-2.17-3.41-8.63-3.35-18.19-5.15-27.04.15.35.45.75.96,1.02.52.32,1.49.35,1.93.12.04,0,.21-.1.19-.09.03-.02,0,0-.02.02-2.28,2.09-4.42,4.73-6.56,7.13,0,0-5.36,6.15-5.36,6.15-2.55,2.76-4.88,5.84-8.03,8.16-.62.38-1.25.68-2.23.64-1-.01-2.05-.79-2.48-1.47-.84-1.25-.95-2.73-1.07-3.85-.41-9.31,1.87-18.4,4.76-27.13,1.7-5.37,4.73-10.86,8.62-15.08,7.84-8.61,18.36-14.3,29.76-16.52,5.99-1.46,12.32-.02,17.55,2.76,5.06,2.55,9.62,5.75,13.97,9.29,4.26,3.52,8.27,7.29,11.88,11.47.53.64-.27,1.54-.96,1.05h0Z\"><\/path><path d=\"M266.04,214.54c-5.84,1.35-11.3,3.91-17.18,5.25-6.11,1.4-12.55,2.22-18.8,2.44-12.09.44-24.33-1.22-35.49-5.25-10.31-3.73-19.78-9.3-27.87-16.32-4.02-3.48-7.7-7.32-10.91-11.49-1.69-2.2-3.28-4.48-4.74-6.83-1.37-2.21-2.29-4.59-4.4-6.23-1.83-1.42-5-.28-4.92,2.19.17,5.2,4.91,10.57,8.01,14.58,3.57,4.62,7.62,8.94,12.08,12.8,8.75,7.57,19.05,13.48,30.31,17.21,12.05,3.99,25.09,5.46,37.98,4.18,6.5-.64,12.73-1.88,19-3.77,5.92-1.78,12.57-3.82,17.46-7.63.59-.46.24-1.31-.53-1.13Z\"><\/path><path d=\"M286.68,215.6c1.49,19.43,7.73,38.25,18.86,54.19,7,10.88,15.19,20.69,25.7,28.27,4.46,3.38,11.45,7.79,16.27,10.81,11.26,7.4,21.7,15.51,31.24,25.16,1.64,1.66.95,4.61-1.23,5.4.05.15-.59-1.27-.33-.66l-.03.02c-.21.12-.67.35-.9.47-19.92,10.18-41.97,14.98-62.97,22.28-10.68,3.56-21.25,7.15-31.48,11.73-7.63,3.19-15.89,7.85-24.28,8.75-2.93.36-5.79.48-8.8.3-.89-.05-1.57-.82-1.52-1.71.05-.87.78-1.54,1.65-1.52,2.66.06,5.47-.16,8.15-.61,7.89-1.18,15.67-6.05,22.89-9.39,30.54-14.72,63.44-23.48,95.16-35.1.28.6-.35-.83-.27-.69,0,0,.11-.05.11-.05l-1.09,5.34c-4.27-4.57-9.15-8.99-14.08-13.13-6.16-5.14-12.78-10.01-19.53-14.36-9.9-6.28-19.5-13.31-27.23-22.25-8.63-10.33-15.91-21.69-21.15-34.05-4.95-12.48-7.41-25.77-7.36-39.18,0-.61.51-1.1,1.12-1.09.6,0,1.08.49,1.09,1.08h0Z\"><\/path><path d=\"M193.54,228.53c-2.43,22.9-3.76,46.79-5.43,69.81-.27,2.91-4.59,2.61-4.41-.35,1.5-23.03,2.67-47.05,4.93-69.94.37-3.24,5.17-2.81,4.92.48h0Z\"><\/path><path d=\"M187,223.34c-10.15,5.83-33.79,18.57-43.23,24.7-4.55,3.07-9.17,6.26-13.65,9.3-16.22,10.69-18.16,22.66-14.67,40.83,1.18,5.19,3.03,10.55,5.77,15.07.43.69.21,1.6-.48,2.03-.67.41-1.54.22-1.99-.41-3.41-4.88-5.57-10.16-7.18-15.72-6.59-25.39-.02-38.35,21.46-52.16,16.02-11.54,33.95-19.81,51.76-28.07,2.85-1.21,4.94,2.83,2.21,4.42h0Z\"><\/path><path d=\"M192.11,234.25c-14.29,7.66-28.83,15.06-42.01,24.4-5.34,3.37-12.03,7.16-15.89,11.93-4.27,4.86-5.57,11.57-5.58,17.96-.06,6.48-.41,13.33,1.95,19.44.03.08.13.22.06.15,1.28,1.44-.87,3.42-2.19,1.98-.39-.43-.46-.64-.71-1.04-3.52-7.48-3.57-16-3.92-24.1-.28-12.37,6.8-21.75,16.63-28.23,2.84-2.01,5.89-3.89,8.71-5.83,4.8-3.52,10.07-6.68,15.2-9.36,8.38-4.43,16.91-8.32,25.69-11.79,2.88-1.08,4.8,2.99,2.05,4.49h0Z\"><\/path><path d=\"M121.35,319.35c.15.02.49-.22.5-.25,0,.01-.02.03-.03.04-2.13,3.33-2.31,7.54-2.21,11.44.27,5.58,3.34,22.64,8.17,25.44,0,0,.1.03.1.03.03.01.1.03.02.01-.21-.02-.41.16-.33.1.36-.56.55-1.79.64-2.58.22-2.11.22-4.35.14-6.51-.03-1.48,2.16-1.57,2.26-.1.12,2.87.23,5.77-.32,8.65-.15.62-.26,1.24-.82,2.02-.68.99-2.05,1-2.98.45-5.85-3.29-9.19-20.74-9.69-27.38-.2-3.48.03-7.09,1.17-10.46.51-1.29.98-2.71,2.16-3.6,2.02-1.25,3.49,1.99,1.23,2.69h0Z\"><\/path><path d=\"M131.09,344.43c.87,3.52,1.98,7.03,3.4,10.35,1.1,2.56,2.38,4.71,4.62,6.24.5.33,1.49,1,2.01.85-.02-.01.02-.02-.14-.05h-.03s-1.45.93-1.45.93c1.8-6.54-1.35-13.4-3.5-19.54-.59-1.49,1.63-2.42,2.27-.93,2.53,6.8,5.88,13.95,3.86,21.37-.19.77-1.14,1.16-1.79.83-.48-.21-.96-.71-1.34-1.06-.99-1.02-2.1-2.01-3.04-3.08-3.29-4.72-4.34-10.26-6.07-15.61-.22-.79,1-1.12,1.19-.3h0Z\"><\/path><path d=\"M137.16,341.61c2.93,5.26,5.61,11.98,11.37,14.62.89.29,1.59.37,1.83.05.15-.86-.33-1.95-.71-2.92-1.44-3.24-3.21-6.47-5.09-9.52-.93-1.56-1.93-3.09-2.91-4.6-.39-.57-.23-1.35.35-1.72.54-.35,1.25-.22,1.63.28,3.92,5.35,7.9,10.91,9.54,17.48.49,2.48-1.72,4.6-4.18,3.65-2.35-1.12-4.03-2.89-5.81-4.72-2.8-3.77-4.81-7.99-7.09-12.04-.39-.72.73-1.31,1.09-.56h0Z\"><\/path><path d=\"M422.85,181.03c4.01-4.93,9.54-10.3,9.74-17.01-.08-1.01-.29-1.75-.76-1.95-.85.15-1.69.99-2.48,1.73-3.97,4.05-7.45,8.78-10.67,13.46-.94,1.39-3.07.09-2.25-1.38,3-5.2,6.48-10.04,10.8-14.29,1.31-1.16,2.8-2.67,4.95-2.5,1.76.18,2.88,1.9,2.89,3.41-.14,2.75-1.18,5.12-2.23,7.61-2.55,4.29-5.92,7.93-8.99,11.79-.56.68-1.6-.2-1-.87h0Z\"><\/path><path d=\"M141.02,336.38c6.29,5.36,13.96,11.9,22.27,10.63-.51.4-.72,1.18-.47,1.71-2.3-3.13-5.39-5.57-8.06-8.51-2.9-3.16-6.96-5.52-10.79-7.49-1.99-.94-1.38-4.04.78-4.19,4.2-.38,8.83-.62,13.07-.84,2.18-.08,4.93-.49,6.46-1.58-.03-.17-.28-.54-.71-.95-1.95-1.84-4.18-3.6-6.39-5.29-4.34-3.01-8.69-6.66-13.85-7.97-2.93-.56-6.26-.55-9.06.48-1.68.89-3.22,2.14-4.9,3-2.13,1.19-4.31-1.59-2.69-3.38,2.21-2.41,4.95-4.5,8.2-5.01,6.32-1.33,12.81.5,17.85,4.37,4.84,3.38,9.35,6.81,13.66,10.9.59.58,1.3,1.3,1.75,2.49,1.52,4.59-4.1,7.04-7.68,7.59-4.99.53-10.19.67-15.17.73,0,0,1.12-4.22,1.12-4.22,3.22,2.65,8.07,6.05,10.77,9.18,2.65,3.02,6.05,5.45,8.63,8.69,2.82,5.03-6.77,4.53-9.39,3.8-2.43-.53-4.77-1.55-6.85-2.89-4.06-2.7-7.33-6.03-10.16-9.77-.8-1.05.66-2.36,1.62-1.47h0Z\"><\/path><path d=\"M410.04,207.67c-.06-.14-.43-.33-.46-.32.02,0,.03,0,.05,0,3.95.28,7.73-1.57,11.11-3.52,4.75-2.87,18.32-13.78,18.46-19.33,0,0-.02-.1-.02-.1,0-.03-.02-.1,0-.02.08.19.33.28.24.24-.66-.05-1.83.37-2.57.67-1.96.81-3.93,1.88-5.79,2.99-1.27.75-2.41-1.16-1.17-1.93,2.46-1.48,4.96-2.96,7.75-3.85.77-.22,2.04-.53,3,.06,5.52,5.22-13.96,21.04-18.44,23.68-1.96,1.22-4.04,2.28-6.27,3.06-2.3.74-4.84,1.46-7.28.9-2.55-.81-.61-4.33,1.39-2.54h0Z\"><\/path><path d=\"M428.53,186.86c2.68-2.45,5.23-5.1,7.47-7.93,1.72-2.19,3-4.34,3.28-7.04.05-.6.17-1.79-.21-2.17,0,.02-.03-.01.02.15-.02.04,1.51.84,1.52.86-3.08.67-6.04,2.56-8.37,4.82-2.51,2.36-4.9,4.95-7.13,7.59-.43.53-1.22.61-1.74.17-.51-.43-.58-1.2-.16-1.71,2.28-2.78,4.64-5.42,7.23-7.94,2.7-2.65,5.86-4.78,9.7-5.66.76-.2,1.56.44,1.59,1.18.05.52-.17,1.19-.29,1.68-.42,1.36-.77,2.8-1.26,4.14-2.57,5.15-6.94,8.71-10.82,12.78-.59.57-1.46-.34-.84-.9h0Z\"><\/path><path d=\"M414.86,178.69c2.53-4.38,4.52-9.52,3.78-14.65-.39-2.55-.7-5.43-2.17-7.56-.07-.05.09.08.17.1.33.15.9,0,.99-.07-2.76,3.85-5.13,8.79-6.74,13.42-.79,2.15-2.45,7.49-3.35,9.62-.74,1.6-3.2,1.53-3.87-.07-1.78-3.89-3.81-7.65-6.01-11.3-.97-1.71-2.18-3.24-3.86-4.21-.52-.29-1.18-.6-1.43-.38-1.09,2.8-1.44,6.3-1.96,9.4-.53,5.25-1.68,10.78-.46,15.95.69,2.33,1.97,4.7,3.53,6.54,1.57,1.98,4.1,2.6,6.07,4,1.08.62,1.44,2.04.76,3.09-1.6,2.23-4.69.09-6.58-.59-5.58-2.75-9.16-10.57-9.12-16.57.19-7.42,1.5-14.51,3.4-21.68.48-2.13,2.52-4.47,5.09-3.82,3.41.97,5.26,3.97,7.11,6.64,2.29,3.49,4.81,7.28,7.36,10.56,0,0-4.09.36-4.09.35,1.83-4.23,5.73-14.07,8.26-17.79,1.36-2.05,2.31-4.2,4.34-5.77.19-.09.39-.25.97-.27.25.02.42.04.59.11,3.31,1.59,3.6,10.1,3.48,13.47-.44,4.56-2.15,8.66-4.26,12.67-.31.57-1.03.78-1.6.46-.6-.33-.79-1.1-.42-1.67h0Z\"><\/path><path d=\"M100.8,206.4c14.61-5.17,31.32-2.34,42.82,8.22,6.7,6.31,10.78,15.1,11.69,24.21.33,4.54-6.28,5.29-6.97.78-.54-4.88-2.53-9.77-5.21-13.84-3.78-6.1-10.78-10.19-17.58-12.27-6.96-1.92-14.71-1.23-21.47,1.21-5.64,2.18-8.92-6.05-3.27-8.31h0Z\"><\/path><path d=\"M156.54,298.13c-.52-14.92.13-30.15-2.71-44.82-1.06-4.5,5.51-6.23,6.79-1.77,1.37,7.88,1.13,15.87,1,23.77-.18,7.65-.48,15.27-.81,22.9-.15,2.72-4.2,2.67-4.27-.07h0Z\"><\/path><path d=\"M241.93,242.57c-5.36,0-9.61-1.43-12.66-4.26-4.47-4.16-4.52-9.78-4.52-10.02,0-1.36,1.11-2.47,2.47-2.47s2.46,1.1,2.47,2.45c0,.1.12,3.82,3,6.46,2.44,2.24,6.23,3.19,11.27,2.82,4.47-.32,7.83-1.79,9.96-4.37,3.38-4.07,2.77-9.74,2.77-9.79-.15-1.35.81-2.58,2.16-2.74,1.35-.17,2.57.8,2.74,2.15.04.31.88,7.76-3.83,13.49-3.03,3.68-7.55,5.76-13.44,6.18-.82.06-1.61.09-2.38.09ZM229.69,228.29h.01-.01Z\"><\/path><path d=\"M130.58,303.75c.69-1.67,2.1-2.12,3.55-2.76,4.07-1.76,8.32-3.11,12.67-3.98,29.21-5.97,60.05,7.8,77.41,31.52,28.26,37.82,25,92.78-.42,131.2-19.81,30.55-55.28,48.91-90.62,33.11-43.76-19.78-61-74.06-52.29-118.77,3.26-17.02,10.09-33.66,21.18-47.11,3.65-4.5,7.81-8.6,12.34-12.19.54-.43,1.32-.33,1.75.2.4.51.34,1.23-.11,1.67-4.05,3.89-7.79,8.07-11.13,12.55-30.04,40.22-29.46,101.67,3.66,139.9,22.75,26.51,60.03,34.03,88.81,12.36,44.31-33.51,56.54-105.04,22.88-149.95-17.9-24.33-51.26-37.52-80.42-27.58-1.29.44-2.57.94-3.83,1.47-1.29.5-2.37,1.34-4.18.84-1.09-.25-1.71-1.47-1.26-2.49h0Z\"><\/path><path d=\"M307.39,263.61c24.59,3.82,43.55,24.26,52.92,46.36.39,1.49,2.35,5.86-.09,6.17-.44.03-.84-.15-1.1-.47-2.17-2.44-3.24-5.35-4.73-8.16-1.47-2.74-3-5.44-4.62-8.08-4.86-7.91-10.97-15.01-18.47-20.49-2.06-1.51-5.46-3.79-7.65-5.11,0,0-4.06-2.19-4.06-2.19-3-1.45-7.52-3.43-10.72-4.36,0,0-1.11-.36-1.11-.36l-.55-.18c-.18-.07-.38-.06-.49-.43l-.41-1.36c-.22-.68.36-1.41,1.08-1.35h0Z\"><\/path><path d=\"M168.78,316.76c1.27-.72,2.32-.24,3.41,0,1.07.29,2.19.47,3.23.87,4.16,1.4,8.46,3.11,12.22,5.37,25.57,14.49,37.86,44.88,37.3,73.33.1,41.28-30.56,96.21-78.2,86.99-17.61-3.66-32.09-16.32-41.17-31.41-14.24-23.57-17.31-53.09-10.36-79.54,3.07-11.66,8.31-22.89,15.91-32.3,2.81-3.39,5.9-6.54,9.29-9.33.44-.36,1.08-.3,1.44.14.34.41.3,1.02-.08,1.38-18.16,18.06-27.04,43.99-26.49,69.34.35,32.62,18.02,70.37,52.2,78.18,25.97,5.98,49.2-13.01,60.88-34.8,20.66-36.96,17.22-91.82-20.07-116.86-3.5-2.15-7.25-4.29-11.13-5.65-1.74-.66-4.15-1.52-5.95-1.89-1.01-.28-2.05-.33-2.87-1.57-.56-.72-.36-1.8.44-2.25h0Z\"><\/path><path d=\"M165.69,394.97c.31,9.32-8.08,19.96-17.68,13.47-7.13-5.57-7.36-16.79-2.42-23.8,8.6-11.25,20.5-1.2,20.1,10.34h0ZM162.75,394.87c.41-5.4-2.11-12.76-8.34-13.16-9.35.6-11.32,14.18-6.92,20.74,6.16,9.21,15.01.85,15.25-7.59h0Z\"><\/path><path d=\"M163.72,380.6c10.68-13.75,21.88-27.19,34.71-38.99,1.48-1.33,3.69.68,2.5,2.28-5.2,7.01-11.07,13.44-17.07,19.76-6,6.32-12.14,12.5-18.59,18.37-.91.84-2.31-.41-1.55-1.41h0Z\"><\/path><path d=\"M164.18,410.25c12.1,14.27,23.8,28.97,33.57,44.96.47.81.2,1.85-.61,2.32-.71.41-1.59.26-2.12-.33-6.22-7.02-11.72-14.58-17.1-22.25-5.37-7.67-10.59-15.44-15.43-23.46-.65-1.06.87-2.2,1.69-1.23h0Z\"><\/path><path d=\"M139.75,402.44c-12.41,8.61-24.94,17.05-37.91,24.79-1.86,1.06-3.57-1.61-1.81-2.85,6.25-4.24,12.65-8.24,19.1-12.16,6.45-3.93,12.93-7.81,19.49-11.55,1.12-.64,2.2,1.01,1.12,1.77h0Z\"><\/path><path d=\"M169.18,394.94c15.76-.6,31.68-.57,47.23,2.27.92.2,1.51,1.1,1.32,2.02-.16.75-.8,1.28-1.52,1.35-7.91.62-15.78.12-23.65-.56-7.87-.69-15.71-1.56-23.5-2.99-1.19-.21-1.09-2.03.13-2.09h0Z\"><\/path><path d=\"M140.05,389.24c-14.39-6.45-28.65-13.53-41.34-22.97-.74-.58-.87-1.66-.28-2.4.48-.6,1.28-.8,1.96-.53,7.37,2.95,14.2,6.89,20.95,10.99,6.75,4.11,13.4,8.36,19.74,13.1.97.72.08,2.3-1.04,1.82h0Z\"><\/path><path d=\"M255.13,383.19c7.79,14.9,6.75,32.28,6.37,48.53-.13,5.41-.47,10.77.09,16.27.19,1.91-1.2,3.62-3.11,3.81-2.37.29-4.37-2.08-3.71-4.36,1.38-5.22,1.66-10.59,1.98-15.92.5-10.57.71-21.28-.68-31.74-.76-5.08-1.79-10.38-3.9-15.04-.89-1.91,1.87-3.38,2.96-1.56h0Z\"><\/path><path d=\"M288.24,472.95c-.04,18.46-18.8,32.63-36.24,24.9-21-9.43-21.28-40.76-.31-50.49,18.02-8.34,37.04,6.58,36.55,25.59h0ZM282.67,472.95c-.21-18.37-21.76-29.01-34.98-15.11-7.88,8.07-8.12,22.25-.44,30.63,13.67,14.83,35.8,3.74,35.42-15.51h0Z\"><\/path><path d=\"M359.3,420.8c29.25,1.95,35.8,43.01,8.6,53.88-6.07,2.28-13.02,1.93-18.85-.86-2.49-1.47-8.23-3.85-5.56-7.43.94-1.08,2.54-1.25,3.68-.45,2.75,1.86,5.83,3.12,9.02,3.57,9.94,1.51,19.59-5.03,22.7-14.67,3.76-10.94-1.98-24.48-13.43-27.79-2.02-.55-4.16-.8-6.23-.69-3.84.03-3.79-5.68.06-5.57h0Z\"><\/path><path d=\"M269.36,472.95c0,4.31-4.11,7.84-8.42,7.84s-7.81-3.5-7.81-7.81,3.5-8.76,7.81-8.76,8.42,4.42,8.42,8.73Z\"><\/path><path d=\"M269.87,110.33c.69,3.86-1.35,7.48-4.08,7.97s-5.5-2.25-6.18-6.11c-.69-3.86.82-8.24,3.55-8.72s6.03,3.01,6.72,6.87Z\"><\/path><path d=\"M212.86,130.88c.69,3.86-1.35,7.48-4.08,7.97s-5.5-2.25-6.18-6.11c-.69-3.86.82-8.24,3.55-8.72s6.03,3.01,6.72,6.87Z\"><\/path><path d=\"M353.15,343.88c7.47,9.81,12.54,21.34,14.22,33.57,2.54,15.69,3,32.45-2.87,47.46-1.36,3.73-2.86,7.37-4.6,10.95-.35.73-1.23,1.04-1.96.68-.66-.32-.98-1.07-.76-1.76,2.2-7.27,4.65-14.81,5.76-22.27,1.08-7.52,1.17-15.15.56-22.77-.7-7.46-1.74-15.19-4.35-22.26-2.59-6.9-6.43-13.65-11.25-19.19-2.98-3.53,2.24-7.97,5.24-4.4h0Z\"><\/path><path d=\"M313.73,358.61c4.86,3.16,9.01,7.03,12.34,11.76,5,7.94,7.64,17.09,8.89,26.31.88,6.38.1,15.46-.08,21.93-.17,5.26-.54,10.72-.46,15.9.03.82.08.9.39,1.38.67.88,2.12.71,3.28.5,1.85-.38,2.21-3.36,2.12-4.81.55-10.58,1.07-21.31.71-31.91-.19-7.02-.35-13.97-2.9-20.52-1.22-3.22-2.8-6.39-4.44-9.56-1.63-3.17-3.35-6.34-5.06-9.5-.48-.86-.16-1.95.71-2.42.84-.45,1.89-.16,2.37.66,3.67,6.21,7.55,12.29,10.49,19.22,2.97,6.88,3.35,14.64,3.69,21.94.3,7.26.4,14.55,0,21.81-.13,3.08-.44,6.38-.68,9.46,0,0-.07,1.03-.07,1.03,0,2.82-1.07,4.55-2.89,6.42-2.98,2.88-9.52,2.91-11.3-1.43-.9-2.64-.56-5.03-.58-7.56.22-7.24.95-14.39,1.22-21.59.58-10.53-1.88-21.01-6.37-30.48-2.83-6.24-8.09-11.13-13.79-14.67-2.54-1.61-.21-5.46,2.42-3.88h0Z\"><\/path><path d=\"M373.59,442.68c-4.14-1.94-8.98-1.1-13.37-1.13-7.16-.05-13.09-2.84-19.65-5.23-.67-.25-1.07.65-.66,1.11,4.08,4.64,10.4,6.82,16.37,7.6,3.32.44,6.56.1,9.87.15,3.67.05,12.64,2.75,5.3,7.42-7.77,4.93-19.42.72-26.83-2.9-3.4-1.65-7.23-3.41-9.95-6.07-3.78-3.67-2.84-6.87-.49-10.83.44-.73-.09-1.99-1.06-1.88-3.6.4-5.15,3.8-5.07,7.24.11,4.36,3.05,7.73,6.47,10.11,9.42,6.57,23.16,12.06,34.74,9.09,6.69-1.72,13.02-10.62,4.34-14.68Z\"><\/path><path d=\"M302.68,451.05c-.06-.94.2-2.13.32-3.06,2.01-12.19,1.78-24.53,1.24-36.84-.35-6.39-.35-12.92-2.93-18.79-1.24-2.88-2.9-5.74-4.5-8.65l-4.83-8.75c-.47-.86-.16-1.94.7-2.41.84-.47,1.9-.17,2.39.65,3.1,5.29,7.56,11.87,10.19,17.4,3.08,6.32,3.27,13.51,3.77,20.3.81,11.73.6,23.64-1.09,35.3-.16,1.02-.51,3.22-.66,4.24,0,.06-.03.22-.02.19,0-.02,0-.04-.02-.05.23,2.99-4.17,3.46-4.55.46h0Z\"><\/path><path d=\"M277.2,373.49c6.15,4.01,11.51,9.11,14.74,15.76,5.51,11.09,7.87,23.59,6.97,35.93.16,8.58.13,17.15-1.05,25.7-.12.98-1.01,1.67-1.99,1.55-.86-.11-1.51-.82-1.56-1.66-.46-6.87-.52-13.73,0-20.57.45-2.93.39-7.26.48-10.26.05-3.28-.2-6.59-.72-9.86-1.8-9.53-4.64-19.56-11.65-26.61-2.28-2.31-4.98-4.45-7.66-6.1-2.52-1.64-.17-5.45,2.44-3.87h0Z\"><\/path><path d=\"M337.06,457.56c-4.14-1.94-8.98-1.1-13.37-1.13-7.16-.05-13.09-2.84-19.65-5.23-.67-.25-1.07.65-.66,1.11,4.08,4.64,10.4,6.82,16.37,7.6,3.32.44,6.56.1,9.87.15,3.67.05,12.64,2.75,5.3,7.42-7.77,4.93-19.42.72-26.83-2.9-3.4-1.65-7.23-3.41-9.95-6.07-3.78-3.67-2.84-6.87-.49-10.83.44-.73-.09-1.99-1.06-1.88-3.6.4-5.15,3.8-5.07,7.24.11,4.36,3.05,7.73,6.47,10.11,9.42,6.57,23.16,12.06,34.74,9.09,6.69-1.72,13.02-10.62,4.34-14.68Z\"><\/path><path d=\"M287.44,470.82c7.6,1.04,15.58,1.22,23.23.55,1.42-.14,1.76,1.94.36,2.25-5.72,1.12-11.95,2.29-17.69,3.13-2.01.27-3.96.56-6.06.77-5.01.26-4.85-7.2.16-6.7h0Z\"><\/path><path d=\"M342.32,464.17c2.39-1.6,4.98-2.7,7.56-3.86,2.36-1.17,4.66-2.83,6.98-4.18.66-.38,1.5-.15,1.88.51.27.47.23,1.03-.05,1.45-1.83,2.62-4.21,4.57-7.16,5.88-.86.66-11.36,2.93-9.21.2h0Z\"><\/path><path d=\"M289.18,215.52c11.69,5.87,23.92,12.43,37.05,13.82,5.84.21,11.54-.97,17.33-2.43,9.28-2.52,18.59-6.05,26.82-10.96,8.19-5.17,16.13-11.62,23.76-17.72.98-.79,2.41-.63,3.19.35.73.9.65,2.19-.14,3-3.56,3.68-7.25,7.11-11.08,10.48-7.69,6.87-16.41,12.9-25.9,16.97-9.65,4.25-19.62,7.43-30.32,7.92-5.47.33-11.04-1.03-16.08-2.84-7.4-2.68-14.18-6.23-20.76-10.36-2.17-1.37-4.29-2.74-6.4-4.28-1.05-.77-1.28-2.24-.51-3.29.71-.97,2.02-1.24,3.04-.67h0Z\"><\/path><path d=\"M292.25,235.63c9.59,4.29,19.71,8.12,29.96,10.41,3.81.79,7.56,1.46,11.41,1.31,6.46-.25,12.78-1.79,18.95-3.89,7.4-2.52,14.57-5.81,21.29-9.76,11.13-6.99,20.62-16.3,30.86-24.77,2.1-1.78,5.04,1.15,3.16,3.26-3.64,4.04-7.42,7.9-11.34,11.65-5.97,5.59-12.16,11.31-19.32,15.52-12.67,7.18-26.81,11.85-41.39,12.89-4.91.25-9.94-.45-14.66-1.57-10.73-2.61-20.84-6.43-30.87-10.77-2.84-1.32-.96-5.57,1.96-4.27h0Z\"><\/path><path d=\"M256.56,289.66c-8.99-.93-25.85-4.76-29.44-14.14-1.48-4.13,0-9.09,3.09-12.17,3.3-3.18,8.46-2.86,12.36-1.3,1.9.82,5.86,2.03,4.34,4.85-.65,1.09-2.07,1.42-3.14.77-5.11-2.66-11.06-3.64-12.49,3.31-2.05,9.17,17.85,14.27,24.62,15.7,0,0,.66.12.66.12l.31.05c1.71.31,1.44,2.88-.31,2.81h0Z\"><\/path><path d=\"M256.67,286.44c.53-.67,1.34-1.93,1.83-2.65,3.88-6.43,8.32-13.76,8.22-21.41-.18-2.51-1.37-4.19-3.38-5.23-5.42-3.46-9.08,1.75-10.66,6.64-.33,1.25-1.65,1.99-2.89,1.6-2.94-1.08-.91-4.57-.14-6.48,2.39-5.58,8.15-9.52,14.17-6.71,2.66,1.13,5.17,3,6.3,5.74,3.65,9.47-4.7,21.74-10.17,29.06-.25.3-.77.97-1.04,1.26-1.32,1.75-3.7-.16-2.23-1.8h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInklusion\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t3-5 Kinder mit heil&shy;p\u00e4dagogischem F\u00f6rder&shy;bedarf\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33ef520 elementor-widget elementor-widget-n-accordion\" data-id=\"33ef520\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;multiple&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5440\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5440\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Minigruppe<\/div><div class=\"more\">Mehr \u00fcber die Minigruppe erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5440\" class=\"elementor-element elementor-element-5a269a8 e-con-full e-flex e-con e-child\" data-id=\"5a269a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7caee23 elementor-widget elementor-widget-text-editor\" data-id=\"7caee23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Minigruppe findet jeden Montag von 15 bis 17 Uhr in den R\u00e4umen des Kindergartens f\u00fcr Kinder ab ca. 2 Jahren statt. Das integrative Konzept spiegelt sich auch hier wieder und bietet Raum f\u00fcr Kinder mit und ohne heilp\u00e4dagogischem F\u00f6rderbedarf. Das gemeinsame Spielen und Entdecken steht dabei im Vordergrund. Die Kinder lernen im freien und angeleiteten Spiel einander kennen, singen Lieder, h\u00f6ren Geschichten und machen erste Erfahrungen mit Montessori-Material. In den Schulferien und an Feiertagen findet die Minigruppe nicht statt.<\/p><p>Anmeldungen sind nach Absprache m\u00f6glich. Melden Sie sich einfach \u00fcber unser Kontaktformular oder unter:<\/p><p>Tel: 0921 \u2013 57938<\/p><p>Mail: <a href=\"mailto:info@integrativer-kiga-bayreuth.de\">info@integrativer-kiga-bayreuth.de<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8be8623 e-flex e-con-boxed e-con e-parent\" data-id=\"8be8623\" data-element_type=\"container\" data-e-type=\"container\" id=\"tagesablauf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3044b69 e-con-full e-flex e-con e-child\" data-id=\"3044b69\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d567520 elementor-widget elementor-widget-heading\" data-id=\"d567520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tages&shy;ablauf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee1f088 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ee1f088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M66.83,5.78c-1.71-3.95-5.68-7.3-10.07-5.06-4.6,2.34-7,8.27-8.02,13.01-1.48,6.9-.8,14.38.74,21.21.05.2.38.16.36-.05-.61-10.2-2.73-21.84,4.51-30.43,1.71-2.03,4.22-3.79,6.95-2.7,2.39.95,3.82,3.45,4.59,5.78.86,2.57,1.16,5.6.5,8.26-.11.43-.21,1.11-.5,1.44-1.28,1.48-2.53.07-3.16-.8-1.03-1.43-1.01-2.96-.75-4.63.13-.86-1.15-1.63-1.56-.66-1.3,3.02.97,9.91,5.31,8.19,1.96-.78,2.27-3.34,2.43-5.15.27-2.85-.2-5.8-1.34-8.43Z\"><\/path><path d=\"M47.28,22.99c-.71-3.61-1.54-7.24-2.96-10.64-2.36-5.64-7.02-11-13.39-11.87-5.92-.81-11.68,2.89-12.54,8.94-.64,4.55,1.5,12.67,7.78,11.07,2.47-.63,4.47-3.48,3.29-5.97-1.06-2.25-3.9-2.86-5.8-1.39-.83.64.26,2.05,1.13,1.47,2.1-1.41,4.28,1.27,2.62,3.24-1.42,1.69-3.86,1.23-5.34-.09-2.28-2.04-2.5-5.74-1.97-8.57,1.16-6.28,8.29-8.52,13.69-6.22,11.73,4.99,12.35,21.29,14.27,31.95.02.14.22.09.23-.03.42-3.92-.25-8.03-1-11.87Z\"><\/path><path d=\"M46.38,34.27c-1.78-.47-3.17.68-3.74,2.18-.63,1.32-.61,2.94.12,4.28,1.15,2.14,3.88,1.68,4.86-.38.86-1.77,1.19-5.44-1.24-6.09ZM46.29,39.31c-.17.67-.73,1.7-1.62,1.49-.66-.16-1.02-1.16-1.15-1.72-.06-.25-.08-.5-.1-.75.57-.75,1.09-1.89,1.92-2.15,1.51-.47,1.16,2.31.95,3.13Z\"><\/path><path d=\"M55.57,32.73c-.9-.7-2.14-.82-3.16-.28-.95.51-1.63,1.7-1,2.7.03.05.07.09.11.13-.04,1.74,1.21,3.46,2.87,4.14.22.09.49-.02.65-.17,1.78-1.68,2.82-4.73.52-6.52ZM54.34,37.98c-1.09-.49-1.77-1.53-2-2.68,0,0,.01,0,.02-.01.57-.69,1.34-1.58,2.21-.71.96.94.44,2.42-.23,3.41Z\"><\/path><path d=\"M61.69,77.48c-1.45-7.31-3.01-14.6-5.19-21.73-1.12-3.68-2.41-7.32-3.94-10.85-.72-1.66-2.51-4.03-4.16-1.78-.22.29-.16.62.03.86-.93,6.35-.03,12.96,1.44,19.17,1.57,6.63,4.1,13.16,7.61,19.01.83,1.38,2.57,3.76,4.35,2.13,1.63-1.49.19-5.12-.15-6.81ZM58.88,81.8c-1.01-1.08-1.74-3.08-2.4-4.39-.77-1.55-1.49-3.13-2.14-4.74-1.2-2.97-2.19-6.02-2.98-9.13-1.6-6.33-1.92-12.72-2.37-19.2.24.05.5,0,.7-.22.68-.76,2.77,4.67,2.81,4.77.66,1.63,1.26,3.27,1.83,4.94,1.05,3.07,1.95,6.19,2.76,9.33.87,3.42,1.64,6.86,2.36,10.31.33,1.59.65,3.19.97,4.78.16.8.34,1.59.47,2.39.13.55.22,1.12.25,1.69-1.15.44-1.9.26-2.26-.54Z\"><\/path><path d=\"M91.09,36.7c.21-5.69-3.52-10.57-9.35-10.92-5.98-.35-12.22,2.96-16.85,6.44-5.09,3.82-10.23,9.53-11.92,15.81-.07.24.26.37.39.16,1.82-2.98,3.35-6,5.63-8.67,2.23-2.63,4.77-5.02,7.61-6.98,5.07-3.49,14.42-8.34,20.09-3.55,6.43,5.44,1.54,15.35-2.63,20.54-2.31,2.87-5.09,5.29-8.19,7.18-3.31.4-6.51,1.77-9.11,3.93-.62.52.05,1.5.76,1.3,3.04-.83,5.93-2.08,8.6-3.69,2.33-.27,4.71,0,6.95.86,4.93,1.9,6.94,7.27,5.2,12.15-1.72,4.8-6.95,7.59-11.85,7.66-5.5.08-10.73-2.7-14.89-6.09-1.14-.92-2.76.69-1.62,1.62,5.14,4.14,11.27,7.03,18,6.01,5.53-.83,10.88-4.17,12.23-9.91,1.23-5.2-1.02-10.57-6.02-12.71-1.77-.76-3.63-1.16-5.5-1.24,1.51-1.1,2.93-2.31,4.24-3.65,4.18-4.23,8.01-10.15,8.23-16.26Z\"><\/path><path d=\"M57.57,83.59c-.05,4.66-1.48,9.63-5.26,12.65-3.88,3.09-9.71,3.45-13.17-.47-3.51-3.98-3.36-9.65-2.05-14.47.07-.27.15-.55.23-.83,3.77-2.39,6.82-5.92,8.59-10.02.23-.53-.02-1.23-.69-1.21-5.27.15-7.78,5.51-9.19,9.99-6.47,3.88-14.77,4.12-20.78-1.94-4.18-4.21-6.05-10.38-3.86-16.03,2.28-5.9,8.15-11.6,13.62-14.63,8.1-4.47,16.48-.49,23.97,3.24.45.23.8-.38.39-.68-6.45-4.6-14.87-8.13-22.75-5.11-3.38,1.3-6.28,3.57-8.88,6.03-2.76,2.61-5.43,5.5-7.14,8.93-6.1,12.2,5.18,26.2,18.28,24.52,2.28-.29,4.46-.98,6.49-1.99-1.26,5.25-1.17,11.1,2.71,15.26,3.65,3.92,9.54,4.02,13.91,1.22,4.86-3.12,6.74-8.97,6.9-14.47.02-.85-1.31-.85-1.31,0ZM43.83,71.07c-1.39,2.6-3.33,4.87-5.61,6.66,1.1-2.92,2.8-5.85,5.61-6.66Z\"><\/path><path d=\"M84.88,37.57c-.44-4.26-6.43-3.07-9.05-2.03-3.85,1.53-7.06,4.68-8.54,8.56-.69,1.81-1.19,4.07-.19,5.88.9,1.63,2.65,2.32,4.38,1.68,3.53-1.29,7.57-6.21,8.03-9.96.22-1.78-.89-2.93-2.69-2.78-2.11.19-3.8,2.03-4.88,3.69-.79,1.21-2.35,3.99-.74,5.19,1.63,1.22,2.54-1.11,3.59-1.85.7-.49.09-1.58-.68-1.16-.45.24-.83.8-1.24.99-.24.5-.46.48-.66-.07.19-.6.43-1.17.74-1.71.61-1.11,2.93-4.36,4.6-3.52,2.39,1.21-5.07,10.58-7.82,9.9-2.92-.72-1.45-5.16-.61-6.87.7-1.42,1.65-2.7,2.79-3.8,2.29-2.21,6.5-4.54,9.84-3.76,5.36,1.27-2.36,9.95-3.84,11.63-2.15,2.43-6.09,7.39-9.85,6.53-4.14-.95-2.92-7.01-2.07-9.81,1.22-4.09,3.69-7.99,8.12-8.96.28-.06.16-.49-.12-.44-4.69.91-7.55,4.8-8.89,9.15-.93,3.04-1.88,7.91,1.09,10.22,3.79,2.96,8.43-1.81,10.9-4.33,1.79-1.83,3.42-3.8,4.88-5.89,1.25-1.79,3.16-4.17,2.92-6.52Z\"><\/path><path d=\"M38.71,57.65c-2.6-3.14-8.65-2.96-12.12-1.87-3.45,1.08-7.14,4.21-6.88,8.17.28,4.32,5.56,4.29,8.57,3.07,2.62-1.06,7.55-5.81,2.62-7.57-2.78-.99-9.5,2.4-6.47,5.76.55.6,1.47-.17,1.1-.85-1.69-3.08,8.52-4.94,4.52-.45-1.25,1.41-3.57,2.14-5.37,2.16-2.98.03-3.95-2.36-2.65-4.8.83-1.56,2.29-2.76,3.88-3.48,2.96-1.35,7.71-1.64,10.6.08,4.11,2.46-1.65,6.97-3.9,8.45-2.6,1.7-5.71,3.55-8.72,4.36-4.65,1.26-7.59-2.92-6.51-7.21,1.73-6.84,10.51-11.51,17.15-10.73.29.03.35-.45.07-.51-4.65-.98-9.05.48-12.76,3.38-3.1,2.41-6.15,6.09-5.89,10.27.23,3.76,3.17,6.71,7.01,6.32,2.19-.22,4.25-1.36,6.19-2.33,2.08-1.04,4.14-2.14,5.98-3.57,2.38-1.84,6.14-5.53,3.56-8.65Z\"><\/path><path d=\"M46.56,83.59c-3.98-.21-4,8.82.02,7,.4-.18.79-.49,1.12-.87-.18.65-.49,1.25-.97,1.7-2.1,1.98-3.19-2.06-3.26-3.41-.1-1.9.52-3.74,1.8-5.15.19-.21-.1-.5-.31-.31-1.84,1.69-2.76,4.02-2.39,6.52.24,1.58,1.28,4.5,3.34,4.2,3.76-.53,4.92-9.46.64-9.69ZM45.23,88.52c-.04-.26-.05-.53-.04-.79.26.27.77.19.91-.23.69,1.24.4,1.58-.86,1.02Z\"><\/path><path d=\"M81.17,65.02c-2.38-1.86-6.61-.49-6.65,2.76-1.01,3.09,2.09,5.87,5.22,4.67,2.9-1.11,4.04-5.39,1.43-7.42ZM76.29,67.23c.34-1.02,1.5-1.49,2.5-1.44.55.02,1.01.22,1.38.51-.04-.02-.09-.04-.14-.07-1.38-.56-2.96,0-3.16,1.59-.05.43.6.69.88.36.49-.6,1.8-.74,2.11.11.47,1.3-1.31,2.14-2.3,1.67-.95-.45-1.61-1.71-1.27-2.74ZM75.16,69.94c.7,1.07,1.89,1.8,3.09,1.86-1.26,0-2.49-.75-3.09-1.86Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be66508 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"be66508\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_T.png\" class=\"attachment-large size-large wp-image-232\" alt=\"Illustrierter Buchstabe T in Gelb mit zwei Kindern bei Regen und Sonnenschein als Grafikelement des Integrativen Montessori Kindergartens Bayreuth\" srcset=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_T.png 500w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_T-300x300.png 300w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_T-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-562bcdc e-con-full e-flex e-con e-child\" data-id=\"562bcdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9900186 elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"9900186\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Anfang&quot;,&quot;_id&quot;:&quot;46bad88&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;c134ed1&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;e13a821&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;1cc4229&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;6cb06c7&quot;},{&quot;slide_title&quot;:&quot;Ende&quot;,&quot;_id&quot;:&quot;4b1b781&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-161933b e-flex e-con-boxed e-con e-child\" data-id=\"161933b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-680d59c e-con-full e-flex e-con e-child\" data-id=\"680d59c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c48cd17 e-con-full e-flex e-con e-child\" data-id=\"c48cd17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0abb9bc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0abb9bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M19.03,89.23C-1.67,72.51-5.89,42.69,9.71,21.06,17.26,10.03,27.75,3.21,40.94.81c34.25-6.16,64.11,23.86,57.96,58.08-4.48,26.27-30.17,44.73-56.49,40.51-6.32-.96-12.44-3.15-17.89-6.44-.27-.16-.36-.52-.2-.79.16-.27.51-.36.78-.2,10.8,6.2,23.96,7.96,35.95,4.92,24.91-6.04,41.02-31.65,35.59-56.72C89.83,7.58,52.29-8.48,24,9.06c-5.26,3.28-10.26,7.2-13.99,12.22C1.08,33.27-1.65,49.46,2.68,63.74c2.56,8.61,7.59,16.46,14.36,22.36.6.6,2.07,1.68,2.72,2.23.58.47-.12,1.38-.73.9h0Z\"><\/path><path d=\"M44.45,47.52c-.49-3.66-.74-7.36-.93-11.04-.32-6.31-1.62-13.58-.39-19.8.04-.18.33-.28.4-.06,1.78,5.88,1.22,12.87,1.58,18.98.2,3.47.43,6.95.84,10.4.41,3.39,1.58,6.86,1.63,10.25,0,.57-.68.81-.98.28-1.48-2.65-1.75-6.02-2.15-9Z\"><\/path><path d=\"M48.09,54.03c4.12-1.4,9.33-.85,13.65-.78,5.23.08,10.44.45,15.62,1.15,1,.13.81,1.71-.2,1.57-.79-.03-1.58-.07-2.37-.1-.07,0-.13-.02-.18-.06-3.96-.23-7.93-.39-11.89-.39-4.62,0-9.88,1.05-14.4.23-.76-.14-1.08-1.34-.23-1.62Z\"><\/path><path d=\"M51.34,88.61c0-2.34-.25-4.66-.15-7,0-.1.15-.12.18-.03.73,2.25.84,4.64.85,7.01.01,2.03.21,4.66-.6,6.53-.11.26-.46.22-.51-.07-.33-2.04.22-4.36.23-6.45Z\"><\/path><path d=\"M67.14,14.26c1.04-1.37,1.89-2.88,2.99-4.2.05-.06.15,0,.13.07-.5,1.7-1.48,3.16-2.52,4.57-.89,1.21-1.92,2.85-3.29,3.55-.19.1-.41-.1-.31-.3.68-1.37,2.07-2.46,3-3.69Z\"><\/path><path d=\"M16.53,69.75c1.29-1.15,2.41-2.45,3.75-3.54.06-.05.15.03.11.1-.82,1.57-2.07,2.81-3.36,3.99-1.11,1.01-2.44,2.43-3.91,2.84-.21.06-.38-.18-.25-.35.93-1.21,2.51-2.01,3.66-3.03Z\"><\/path><path d=\"M49.56,3.37c.92,1.8.48,4.26.26,6.14-.26,2.2-.73,4.41-1.81,6.46-.08.16-.38.07-.36-.09.24-2.08.71-4.13.87-6.21.16-2-.42-4.3.15-6.23.1-.34.72-.42.9-.07Z\"><\/path><path d=\"M74.34,86.22c-1.56-.44-2.72-2.04-3.67-3.21-1.11-1.36-2.11-2.85-2.67-4.61-.04-.14.18-.27.26-.17,1.05,1.28,1.96,2.68,3.07,3.92,1.06,1.19,2.7,2.1,3.49,3.5.13.24-.17.66-.48.57Z\"><\/path><path d=\"M11.31,27.26c1.61-.12,3.25.98,4.55,1.75,1.51.89,2.96,1.95,4.09,3.41.09.11-.07.31-.19.25-1.43-.84-2.77-1.84-4.23-2.62-1.4-.75-3.26-1.04-4.48-2.09-.21-.18-.07-.68.25-.7Z\"><\/path><path d=\"M83.38,46.86c1.57-.63,3.43-.47,5.25-.5,1.8-.03,3.68-.1,5.48.06.13,0,.26.02.39.04.01,0,.02,0,.03,0,0,0,0,0,0,0,.07.01.14.02.22.03.68.13.72.86.02.99-1.86.35-3.83.42-5.76.53-1.75.1-3.76.43-5.38-.07-.62-.19-.95-.81-.25-1.09Z\"><\/path><path d=\"M27.04,11c1.05.61,1.92,1.68,2.85,2.66.92.97,1.9,1.96,2.74,3,.06.07.12.15.18.23,0,0,.01.01.02.02,0,0,0,0,0,0,.03.04.06.08.09.13.29.41,0,.72-.4.39-1.08-.88-2.1-1.92-3.12-2.92-.92-.91-2.07-1.88-2.69-2.95-.23-.41-.15-.82.32-.55Z\"><\/path><path d=\"M34.53,80.06c-.03,1.22-.55,2.5-.95,3.78-.4,1.27-.8,2.61-1.3,3.84-.03.09-.07.18-.11.27,0,0,0,.02,0,.02,0,0,0,0,0,0-.02.05-.04.1-.07.15-.22.45-.62.35-.53-.16.25-1.37.66-2.77,1.05-4.15.35-1.25.64-2.72,1.28-3.78.25-.4.65-.53.64.01Z\"><\/path><path d=\"M89.07,68.39c-1.19-.24-2.36-.97-3.56-1.59-1.19-.62-2.43-1.24-3.56-1.95-.08-.05-.16-.1-.25-.16,0,0-.02,0-.02-.01,0,0,0,0,0,0-.04-.03-.09-.06-.13-.09-.41-.3-.24-.67.25-.49,1.31.48,2.61,1.13,3.9,1.75,1.17.56,2.57,1.1,3.5,1.92.35.31.41.73-.12.63Z\"><\/path><path d=\"M86.81,28.07c-.85.87-2.1,1.45-3.28,2.11-1.17.66-2.37,1.36-3.58,1.92-.08.04-.17.08-.27.12,0,0-.02,0-.02.01,0,0,0,0,0,0-.05.02-.1.04-.15.06-.47.18-.7-.17-.28-.48,1.12-.83,2.37-1.57,3.6-2.31,1.11-.67,2.33-1.55,3.52-1.88.45-.13.84.06.46.44Z\"><\/path><path d=\"M15.11,50.94c-1.53.72-3.4.66-5.22.79-1.8.13-3.67.3-5.47.24-.13,0-.26,0-.4-.02-.01,0-.02,0-.03,0,0,0,0,0,0,0-.07,0-.14-.01-.22-.02-.68-.09-.76-.82-.07-.99,1.84-.45,3.8-.63,5.72-.85,1.74-.2,3.73-.64,5.38-.22.63.16,1,.76.31,1.08Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a192b1 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0a192b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59eb942 e-con-full e-flex e-con e-child\" data-id=\"59eb942\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c6a3b32 e-con-full card_yellow e-flex e-con e-child\" data-id=\"c6a3b32\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-883c392 elementor-widget elementor-widget-heading\" data-id=\"883c392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">7:00 \u2013 8:30 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3bc00d elementor-widget elementor-widget-heading\" data-id=\"f3bc00d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bringzeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ece34f elementor-widget elementor-widget-text-editor\" data-id=\"4ece34f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Eltern verabschieden sich von ihrem Kind und bringen es in den Gruppenraum. Wir legen Wert darauf, jedes Kind am Morgen pers\u00f6nlich zu begr\u00fc\u00dfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5dd78d e-flex e-con-boxed e-con e-child\" data-id=\"d5dd78d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6b7287e e-con-full e-flex e-con e-child\" data-id=\"6b7287e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b70fb8 e-con-full e-flex e-con e-child\" data-id=\"7b70fb8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73a4c70 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"73a4c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M36.25,57.26c4.46,3.27,8.65,6.98,12.86,10.57,4.09,3.49,8.35,7.14,11.44,11.57.1.14-.09.29-.22.22-4.67-2.52-8.78-6.13-12.86-9.51-4.29-3.56-8.79-6.9-13.02-10.53-1.26-1.08.43-3.33,1.8-2.33Z\"><\/path><path d=\"M59.57,77.43c6.63-9.46,13.07-19.04,19.55-28.6,6.48-9.55,12.75-19.31,19.79-28.45.27-.35.84-.05.61.35-5.87,9.92-12.6,19.34-19.05,28.89-6.46,9.56-12.97,19.09-19.3,28.75-.66,1-2.29.04-1.6-.94Z\"><\/path><path d=\"M35.85,55.57c10.67-5.21,21.11-10.92,31.47-16.7,10.36-5.78,20.45-12.08,30.85-17.78.54-.3.98.48.48.81-9.8,6.65-20.22,12.5-30.43,18.5-10.23,6.01-20.59,11.81-30.83,17.8-1.71,1-3.28-1.78-1.54-2.63Z\"><\/path><path d=\"M21.4,38.32c2.37-1.6,6.08-1.79,8.86-2.33,3.39-.66,6.74-1.47,10.1-2.25,6.56-1.51,13.14-2.94,19.69-4.47,13.11-3.06,26.18-6.46,39.45-8.68.5-.08.72.62.21.78-12.84,3.97-26.04,6.78-39.11,9.92-6.38,1.53-12.73,3.17-19.11,4.71-3.35.81-6.71,1.57-10.03,2.5-2.84.8-6.52,2.41-9.46,2.05-1.16-.15-1.66-1.53-.61-2.23Z\"><\/path><path d=\"M1.35,23.2c16.59-.07,33.16-.68,49.73-1.2,8.13-.26,16.25-.5,24.38-.75,4.23-.13,8.45-.25,12.68-.38,3.38-.1,7.61-.87,10.78.5.07.03.07.15,0,.19-3.07,1.57-7.42,1.08-10.78,1.19-4.07.14-8.13.28-12.19.42-8.29.28-16.58.56-24.87.84-16.59.54-33.17,1-49.73,1.99-1.79.11-1.82-2.79,0-2.8Z\"><\/path><path d=\"M1.7,23.49c2.18.8,4.05,2.39,5.96,3.69,1.97,1.34,3.94,2.68,5.91,4.03,3.91,2.67,7.68,5.35,11.1,8.63.46.44-.12,1.05-.64.82-4.4-1.97-8.35-4.5-12.35-7.16l-5.56-3.7c-1.91-1.27-4.16-2.4-5.71-4.1-.82-.9-.04-2.69,1.28-2.21Z\"><\/path><path d=\"M20.4,78.74c1.6-4.11,4.29-7.88,6.8-11.48,2.53-3.63,5.2-7.42,8.33-10.56.69-.69,2.03.26,1.39,1.08-2.7,3.49-5.65,6.76-8.23,10.35-2.58,3.58-4.67,7.52-7.33,11.02-.32.42-1.2.2-.96-.41Z\"><\/path><path d=\"M19.94,58.27c.14-3.53.3-7.06.44-10.59.13-3.13-.27-6.88.7-9.87.27-.82,1.59-.94,1.79,0,.68,3.08-.05,6.73-.22,9.87-.2,3.69-.39,7.38-.59,11.07-.37,6.91-.67,13.92-1.85,20.75-.04.25-.41.17-.42-.06-.53-7.02-.14-14.14.15-21.18Z\"><\/path><path d=\"M19.46,79.02c3.53-3.01,7.82-5.2,11.86-7.45,4.11-2.29,8.3-4.61,12.67-6.38,1.21-.49,2.05,1.53.89,2.12-4.27,2.17-8.69,4.03-12.96,6.2-4.01,2.04-7.88,4.51-12.04,6.23-.4.16-.74-.45-.42-.72Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e01926 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e01926\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2bb2f8c e-con-full e-flex e-con e-child\" data-id=\"2bb2f8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-822d823 e-con-full card_yellow e-flex e-con e-child\" data-id=\"822d823\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3534f2 elementor-widget elementor-widget-heading\" data-id=\"a3534f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">bis 9:30 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-455858c elementor-widget elementor-widget-heading\" data-id=\"455858c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Freizeitspiel<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c54a6 elementor-widget elementor-widget-text-editor\" data-id=\"d7c54a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das eigene Tun des Kindes steht im Vordergrund. Die Kinder w\u00e4hlen ihre T\u00e4tigkeiten, entsprechend ihrer individuellen Bed\u00fcrfnissen und Interessen aus. Sie kn\u00fcpfen Kontakte zu ihren Spielkameraden und lernen, sich mit ihnen auseinander zu setzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c7db14 e-flex e-con-boxed e-con e-child\" data-id=\"0c7db14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26d462c e-con-full e-flex e-con e-child\" data-id=\"26d462c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0e9ba84 e-con-full e-flex e-con e-child\" data-id=\"0e9ba84\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0956584 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0956584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M40.94,37.54c-.9-4.19-2.66-8.11-4.37-12.03-1.63-3.72-2.93-8.46-5.51-11.61-.83-1.01-2.14.12-1.97,1.14.64,3.82,3.3,7.79,4.93,11.3,1.86,3.96,3.67,7.96,6.29,11.48.23.31.72.13.64-.27h-.01Z\"><\/path><path d=\"M59.39,5.94c-4.84,2.54-9.81,4.65-14.85,6.73-2.29.95-4.61,1.87-6.93,2.74-2.21.83-4.71,1.34-6.67,2.67-.66.45-.48,1.65.43,1.61,2.53-.12,5-1.36,7.33-2.28,2.24-.88,4.45-1.82,6.63-2.84,4.98-2.31,9.72-5.19,14.36-8.11.33-.21.04-.7-.31-.52h0Z\"><\/path><path d=\"M69.41,1.52C67.1-.22,63.1-.09,60.34.11c-3.12.22-6.2.97-9.06,2.25-3.26,1.46-10.98,6.49-5.98,10.51.28.23.64-.05.49-.38-2.51-5.63,6.18-8.9,10.15-9.9,2.2-.56,4.46-.81,6.74-.75,2.16.05,4.34.83,6.47.59.5-.05.65-.61.25-.92h.01Z\"><\/path><path d=\"M68.39,1.05c-2.81,3.66-4.02,7.98-7.66,11.14-1.82,1.58-3.98,2.81-6.33,3.42-1.65.43-8.73,1.36-8.46-1.99,0-.15-.23-.21-.29-.08-.68,1.5.43,2.63,1.79,3.29,2.87,1.39,6.72.76,9.54-.34,5.73-2.25,11.75-8.64,13.07-14.74.22-1.06-1.05-1.49-1.66-.7h0Z\"><\/path><path d=\"M58.01,80.99c-2.51,3.01-4.09,6.64-6.67,9.63-2.91,3.35-6.45,5.67-10.84,6.57-9.14,1.88-18.11-2.38-24.89-8.25-6.74-5.84-11.17-13.21-10.96-22.33.2-8.51,3.86-17.21,9.98-23.17,7.1-6.92,17.91-9.11,26.72-4.02.83.48,1.44-.69.73-1.24-7.34-5.62-17.68-4.72-25.12.35-7.76,5.29-12.78,14.3-14.24,23.47-1.57,9.87,1.48,18.96,8.48,26.05,6.77,6.87,16.02,12.39,25.97,11.92,10.31-.49,19.21-8.38,22.71-17.9.38-1.03-1.17-1.94-1.87-1.09h0Z\"><\/path><path d=\"M89.68,30.89c-5.71-7.11-15.27-14.04-24.85-12.07-9.85,2.03-20.09,10.14-23.56,19.67-.21.6.64.87.96.4,5.13-7.35,10.83-13.65,19.47-16.87,5.16-1.93,9.87-1.66,14.78.87,3.62,1.86,6.87,4.35,9.65,7.32,11.92,12.7,12.62,33.57-.54,45.77-7.45,6.9-16.88,8.55-26.6,6.86-1.88-.32-2.7,2.34-.8,2.9,8.69,2.54,19.14-.39,26.27-5.62,7.52-5.52,12.03-14.16,13.03-23.35,1.01-9.32-1.95-18.57-7.8-25.87h-.01Z\"><\/path><path d=\"M59.48,88.15c-.07-.6-.4-1.28-1.07-1.4-.27-.05-.51-.1-.77,0-.58.21-1.11.73-1.07,1.4.13,2.42.33,5.59,1.64,7.69.23.39.73.26.88-.11.92-2.23.65-5.24.39-7.58h0Z\"><\/path><path d=\"M63.88,92.51c-.68-1.1-1.24-2.16-2.08-3.16-.87-1.04-1.73-2.09-2.78-2.97-1.42-1.18-3.3.64-2.05,2.04.91,1.02,2,1.84,3.06,2.68,1.04.81,2.13,1.35,3.26,2,.36.21.81-.21.58-.58h0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-954eeb2 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"954eeb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c626d8 e-con-full e-flex e-con e-child\" data-id=\"5c626d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92b5aeb e-con-full card_yellow e-flex e-con e-child\" data-id=\"92b5aeb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-204793d elementor-widget elementor-widget-heading\" data-id=\"204793d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">9:30 \u2013 11:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f836b9 elementor-widget elementor-widget-heading\" data-id=\"7f836b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Morgenkreis &amp; Brotzeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60456c7 elementor-widget elementor-widget-text-editor\" data-id=\"60456c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>T\u00e4gliches Ritual aus Kinder z\u00e4hlen, Datum und Wetter besprechen, gemeinsames Kreisspiel.<br \/>Anschlie\u00dfend treffen wir uns an einer langen Tafel. Singen, Beten und Essen dann gemeinsam.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-119b95d e-flex e-con-boxed e-con e-child\" data-id=\"119b95d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9fe1a4d e-con-full e-flex e-con e-child\" data-id=\"9fe1a4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-34f9857 e-con-full e-flex e-con e-child\" data-id=\"34f9857\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e212ee9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e212ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_2\" data-name=\"Ebene 2\" viewBox=\"0 0 500 500\"><path d=\"M212.44,226.69s.03-7.3.03-7.3c-.09-.85.23-5.02-.26-5.48-1.07-1.02-2.71-1.07-4.3-1.23-1.9-.12-3.77-.05-5.47.92-1.64.86-3.43,2.53-5.62,4.06-2.18,1.55-4.76,2.88-7.4,3.65-17.06,5.18-34.62-5.04-36.39-23.21-1.19-11.27,5.53-22.72,15.95-27.26,7.7-3.41,16.75-3.19,24.57-.22,4.22,1.58,6.25,4.41,10.11,4.6,1.5,0,3.21-.13,4.62-.36,1.16-.24,2.23-.38,2.85-.95.01-.04-.2.09-.34.37-.09.16-.17.42-.19.54-.57-12.89-1.58-25.78-1.92-38.67-.34-9.73-.18-19.47-.17-29.2,0,0,6.96,6.96,6.96,6.96-51.52-.3-125.69-1.87-177.93-2.9,0,0,4.06-4.06,4.06-4.06-.29,26.42-1.61,62.97-1.38,88.97.11,29.65,1.72,59.31,1.45,88.97,0,0-4.13-4.13-4.13-4.13l67.87-.24c1.06-.04,1.98.39,2.79.98,5.12,3.83,6.85,10.54,6.33,16.63-.25,3.78-2.76,7.44-4.47,10.23-2.04,3.58-2.54,7.22-2.59,11.52-.04,2.68.41,5.15,1.36,7.54,2.78,7.2,10.23,12.2,17.95,11.97,9.74.04,18.4-8.36,18.64-18.09.12-4.73-.57-9.23-3.19-13.03-2.48-3.43-6.12-7.35-6.52-12.18-.69-6.37.97-15.75,7.71-15.82,0,0,72.05.13,72.05.13,0,0-4.48,4.33-4.48,4.33.71-12.06,1.68-25.14,1.59-37.16,0,0,0-12.44,0-12.44-.02-1.6,1.28-2.92,2.89-2.92,1.53,0,2.78,1.2,2.88,2.7l.79,12.48c.54,8.29.77,16.81.78,25.13,0,0,.03,12.51.03,12.51,0,2.39-1.93,4.33-4.31,4.33-.75.04-71.88.12-72.6.12.87.1,1.93-.17,2.48-.8-.37.78-.69,3.08-.67,4.58-.12,2.54.42,3.68,2.06,5.85,2,2.51,4.45,5.79,5.65,9.05,3.98,10.66,2.42,23.13-5.5,31.44-10.51,11.57-29.68,11.87-40.52.57-5.3-5.28-8.32-12.97-8.07-20.4,0-5.13,1.06-11.19,3.87-15.83,1.45-2.62,3.08-4.2,3.42-6.8.23-2.94-.33-6.56-2.65-8.55-.02-.01,0,0,0,0h0s.11.07.11.07c0,0,2.19.59,2.19.59,0,0-67.87-.24-67.87-.24-2.28,0-4.14-1.85-4.13-4.13-.27-29.66,1.33-59.31,1.45-88.97-.15-25.88-.72-62.76-1.38-88.97-.05-2.26,1.81-4.11,4.06-4.06,52.55-.6,126.15-3,177.93-2.89,3.84,0,6.96,3.11,6.96,6.96,0,9.73.16,19.47-.18,29.2-.34,12.78-1.34,25.55-1.91,38.33-.02,1.29-.21,2.56-.8,3.76-3.05,5.97-10.73,5.95-16.36,5.8-2.39-.15-5.11-1.02-7.04-2.19-2.58-1.54-4.11-2.75-5.92-3.54-5.55-2.29-12.55-2.74-18.17-.45-7.7,3.11-12.81,11.37-12.15,19.7,1.19,14.18,14.64,21.57,27.79,17.86,6.09-1.35,9.67-7.64,16.3-8.61,6.37-.8,14.98.73,14.46,8.93,0,0,0,3.65,0,3.65l.03,7.3c-.11,4.02-5.95,3.99-6.04,0h0Z\"><\/path><path d=\"M220.93,284.54c1.16,23.8,1.46,48.06,1.52,71.9,0,0,0,.05,0,.05,0-.02,0,.13,0-.07.02-.21-.05-.5-.06-.71-.09-.95-.78-2.33-1.3-2.78-.6-.57-.8-.62-.74-.59,1.08.37,2.72.45,4.06.48.77.02,1.32-.04,2.03-.34,2.7-1.39,4.82-3.75,8.43-5.54,10.45-5.21,23.91-4.47,33.23,2.6,22.39,17.06,11.2,52.58-17.17,52.83-6.55.16-14.12-1.69-19.36-5.54-1.95-1.22-3.05-1.9-5.22-1.79-2.19.04-4.54.53-6.12,2.01-.14.14-.22.22-.31.34,0,0-.02.02,0,0l.02-.03s.09-.15.09-.15c0,0,.71-2.64.71-2.64l.06,67.89-5.34-5.34c56.76-.11,121.23,0,177.93,1.26,0,0-4.07,4.07-4.07,4.07.27-14.83.45-29.66.47-44.48.29-14.84-.9-29.66-1.35-44.48-.15-25.25-.37-63.37-.4-88.97,0,0,5.35,5.35,5.35,5.35-.11,0-67.88.23-67.98.23-1.49.02-2.74-.67-3.84-1.55-3.4-2.69-5.47-7.03-6.12-11.13-.78-4.17-.29-9.22,1.9-12.82,1.01-1.8,1.89-3.02,2.5-4.13,1.96-3.43,2.41-6.77,2.48-10.96.08-20.32-27.27-25.6-34.72-6.63-1.64,4.49-1.28,10.32.29,14.56,1.02,2.62,2.44,4.19,4.3,6.66,1.72,2.1,3.75,5.9,4.01,9.09.31,5.09.18,11.36-4.05,15.18-1.5,1.3-3.88,2.11-5.92,1.62-8.75-1.83-18.18-2.97-27.08-2.66-9.3.42-18.89,1.36-28.13,2.6-7.14.75-8.64-9.55-1.52-10.83,14.64-1.91,29.61-3.96,44.33-2.37,5.07.53,9.83,1.23,14.88,2.3-.43-.07-1.06-.17-1.49-.13-1.05.04-2.2.53-2.75,1.33.5-1.24.66-4.08.52-5.66-.5-2.9-3.1-4.87-4.86-7.71-3.9-5.53-5.21-12.79-4.93-19.23.78-19.96,21.76-33.37,40.22-25.67,11,4.36,18.51,15.85,18.11,27.67-.04,3.5-.39,7.2-1.59,10.99-.84,3.14-3.34,6.96-4.82,9.37-.81,1.51-.91,2.28-.84,3.89.05,1.94.55,4,1.71,5.43.17.19.32.38.48.5,0,0-.21-.13-.21-.13l-2.8-.75s67.87.23,67.91.23c2.95,0,5.33,2.41,5.32,5.35,0,0-.15,44.48-.15,44.48-.19,21.56.23,45.31-1.23,66.72-.84,22.24-.16,44.48.1,66.72.04,2.26-1.81,4.11-4.07,4.07-56.69,1.28-121.19,1.34-177.94,1.26-2.95,0-5.33-2.39-5.33-5.34,0,0,.07-67.89.07-67.89-.04-1.2.39-2.27,1.06-3.19,4.85-6.56,14.81-8.52,22.17-5.59,3.31,1.44,5.95,3.8,8.9,4.72,6.85,2.12,15.46,1.62,20.89-3.64,8.41-7.49,7.59-21.67-1.97-27.76-5.82-3.85-13.98-3.71-19.93-.43-2.47,1.45-5.52,4.63-8.88,6.23-2.06,1.05-4.53,1.69-6.86,1.78-3.42.11-6.72-.08-10.13-1.26-3.5-1.14-7.23-4.79-6.97-9.17.08-23.79.35-47.99,1.52-71.74.54-6.9,10.39-6.87,10.93,0h0Z\"><\/path><path d=\"M311.93,196.9c-.25-.14-1-.35-1.3-.18,1.72-1.18,3.15-3.92,4.06-5.92.61-1.76.54-3.12.18-5.23-.6-3.17-1.27-6.92-.86-10.31.39-4.16,1.85-7.81,3.57-11.31,1.47-2.76,3.37-5.4,5.7-7.49,22.77-20.01,55.48,5.29,41.66,32.31-2.27,4.45-5.74,9.03-10.16,11.78-2.53,1.7-4.98,2.55-6.56,4.92-1.27,2.02-2.31,4.84-2.25,7.26,0,1.07.25,2.25.63,3.05,0,0-1.11-1.01-1.11-1.01.01,0,60.3,31.16,60.31,31.17,0,0-3.51,1.13-3.51,1.13,22.88-45.9,48.44-98.68,70.62-145,1.33-3.46,2.02-7.26,3.99-10.45,0,0,2.61-4.91,2.61-4.91,0,0,3,9.27,3,9.27-22.56-12.1-55.44-29.88-78.21-42.46-25.71-14.09-52.61-28.32-78.59-41.71,0,0,4.51-1.46,4.51-1.46-9.22,17.96-22.23,42.56-31.21,60.27-.24.49-.62.9-1.05,1.16-6.83,3.73-16.76.49-20.92-5.8-1.83-2.8-2.83-5.1-5.09-7.27-3.86-3.69-9.42-6.85-14.91-7.35-8.31-.88-16.78,3.87-20.35,11.42-4.29,8.4-1.72,19.33,5.7,25.07,4.75,3.45,10.7,5.66,16.51,4.91,3.29-.41,6.5-1.56,10.18-1.08,5.78.79,15.78,6.91,12.91,12.93,0,0-16.21,32.17-16.21,32.17-5.32,10.77-9.9,21.92-14.94,32.82,0,0-1.82-6.75-1.82-6.75,4.15,2.48,8.27,4.98,12.31,7.63,4.07,2.72,7.91,5.68,11.12,9.48,1.3,1.57,1.08,3.9-.49,5.2-.95.79-2.21,1.01-3.32.72-9.57-2.79-17.42-9.03-25.58-14.48-2.13-1.47-2.74-4.32-1.5-6.53,2.95-5.24,6-10.42,9.05-15.6,3.03-5.2,6-10.42,8.82-15.72,0,0,16.6-31.98,16.6-31.98,0,0,.14-.24.14-.24-.19.3-.35.69-.36,1.03,0,.17.03.33.03.36-.17-.33-.47-.67-.98-1.12-1.48-1.24-3.85-2.73-5.81-3.27-1.49-.38-2.71-.26-4.54.04-3.14.6-6.89,1.26-10.25.84-5.43-.62-10.3-2.68-14.64-5.67-10.44-7.19-14.2-22.18-8.35-33.43,6.39-13.36,23.53-18.69,36.44-11.53,4.45,2.24,9.05,5.68,11.81,10.08.96,1.45,1.73,2.9,2.47,3.99,2.22,3.92,9.6,5.8,12.7,4.08l-1.05,1.16c5.14-10.08,10.27-20.16,15.34-30.27l15.27-30.31c.83-1.64,2.83-2.31,4.48-1.48,19.87,10.03,39.76,20.02,59.79,29.72,12.85,6.16,46.96,22.46,60.23,28.77,13.4,6.37,26.73,12.85,40.04,19.41,3.36,1.66,4.74,5.73,3.09,9.09,0,0-.09.18-.09.18l-2.45,4.99c-1.44,3.46-4.12,6.25-6.14,9.35-16.38,30.05-39.29,72.44-55.45,102.79-6.95,13.1-13.92,26.19-20.79,39.33-.65,1.29-2.23,1.81-3.51,1.13,0,0-60.57-30.67-60.57-30.67-1.07-.52-1.51-1.68-1.89-2.65-1.82-5.12-.41-10.55,2.34-15.06,1.87-3.08,5.48-4.96,8.21-6.66,3.63-2.37,6.01-5.68,8.04-9.63,2.65-4.93,3.17-10.75,1.48-15.99-4.44-14.11-22.53-18.79-33.22-8.61-1.75,1.58-3.14,3.59-4.24,5.67-2.06,4.16-3.32,8.39-2.71,12.91.5,3.69,1.86,7.74.79,11.77-.93,3.37-2.46,5.91-4.68,8.7-.79.97-2.1,2.14-3.49,2.77-3.31,1.64-8.05-.53-6.4-4.66.86-1.82,3.09-2.54,4.85-1.59h0Z\"><\/path><path d=\"M43.49,285.11c.55,14.78.12,29.57-.3,44.33-.82,29.56-.81,58.94-.36,88.5,0,0,.66,44.33.66,44.33,0,0-5.84-5.76-5.84-5.76,49.28.91,98.62,1.99,147.9,1.3,6.35-.19,12.73-.2,18.99-.96,0,0,.43-.07.43-.07.05-.02.11-.03.16-.03,0,0,1.42-.12,1.42-.12,7.96-.26,8.77,10.79.75,11.87-7.13,1.11-14.36,1.02-21.5,1.26-21.24.39-42.46.22-63.68.04-30.1-.3-60.18-.81-90.27-1.45-.86-16.69-1.58-33.41-2.09-50.1-1.14-44.48-2.03-89.19,1.8-133.56.97-7.28,11.5-6.97,11.93.44h0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2e11e2 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c2e11e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdd1fbd e-con-full e-flex e-con e-child\" data-id=\"cdd1fbd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-61128ed e-con-full card_yellow e-flex e-con e-child\" data-id=\"61128ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d25d9af elementor-widget elementor-widget-heading\" data-id=\"d25d9af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">11:00 \u2013 12:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f46877 elementor-widget elementor-widget-heading\" data-id=\"0f46877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lernarrangements<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b8d27 elementor-widget elementor-widget-text-editor\" data-id=\"e3b8d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr die Gruppen gibt es bspw. das w\u00f6chentliche Turnen und das Vorstellen und Einf\u00fchren von Montessori-Material, das Erleben von Musik, Tanz und Rhythmik, das Vorlesen und H\u00f6ren von Geschichten und M\u00e4rchen, Tischtheater bzw. das Arbeiten an verschiedenen Projekten, Experimentieren, Forschen und vieles mehr.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db3119e e-flex e-con-boxed e-con e-child\" data-id=\"db3119e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-498eb5a e-con-full e-flex e-con e-child\" data-id=\"498eb5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a93ef07 e-con-full e-flex e-con e-child\" data-id=\"a93ef07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4bbd86 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d4bbd86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 500 500\"><path d=\"M235.06,218.77c1.32.71,2.81,1.07,4.32,1.07,1.34,0,2.71-.28,3.98-.85,3.08-1.36,5.32-4.08,5.99-7.26.61-2.89-.18-5.69-2.2-7.9-1.92-2.11-4.75-3.23-7.56-2.99-2.44.2-4.56,1.41-5.83,3.32-.6.47-1.05.92-1.42,1.43-1.37,1.95-1.93,4.64-1.5,7.22.44,2.62,1.93,4.74,4.21,5.97Z\"><\/path><path d=\"M306.08,212.84c-3.22-1.59-7.19-1.09-10.14,1.27-2.62,1.28-4.69,3.99-5.42,7.1-.68,2.91-.12,5.7,1.58,7.86,1.94,2.46,4.99,3.83,8.34,3.83.84,0,1.69-.09,2.55-.26,4.2-.86,7.42-3.69,8.42-7.4,1.3-4.84-1.04-10.28-5.33-12.4Z\"><\/path><path d=\"M307.32,268.72c-.19-1.44-1.38-2.83-2.77-3.24-1.11-.32-2.2.03-2.98.97-2.22,2.67-3.36,5.64-4.57,8.79-.68,1.76-1.38,3.58-2.28,5.33-2.85,5.51-6.37,10.36-10.45,14.41-10.65,10.55-25.51,15.24-38.78,12.24-30.15-6.78-38.16-43.04-34.22-66.63.16-.98-.47-1.75-1.17-2.01-.76-.27-1.51.03-1.93.75-6.7,11.58-7.17,26.79-1.29,41.73,6.46,16.39,19.33,29.27,33.6,33.62,4.24,1.29,8.69,1.92,13.19,1.92,10.78,0,21.83-3.6,30.85-10.36,10.47-7.83,24.47-24.66,22.79-37.53h0Z\"><\/path><path d=\"M367.18,194.52c-8.17-19.63-23.33-36.94-42.71-48.74-34.86-21.23-82.83-20.92-120.55-.22-.61.03-1.38.2-2.03,1-.06.07-.11.15-.16.23-.87.5-1.74,1-2.6,1.53-.06-.09-.13-.18-.2-.26-.71-.77-1.9-.83-2.69-.17-3.95,3.27-7.84,6.92-11.59,10.84-4.16,3.51-8.03,7.29-11.51,11.23-.87.99-1.1,2.25-.7,3.37-23.47,32.24-31.33,70.69-21.56,105.65,6.08,21.72,19.65,41.37,37.24,53.89,23,16.41,51.46,20.06,72.18,20.06.9,0,1.79,0,2.66-.02,18.33-.28,44.89-3.96,67.35-19.93,18.72-13.31,32.31-34.08,39.3-60.04,5.41-20.1,9.38-50.01-2.43-78.41ZM364.58,254.23c-2.84,17.79-10.02,42.92-28.13,61.63-18.17,18.78-42.38,25.1-59.5,27.09-40.6,4.73-91.71-6.7-113.42-52.93-23.12-49.22.5-94.54,16.74-117.27,14.93-12.25,33.45-25.57,57.58-31.75,22.39-5.74,44.96-4.68,65.26,3.05,20.58,7.85,38.1,21.92,49.33,39.63,15.46,24.33,15.14,51.8,12.14,70.55Z\"><\/path><path d=\"M394.97,146.62c.45,0,.9-.12,1.29-.38,9.11-5.79,17.09-13.19,24.81-20.34l2.42-2.24c1.7-1.57,3.57-3.14,5.55-4.81,6.57-5.53,14.01-11.8,16.85-19.66.53-1.45.12-3.08-1.05-4.27-1.2-1.21-2.86-1.63-4.33-1.12-7.87,2.72-14.25,10.09-19.89,16.59-1.7,1.96-3.3,3.82-4.89,5.48l-2.1,2.2c-7.31,7.67-14.87,15.6-20.83,24.67-.64.97-.5,2.24.34,3.09.5.51,1.16.78,1.82.78Z\"><\/path><path d=\"M328.13,104.1c.25.06.51.09.76.09,1.34,0,2.59-.8,3.08-2.06,2.82-7.27,5.24-14.8,7.59-22.09,1.08-3.36,2.16-6.72,3.29-10.07.9-2.69,1.94-5.43,2.93-8.08,2.63-7,5.35-14.25,6.31-21.79.2-1.63-.58-3-2.05-3.59-1.73-.69-3.92-.11-4.98,1.33-6,8.09-9.05,18.65-11.74,27.97-.29.99-.57,1.98-.86,2.95-3.65,12.45-5.73,22.71-6.53,32.28-.12,1.5.75,2.73,2.19,3.06Z\"><\/path><path d=\"M239.96,53.54c2.73,9.58,5.82,20.43,10.63,30.7.47,1,1.46,1.59,2.55,1.59.26,0,.53-.03.8-.1,1.43-.37,2.36-1.59,2.27-2.98-.8-11.3-3.41-22.33-5.71-32.07l-.49-2.07c-2.31-9.83-4.69-20-9.74-29.07-.77-1.38-2.35-2.04-3.92-1.63-1.6.42-2.68,1.79-2.67,3.39.01,10.35,2.88,20.37,5.66,30.07l.62,2.17Z\"><\/path><path d=\"M136.2,153.18c-9.86-16.13-19.39-27.15-31.86-36.86-6.58-5.12-13.65-9.71-21.01-13.64-.68-.37-1.38-.74-2.09-1.13-6.38-3.46-13.61-7.39-20.81-7.45h-.03c-1.96,0-3.82,1.4-4.55,3.4-.67,1.85-.18,3.74,1.28,4.91,3.73,3.02,8.17,4.85,12.47,6.61,2.25.93,4.59,1.88,6.75,2.99,6.68,3.41,13.29,7.5,19.66,12.14,13.42,9.75,25.79,21.46,34.82,32.97.61.78,1.48,1.18,2.38,1.18.64,0,1.3-.2,1.9-.62,1.55-1.07,2.02-3.01,1.11-4.52h0Z\"><\/path><path d=\"M96.18,246.76c1.46-.37,2.34-1.83,2.06-3.39-.27-1.48-1.53-2.45-2.96-2.29h0c-17.39,1.87-32.86,5.57-47.31,11.32l-1.25.5c-13.76,5.47-29.35,11.67-40,21.8-1.62,1.55-1.92,3.69-.76,5.45.94,1.43,2.56,2.24,4.21,2.24.64,0,1.29-.12,1.9-.38,7.01-2.95,13.73-6.75,20.24-10.42,6.92-3.91,14.07-7.95,21.56-10.96,13.94-5.61,28.17-10.27,42.31-13.85Z\"><\/path><path d=\"M121.05,299.68l-4.38,3.56c-11.29,9.18-22.96,18.67-34.1,28.47-6.6,5.8-12.47,11.02-17.95,15.97-1.1.99-2.23,1.97-3.37,2.96-4.7,4.07-9.57,8.27-12.56,13.93-.77,1.45-.6,3.05.45,4.2.74.81,1.79,1.24,2.87,1.24.54,0,1.09-.11,1.62-.33,5.86-2.51,10.46-7.04,14.92-11.41,1.1-1.08,2.19-2.15,3.29-3.18,5.08-4.74,10.61-9.99,17.4-16.52,10.83-10.42,21.4-21.39,31.61-32.01l3.37-3.5c.86-.9.89-2.21.06-3.12-.85-.93-2.24-1.03-3.23-.24Z\"><\/path><path d=\"M219.94,383.7c-1.33-.32-2.6.41-3.02,1.75-5.37,17.05-8.94,33.49-10.91,50.27-.97,8.23-1.63,16.79-2,26.17-.04,1.04-.09,2.08-.14,3.13-.37,7.43-.74,15.12,2.01,22.3.49,1.29,1.71,2.14,3.06,2.14.03,0,.06,0,.08,0,1.33-.03,2.46-.9,2.88-2.22,1.82-5.69,1.79-11.54,1.76-17.19,0-1.52-.02-3.05.01-4.58.14-8.37.61-17.11,1.38-25.97,1.51-17.39,3.82-35.14,6.86-52.77.24-1.4-.6-2.7-1.96-3.03Z\"><\/path><path d=\"M318.76,475.12c-1.6-2.26-3.12-4.39-4.46-6.6-4.68-7.63-9.08-15.66-13.07-23.85-4.71-9.65-8.49-19.82-12.15-29.65-2.54-6.83-5.16-13.88-8.09-20.74-.51-1.19-1.72-1.82-3.02-1.56-1.43.28-2.48,1.48-2.5,2.86,0,1.03-.01,2.05-.02,3.08l-.02,2.1c0,.65.25,1.25.73,1.69.14.13.29.24.46.34,3.1,15.86,9.85,31.48,16.08,44.72,4.05,8.61,8.68,17.24,13.76,25.67.71,1.17,1.41,2.38,2.13,3.61,3.67,6.3,7.47,12.83,13.24,17.14.56.42,1.22.63,1.9.63.71,0,1.44-.24,2.08-.7,1.32-.96,1.89-2.55,1.41-3.97-1.79-5.36-5.18-10.15-8.46-14.77Z\"><\/path><path d=\"M423.02,393.62c-1.76-1.1-3.59-2.23-5.31-3.39-7.37-4.97-14.62-10.18-21.54-15.5-5.84-4.48-11.58-9.38-17.14-14.12-7.69-6.56-15.64-13.34-24.03-19.19-1.03-.73-2.41-.57-3.35.38-.93.94-1.06,2.3-.32,3.31,10.14,13.89,24.3,25.43,39.13,37.01,6.5,5.07,13.05,9.91,19.47,14.38,1.21.85,2.43,1.73,3.66,2.62,6.28,4.53,12.77,9.21,20.33,11.11.3.07.59.11.88.11,1.16,0,2.23-.58,2.85-1.61.8-1.32.65-2.98-.38-4.15-4.04-4.6-9.24-7.83-14.27-10.96Z\"><\/path><path d=\"M481.72,247.38c-11.17-4.06-23.65-4.19-35.72-4.32-1.69-.02-3.36-.04-5.02-.07l-2.75-.05c-9.39-.17-19.08-.35-28.53.75-.55-.79-1.58-1.07-2.48-.64l-.12.06c-1.04.61-2.12,1.08-3.3,1.45l-.91.17c-.86.16-1.72.32-2.48.5-1.58.26-2.67,1.67-2.63,3.44.03,1.7,1.13,3.03,2.68,3.23,8.74,1.18,17.73,1.2,26.43,1.21,4.6,0,9.37.01,14,.2,4,.16,8.16.5,12.17.83,5.71.47,11.54.95,17.33.95,3.7,0,7.38-.19,11.01-.71,1.55-.22,2.62-1.31,2.78-2.85.18-1.79-.88-3.57-2.48-4.14Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4102f7 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c4102f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8841f13 e-con-full e-flex e-con e-child\" data-id=\"8841f13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-93c763b e-con-full card_yellow e-flex e-con e-child\" data-id=\"93c763b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60a9bcf elementor-widget elementor-widget-heading\" data-id=\"60a9bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">ab 12:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba50d09 elementor-widget elementor-widget-heading\" data-id=\"ba50d09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ab nach drau\u00dfen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb2834 elementor-widget elementor-widget-text-editor\" data-id=\"7bb2834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ab ca. 12:00 Uhr gehen wir t\u00e4glich und bei jedem Wetter in unseren gro\u00dfen Garten. Die Kinder spielen an der frischen Luft. Bis 13:00 Uhr k\u00f6nnen die Kinder abgeholt werden.<\/p>\n<p>Dienstags, mittwochs und donnerstags bieten wir f\u00fcr angemeldete Kinder um 13:00 Uhr ein warmes, kindgerechtes Mittagessen an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce77d12 e-flex e-con-boxed e-con e-child\" data-id=\"ce77d12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4259a88 e-con-full e-flex e-con e-child\" data-id=\"4259a88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9932222 e-con-full e-flex e-con e-child\" data-id=\"9932222\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2f149 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bb2f149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 500 500\"><path d=\"M390.18,254.83l-.1-1.82c-1.12-19.85-2.39-42.19-8.15-62.01-.03-.18-.07-.36-.13-.54-.09-.28-.19-.54-.29-.8-.02-.06-.04-.12-.05-.17.47-.77.71-1.68.62-2.62-.18-1.9-1.68-3.32-3.62-3.43-.32-.02-.65-.02-.97-.04-.51-.59-1.02-1.21-1.37-1.72-1.22-1.75-2.44-3.49-3.71-5.23-2.04-2.79-4.15-5.59-6.19-8.3l-2.39-3.18c-3.32-4.43-6.75-8.88-10.06-13.19-2.76-3.59-5.52-7.18-8.25-10.79-11.81-15.62-23.66-30.81-35.22-45.12-12.3-15.23-24.88-30.5-37.37-45.38-6.39-7.62-12.96-15.36-19.52-23.03-1.4-1.64-2.82-3.38-4.19-5.06-4.11-5.04-8.36-10.25-13.42-14.46-1.6-1.33-3.69-1.33-5.21,0-1.05.92-1.58,2.26-1.52,3.59-6.05,11.6-11.1,23.99-15.98,36-1.5,3.7-3,7.39-4.53,11.05-1.41,3.39-2.84,6.78-4.28,10.18-6.11-4.77-12.85-8.81-19.42-12.75l-2.6-1.56c-1.27-.76-2.56-1.56-3.86-2.36-6.23-3.84-12.64-7.79-19.43-10.12-.23-.9-.87-1.67-1.8-2.06-1.38-.58-2.9-.13-3.7,1.04-1.26.31-2.34,1.17-2.96,2.47-.52,1.1-.63,2.3-.38,3.38-2.79,5.17-5.2,10.36-7.29,15.73h0c-.44,1.13-.93,2.29-1.42,3.47-1.96,4.69-4.14,9.9-4.39,15.13-.05.1-.1.2-.15.3-.69,1.78-.23,3.71,1.14,4.97.41.5.96.89,1.59,1.15,3.32,2.15,7,3.58,10.57,4.97,1.73.67,3.37,1.31,4.96,2.02,6.88,3.08,12.81,5.91,18.13,8.68.56.29,1.56.95,2.61,1.64,3.7,2.44,7.3,4.66,10.53,5.54-1.81,4.22-3.61,8.44-5.41,12.66-4.58,10.75-9.32,21.87-14.15,32.72-2.11,4.75-4.52,9.45-7.07,14.43-5.13,10.01-10.44,20.37-13.07,31.07-.08.33-.11.66-.1.99-.18.58-.27,1.21-.24,1.88,0,.13.02.26.04.39-4.12,17.06-4.02,35.57-3.92,53.54.02,3.4.04,6.75.03,10.04-.07,21.52.16,43.92.7,68.48,1.18,53.36,4.14,105.97,6.58,145.84.07,1.08.42,2.04,1,2.81-.21.28-.39.59-.53.93-.69,1.63-.44,3.61.65,5.04.91,1.2,2.25,1.85,3.73,1.85.22,0,.44-.01.67-.04l41.34-5.16c24.68-3.08,49.37-6.17,74.05-9.25l8.58-1.07c.42.23.9.36,1.4.36.12,0,.23,0,.35-.02.65-.08,1.22-.36,1.66-.76l13.06-1.63c11.16-1.39,22.31-2.79,33.46-4.19l6.43-.79c7.07-.87,14.14-1.74,21.21-2.66,2.55-.33,5.23-.78,7.82-1.21,6-1,12.17-2.03,17.8-1.86.02.02.04.04.07.06l.11.08c.24.17.47.35.74.55.95.72,2.23.82,3.18.31l.16-.08c1.91-.93,2.4-1.5,3.08-3.52.53-1.56.11-3.16-1.14-4.29-.03-.03-.07-.05-.1-.08,1.19-16.11,1.25-32.57,1.3-48.54.02-6.15.03-12.5.12-18.71l.26-18.54c.24-16.64.48-33.85.67-50.76v-.29c.25-21.67.51-44.08-.74-66.13ZM283.84,467.3c-.11-7.45-.99-14.9-1.84-22.17-.35-2.95-.71-6-1.01-8.96-1-10.01-2.15-20.17-3.27-30-.44-3.82-.87-7.65-1.3-11.47l-4.65-41.44c-.18-1.58-.31-3.26-.45-5.03-.61-7.7-1.3-16.31-5.91-22.62-.26-.77-.81-1.42-1.54-1.85-.17-.18-.33-.38-.51-.55-1.08-1.06-2.63-1.49-4.1-1.28-7.16-1.97-15.71-.97-23.43-.07-2.52.3-4.91.58-7.04.72-4.19.28-8.49.5-12.65.71-9.71.49-19.74.99-29.48,2.38-2.89.4-4.76,2.64-4.55,5.45.11,1.45.73,2.71,1.68,3.64.41,7.71,1.42,15.47,2.41,23,.53,4.08,1.08,8.31,1.52,12.42,1.3,12.17,2.54,24.54,3.7,36.78h0c.68,7.16,1.2,14.58,1.7,21.77,1.14,16.29,2.32,33.09,5.48,49.14-12.67,1.57-25.35,3.14-38.02,4.71.06-.43.09-.88.05-1.34-3.58-43.14-5.93-89.68-7.19-142.26-.65-26.97-.91-50.96-.81-73.33.06-10.89.19-22.58.8-34.31.18-3.54.47-7.16.75-10.66.3-3.76.6-7.59.79-11.44,37.64-1.93,74.81-4.24,110.52-6.89,18.81-1.39,37.88-2.92,56.65-4.54,4.68-.4,9.57-.72,14.29-1.02,11.79-.75,23.9-1.53,35.46-3.81.73,4.51,1.63,8.99,2.5,13.36,1.17,5.84,2.39,11.87,3.17,17.84,1.36,10.43,2.36,21.29,3.04,33.2,1.39,24.41,1.38,48.93,1.18,69.7-.07,7.38-.15,14.77-.22,22.16-.16,15.48-.33,31.5-.43,47.24-.04,5.9-.15,11.95-.26,17.8-.25,13.44-.51,27.27.06,40.9-3.63-.14-7.59.63-11.07,1.32-1.66.33-3.23.64-4.48.79-9.33,1.08-19.19,2.28-29.29,3.56-17.42,2.15-34.83,4.31-52.25,6.47ZM148.24,79.86c1.3-3.15,2.2-6.54,3.01-9.7.5-1.93.97-3.75,1.51-5.43,1.33-4.18,2.54-8.22,3.69-12.21,4.16,2.49,8.65,4.57,13.03,6.59,3.25,1.5,6.32,2.91,9.26,4.48,3.75,2.01,7.5,4.26,11.13,6.44,3.62,2.17,7.32,4.38,11.12,6.43-3.09,7.23-6.19,14.43-9.24,21.5l-2.14,4.97c-2.29-1.11-6.16-3.99-7.82-5.23-1.15-.86-2.06-1.53-2.67-1.91-3.27-2.02-6.76-4.04-10.66-6.17-.89-.49-1.81-1-2.74-1.52-5.43-3.02-11.39-6.33-17.48-8.23ZM194.79,109.27l1.71-3.98c3.62-8.44,7.31-17.03,11.04-25.65.25.06.5.09.74.09,1.01,0,1.97-.49,2.58-1.38.92-1.35.73-3.21-.44-4.34-.1-.1-.22-.19-.32-.29,2-4.59,4-9.18,6.01-13.74,1.57-3.55,3.18-7.11,4.8-10.69,4.43-9.77,8.97-19.82,12.76-30.01,2.99,3.89,6.34,7.57,9.62,11.16,1.99,2.18,4.04,4.43,5.93,6.63,6.4,7.48,12.61,14.81,18.46,21.79,12.4,14.78,24.61,29.61,36.3,44.08,3.25,4.02,6.51,8.04,9.77,12.06,8.91,11,18.13,22.37,27.05,33.68,3.9,4.94,7.78,10.06,11.54,15.02,4.91,6.47,9.92,13.09,15.15,19.53-9.71.22-19.52,1.33-29.1,2.43-5.22.6-10.62,1.22-15.83,1.67-20.02,1.71-38.53,3.19-56.6,4.52-35.45,2.62-71.81,4.88-108.2,6.74,1.77-3.72,3.21-7.6,4.61-11.4.72-1.96,1.47-3.99,2.24-5.92.96-2.42,1.92-4.84,2.87-7.27,2.18-5.55,4.44-11.29,6.79-16.87,4.45-10.6,9.08-21.33,13.56-31.71,2.32-5.39,4.65-10.77,6.96-16.17ZM203.31,422.14c-.51-4.88-1.03-9.93-1.49-14.81-.62-6.69-1.14-13.61-1.65-20.3-1.27-16.84-2.6-34.19-5.59-50.86,6.89-.34,13.8-1.02,20.53-1.69,3.82-.38,7.76-.77,11.61-1.08,3.5-.29,7.07-.45,10.85-.62,6.54-.3,13.24-.61,19.65-1.62,3.34,7.71,4.17,16.07,5.04,24.87.21,2.15.42,4.3.67,6.44,1.48,12.75,2.96,25.49,4.44,38.23l.66,5.68c-.15-.13-.3-.25-.47-.36v-.82h-2.31c-.41-.08-.79-.14-1.15-.17-4.58-.66-9.25-.51-13.76-.38-.83.03-1.66.05-2.49.07-1.01.03-2.01.02-3.02,0-4.53-.03-9.23-.07-13.53,2.7-1.55,1-2.38,2.62-2.28,4.46.11,2.05,1.42,4.05,3.25,4.96,2.33,1.16,4.82,1.53,7.31,1.53,2.22,0,4.43-.29,6.51-.56,1.07-.14,2.13-.28,3.15-.37l1.8-.16c5.09-.44,10.35-.89,15.42-2.41.98-.29,1.8-.89,2.36-1.7,1.04,9.03,2.12,18.26,3.3,27.36.34,2.61.64,5.24.94,7.88.75,6.56,1.52,13.27,2.92,19.86l-39.56,4.9c-10.06,1.25-20.13,2.5-30.19,3.74.88-18.08-1.05-36.71-2.94-54.78ZM384.14,464.75c.18.03.36.05.55.06-.18.03-.37.05-.56.04v-.09Z\"><\/path><path d=\"M237.51,158.25c4.67,2.88,9.6,4.31,14.99,4.31s11-1.38,17.34-4.13c9.21-4.01,13.19-9.8,13.65-19.95,3.48-9.34,2.18-19.92-3.6-29.12-6.41-10.19-16.94-16.79-28.16-17.65-10.63-.83-20.57,3.43-27.3,11.65-6.74,8.24-9.03,19.29-6.13,29.55,2.92,10.27,10.1,19.74,19.2,25.34ZM275.54,138.8c0,.18,0,.35.03.52-1.17,5.29-4.2,8.72-9.26,10.46-2.75.94-5.3,1.69-7.7,2.18,1.23-5.93,1.1-12.47.98-18.44-.03-1.36-.05-2.68-.06-3.95,0-.31,0-.63,0-.95,2.58.22,5.16.47,7.69.72,2.59.26,5.24.5,7.9.72.33,2.95.46,5.9.44,8.73ZM227.66,128.96c3.95.14,8-.15,11.95-.45,3.77-.28,7.33-.55,10.74-.44,0,.51.01,1.03.01,1.54-.02,3.25-.38,6.63-.77,10.2-.45,4.1-.89,8.29-.79,12.4-2.57-.53-5.06-1.61-7.56-3.39-5.79-4.11-10.43-10.25-12.74-16.83h0c-.35-1-.63-2.01-.84-3.02ZM249.96,116.89c.03.5.05,1.01.07,1.51-.05,0-.1,0-.15-.01-.88-.06-1.79-.12-2.73-.18-5.92-.41-12.87-.89-19.23.04.84-3.13,2.34-6.08,4.5-8.66,4.23-5.06,10.15-7.79,16.63-7.79.18,0,.36.02.54.02-.12,5.08.11,10.15.36,15.08ZM259.21,119.24c-.34-5.31-1.04-10.82-2.52-16.25,9.51,2.92,14.46,10.38,16.85,18.93-4.35-1.16-9.05-2.04-14.34-2.68Z\"><\/path><path d=\"M214.69,379.13c5.14,4.27,11.25,6.63,16.91,6.63,1.13,0,2.24-.09,3.32-.29,5.27-.93,9.61-4.08,12.53-9.09,3.76-6.46,3.77-14.04.31-20.53.37-.21.72-.48,1.03-.8,1.44-1.47,1.79-3.58.87-5.26-3.37-6.12-9.82-9.16-17.68-8.35-10.92,1.13-21.63,9.15-24.4,18.25-2.12,6.96.41,13.87,7.12,19.45ZM240.04,369.75c-1.31,3.29-3.4,5.28-6.21,5.89-3.96.88-9.32-1.1-13.34-4.91-2.32-2.21-3.26-4.51-2.79-6.84.73-3.59,4.87-7.48,10.07-9.44,2.3-.87,4.54-1.24,6.83-1.14,4.03,4.12,7.96,10.12,5.43,16.44Z\"><\/path><path d=\"M363.52,329.76c.09,0,.19,0,.29,0,1.88-.13,3.44-1.52,3.72-3.32.84-5.6.24-11.32-.33-16.85-.19-1.81-.37-3.52-.5-5.24-.57-7.55-1.14-15.11-1.72-22.66-.21-2.69-.35-5.41-.48-8.23.87-1.26,1.06-2.94.48-4.37-.18-.44-.43-.83-.73-1.17-.41-9.27-.97-18.73-3.15-27.53.18-.38.3-.8.33-1.25.14-1.84-1.09-3.5-2.86-3.87-10.93-2.21-22.38-2.51-33.35-2.46-.11-.4-.22-.79-.34-1.19-.41-1.31-1.58-2.14-2.95-2.06-1.4.08-2.61,1.11-2.87,2.47-.05.28-.1.56-.15.83-10.76.11-21.82.33-32.49,2.14-.99.17-1.85.59-2.52,1.19-.06-.12-.11-.25-.17-.37-.62-1.21-1.99-1.88-3.34-1.63-1.33.25-2.32,1.32-2.45,2.67-.63,6.35.65,12.75,1.88,18.95.4,2,.78,3.89,1.09,5.77,1.33,8.01,2.72,16.62,3.96,25.35h0c1.42,9.97,2.59,18.81,3.58,27.02.24,1.99.42,4.08.6,6.1.3,3.47.61,7.01,1.23,10.49-.96.79-1.46,1.99-1.33,3.29.14,1.48,1.1,2.8,2.46,3.37.21.08.42.16.62.23.67,1.8,2.33,2.91,4.29,2.91.22,0,.45-.01.68-.04,1.42-.18,2.63-.92,3.38-1.97,1.49-.12,2.96-.33,4.42-.55,1-.15,2.02-.3,3.06-.42,6.96-.83,13.17-1.6,18.99-2.35,2.23-.29,4.53-.54,6.85-.8,9.28-1.03,18.83-2.11,27.42-5.37.65.58,1.5.92,2.43.92ZM332.66,313.79c-.68-3.26-1.38-6.62-1.77-9.85-1.03-8.51-1.58-17.16-2.05-25.28-.09-1.55-.15-3.12-.2-4.71,7.67.08,15.95.37,25.18.91.33.12.69.18,1.05.18l.42.02c.26,2.58.5,5.1.67,7.58.57,8.1,1.14,16.2,1.73,24.29.11,1.51.18,3.02.25,4.54.16,3.23.32,6.53.79,9.8-8.03-.45-16.3.74-24.33,1.92-.43-3.16-1.09-6.31-1.73-9.39ZM353.57,242.46c-.58,7.55-.02,15.38.74,23.13-8.5-.94-17.16-1.55-25.88-1.83-.11-7.1-.3-14.32-1.26-21.27,3.38-.02,6.77,0,10.09.04,5.35.05,10.85.1,16.31-.07ZM312.94,274.58c2.24-.17,4.41-.34,6.53-.46.19,2.37.36,4.69.48,6.98.42,8.14,1.02,17.75,2.29,27.23h0c.12.88.23,1.77.35,2.67.55,4.32,1.16,9.03,2.46,13.47-7.84.93-14.27,1.66-20.2,2.29-.86.09-1.69.16-2.49.23-.49.04-.97.08-1.46.13-.4-3.42-1.04-6.82-1.68-10.15-.4-2.08-.78-4.05-1.1-6.02-1.32-8.09-2.72-16.71-4.22-25.39-.5-2.89-.99-5.77-1.49-8.66-.12-.7-.24-1.39-.36-2.09,6.74.85,13.91.3,20.88-.24ZM287.4,244.64c.06,0,.12,0,.18,0,5.6-.19,11.26-.61,16.73-1.02,4.44-.33,8.99-.67,13.52-.88-.3,6.81.14,13.82.73,20.77-.54-.02-1.07-.04-1.62-.06-8.59-.31-18.25-.66-26.54,1.71-.38-2.18-.76-4.36-1.14-6.54-.27-1.54-.52-3.11-.77-4.7-.48-3.1-.97-6.25-1.71-9.35.21.02.41.06.63.06Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba0f2c elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5ba0f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f0237c e-con-full e-flex e-con e-child\" data-id=\"1f0237c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-80a2038 e-con-full card_yellow e-flex e-con e-child\" data-id=\"80a2038\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-892e8d0 elementor-widget elementor-widget-heading\" data-id=\"892e8d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">bis 14:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22d1477 elementor-widget elementor-widget-heading\" data-id=\"22d1477\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Abholzeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46c1d5c elementor-widget elementor-widget-text-editor\" data-id=\"46c1d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Abholung aller Kinder. F\u00fcr unsere Mitarbeiter beginnt die Vor- und Nachbereitungszeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-left\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 127.338v257.324c0 17.818-21.543 26.741-34.142 14.142L29.196 270.142c-7.81-7.81-7.81-20.474 0-28.284l128.662-128.662c12.599-12.6 34.142-3.676 34.142 14.142z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3a2f8a e-flex e-con-boxed e-con e-parent\" data-id=\"d3a2f8a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a433e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"a7a433e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Betreuungszeiten<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38390aa e-con-full e-flex e-con e-child\" data-id=\"38390aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6bba745 e-con-full e-flex e-con e-child\" data-id=\"6bba745\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-592aaf8 elementor-widget elementor-widget-heading\" data-id=\"592aaf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00d6ffungszeiten<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7d22c1 e-con-full e-flex e-con e-child\" data-id=\"a7d22c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf6bfd elementor-widget elementor-widget-heading\" data-id=\"ebf6bfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Montag bis Donnerstag<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9b2c49 elementor-widget elementor-widget-heading\" data-id=\"e9b2c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">7:00 \u2013 14:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-035989a elementor-widget elementor-widget-heading\" data-id=\"035989a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Freitag<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd41507 elementor-widget elementor-widget-heading\" data-id=\"dd41507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">7:00 \u2013 13:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-892a7fe e-con-full e-flex e-con e-child\" data-id=\"892a7fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a280d49 elementor-widget elementor-widget-heading\" data-id=\"a280d49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bringen &amp; <br>Abholen<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0afc10e e-con-full e-flex e-con e-child\" data-id=\"0afc10e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a72a44 elementor-widget elementor-widget-heading\" data-id=\"1a72a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Bringzeit<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62de30e elementor-widget elementor-widget-heading\" data-id=\"62de30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">7:00 \u20138:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee31952 elementor-widget elementor-widget-heading\" data-id=\"ee31952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Abholzeit<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d4419 elementor-widget elementor-widget-heading\" data-id=\"40d4419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">bis 14:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a911455 elementor-widget elementor-widget-heading\" data-id=\"a911455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Freitags bis 13:00 Uhr<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c73d60 e-con-full e-flex e-con e-child\" data-id=\"1c73d60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf696d elementor-widget elementor-widget-heading\" data-id=\"ccf696d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schlie\u00dfzeiten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45eebdf elementor-widget elementor-widget-text-editor\" data-id=\"45eebdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die 30 gesetzlichen Schlie\u00dftage im Kindergartenjahr orientieren sich an den Weihnachts-, Oster- und Sommerferien und werden den Eltern im September f\u00fcr das folgende Kindergartenjahr bekannt gegeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a26e69 elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1a26e69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M19.03,89.23C-1.67,72.51-5.89,42.69,9.71,21.06,17.26,10.03,27.75,3.21,40.94.81c34.25-6.16,64.11,23.86,57.96,58.08-4.48,26.27-30.17,44.73-56.49,40.51-6.32-.96-12.44-3.15-17.89-6.44-.27-.16-.36-.52-.2-.79.16-.27.51-.36.78-.2,10.8,6.2,23.96,7.96,35.95,4.92,24.91-6.04,41.02-31.65,35.59-56.72C89.83,7.58,52.29-8.48,24,9.06c-5.26,3.28-10.26,7.2-13.99,12.22C1.08,33.27-1.65,49.46,2.68,63.74c2.56,8.61,7.59,16.46,14.36,22.36.6.6,2.07,1.68,2.72,2.23.58.47-.12,1.38-.73.9h0Z\"><\/path><path d=\"M44.45,47.52c-.49-3.66-.74-7.36-.93-11.04-.32-6.31-1.62-13.58-.39-19.8.04-.18.33-.28.4-.06,1.78,5.88,1.22,12.87,1.58,18.98.2,3.47.43,6.95.84,10.4.41,3.39,1.58,6.86,1.63,10.25,0,.57-.68.81-.98.28-1.48-2.65-1.75-6.02-2.15-9Z\"><\/path><path d=\"M48.09,54.03c4.12-1.4,9.33-.85,13.65-.78,5.23.08,10.44.45,15.62,1.15,1,.13.81,1.71-.2,1.57-.79-.03-1.58-.07-2.37-.1-.07,0-.13-.02-.18-.06-3.96-.23-7.93-.39-11.89-.39-4.62,0-9.88,1.05-14.4.23-.76-.14-1.08-1.34-.23-1.62Z\"><\/path><path d=\"M51.34,88.61c0-2.34-.25-4.66-.15-7,0-.1.15-.12.18-.03.73,2.25.84,4.64.85,7.01.01,2.03.21,4.66-.6,6.53-.11.26-.46.22-.51-.07-.33-2.04.22-4.36.23-6.45Z\"><\/path><path d=\"M67.14,14.26c1.04-1.37,1.89-2.88,2.99-4.2.05-.06.15,0,.13.07-.5,1.7-1.48,3.16-2.52,4.57-.89,1.21-1.92,2.85-3.29,3.55-.19.1-.41-.1-.31-.3.68-1.37,2.07-2.46,3-3.69Z\"><\/path><path d=\"M16.53,69.75c1.29-1.15,2.41-2.45,3.75-3.54.06-.05.15.03.11.1-.82,1.57-2.07,2.81-3.36,3.99-1.11,1.01-2.44,2.43-3.91,2.84-.21.06-.38-.18-.25-.35.93-1.21,2.51-2.01,3.66-3.03Z\"><\/path><path d=\"M49.56,3.37c.92,1.8.48,4.26.26,6.14-.26,2.2-.73,4.41-1.81,6.46-.08.16-.38.07-.36-.09.24-2.08.71-4.13.87-6.21.16-2-.42-4.3.15-6.23.1-.34.72-.42.9-.07Z\"><\/path><path d=\"M74.34,86.22c-1.56-.44-2.72-2.04-3.67-3.21-1.11-1.36-2.11-2.85-2.67-4.61-.04-.14.18-.27.26-.17,1.05,1.28,1.96,2.68,3.07,3.92,1.06,1.19,2.7,2.1,3.49,3.5.13.24-.17.66-.48.57Z\"><\/path><path d=\"M11.31,27.26c1.61-.12,3.25.98,4.55,1.75,1.51.89,2.96,1.95,4.09,3.41.09.11-.07.31-.19.25-1.43-.84-2.77-1.84-4.23-2.62-1.4-.75-3.26-1.04-4.48-2.09-.21-.18-.07-.68.25-.7Z\"><\/path><path d=\"M83.38,46.86c1.57-.63,3.43-.47,5.25-.5,1.8-.03,3.68-.1,5.48.06.13,0,.26.02.39.04.01,0,.02,0,.03,0,0,0,0,0,0,0,.07.01.14.02.22.03.68.13.72.86.02.99-1.86.35-3.83.42-5.76.53-1.75.1-3.76.43-5.38-.07-.62-.19-.95-.81-.25-1.09Z\"><\/path><path d=\"M27.04,11c1.05.61,1.92,1.68,2.85,2.66.92.97,1.9,1.96,2.74,3,.06.07.12.15.18.23,0,0,.01.01.02.02,0,0,0,0,0,0,.03.04.06.08.09.13.29.41,0,.72-.4.39-1.08-.88-2.1-1.92-3.12-2.92-.92-.91-2.07-1.88-2.69-2.95-.23-.41-.15-.82.32-.55Z\"><\/path><path d=\"M34.53,80.06c-.03,1.22-.55,2.5-.95,3.78-.4,1.27-.8,2.61-1.3,3.84-.03.09-.07.18-.11.27,0,0,0,.02,0,.02,0,0,0,0,0,0-.02.05-.04.1-.07.15-.22.45-.62.35-.53-.16.25-1.37.66-2.77,1.05-4.15.35-1.25.64-2.72,1.28-3.78.25-.4.65-.53.64.01Z\"><\/path><path d=\"M89.07,68.39c-1.19-.24-2.36-.97-3.56-1.59-1.19-.62-2.43-1.24-3.56-1.95-.08-.05-.16-.1-.25-.16,0,0-.02,0-.02-.01,0,0,0,0,0,0-.04-.03-.09-.06-.13-.09-.41-.3-.24-.67.25-.49,1.31.48,2.61,1.13,3.9,1.75,1.17.56,2.57,1.1,3.5,1.92.35.31.41.73-.12.63Z\"><\/path><path d=\"M86.81,28.07c-.85.87-2.1,1.45-3.28,2.11-1.17.66-2.37,1.36-3.58,1.92-.08.04-.17.08-.27.12,0,0-.02,0-.02.01,0,0,0,0,0,0-.05.02-.1.04-.15.06-.47.18-.7-.17-.28-.48,1.12-.83,2.37-1.57,3.6-2.31,1.11-.67,2.33-1.55,3.52-1.88.45-.13.84.06.46.44Z\"><\/path><path d=\"M15.11,50.94c-1.53.72-3.4.66-5.22.79-1.8.13-3.67.3-5.47.24-.13,0-.26,0-.4-.02-.01,0-.02,0-.03,0,0,0,0,0,0,0-.07,0-.14-.01-.22-.02-.68-.09-.76-.82-.07-.99,1.84-.45,3.8-.63,5.72-.85,1.74-.2,3.73-.64,5.38-.22.63.16,1,.76.31,1.08Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6b1692 elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b6b1692\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M67.24,17.6c-4.65,1.12-9.51,2.48-14.3,1.34-.47-.11-1.2-.22-1.61-.5-1.05-.72.63-1.29,1.18-1.51,1.09-.44,2.2-.82,3.33-1.14,1.16-.33,2.32-.59,3.51-.78,1.12-.17,2.33-.14,3.41-.45.32-.09.24-.59-.07-.63-1.34-.17-2.9.27-4.21.55-1.38.3-2.76.65-4.1,1.1-.88.29-5.96,1.75-3.55,3.26.98.61,2.43.79,3.55.92,1.36.16,2.74.16,4.1.04,3.02-.27,5.92-1.12,8.79-2.04.08-.03.05-.17-.04-.15Z\"><\/path><path d=\"M58.84,14.51c-1.78.06-3.53.43-5.31.59-.92.09-1.84.14-2.77.13-.51,0-1.01-.02-1.51-.06-.37-.03-1.08,0-1.39-.17-.59-.34.15-.65.51-.85.42-.23.86-.45,1.3-.64.77-.34,1.58-.62,2.39-.87.87-.26,1.76-.46,2.67-.59.81-.12,1.68-.06,2.46-.29.37-.11.22-.6-.08-.67-.99-.23-2.23.06-3.22.24-1.06.2-2.12.48-3.12.86-.96.37-1.89.82-2.78,1.33-.54.31-1.57.76-1.27,1.55.26.69,1.4.66,1.99.72,1.11.11,2.24.12,3.36.06,2.3-.12,4.67-.43,6.85-1.15.12-.04.07-.21-.05-.21Z\"><\/path><path d=\"M50.31,12.73c-1.97.11-3.93.44-5.88.72-.81.12-1.64.29-2.46.35-.55.04-1.94.09-1.54-1.05.15-.41.74-.72,1.1-.9,1.41-.7,2.96-1.2,4.48-1.59.89-.23,1.79-.41,2.7-.54.76-.11,1.91-.39,2.66,0-.05.03-.1.06-.15.08-.16.08-.26.33-.07.45.46.3.87.14,1.22-.26.11-.12.13-.37,0-.5-.68-.73-1.54-.81-2.5-.73-1.21.1-2.42.33-3.6.61-1.11.27-2.21.6-3.28,1.02-.92.36-2.02.73-2.75,1.43-.5.47-.79,1.17-.37,1.8.39.59,1.21.7,1.86.68,1.39-.04,2.82-.38,4.19-.59,1.47-.22,2.94-.42,4.38-.76.14-.03.12-.23-.03-.22Z\"><\/path><path d=\"M55.14,6.16c-1.63-1.38-4.41-1.88-6.48-1.94-2.08-.07-4.67.23-6.43,1.44-1.75,1.2-1.09,3.05.87,3.44,2.43.48,5.52.38,7.85-.45.09-.03.05-.16-.04-.15-2.08.14-4.09.46-6.19.32-.96-.07-3.75-.21-2.79-1.92.43-.76,1.53-1.09,2.3-1.33,1.74-.55,3.61-.7,5.42-.47.88.11,1.75.31,2.59.59.88.3,1.66.8,2.52,1.13.4.15.72-.37.39-.65Z\"><\/path><path d=\"M64.53,11.66c.67-1.66.86-3.54.66-5.32-.18-1.56-.6-3.51-1.93-4.5-1.11-.83-2.55-.59-3.58.25-.5.42-.86.92-1.1,1.48-1.58-1.96-3.73-3.4-6.34-3.56-1.44-.09-3.24.27-3.34,2.02-.12,2.14,2.05,2.95,3.71,3.49.11.04.18-.12.07-.17-1.44-.55-4.15-1.94-3.16-3.93.82-1.66,3.89-.87,5.18-.32,1.54.66,2.73,1.79,3.65,3.16-.13.53-.17,1.09-.14,1.65.04.85.24,1.69.48,2.51.16.56.36,1.48,1.1,1.5,1.45.03,1.13-2.12.81-2.91-.39-.96-.9-1.9-1.5-2.76.03-.09.06-.18.09-.27.46-1.18,1.87-2.34,3.2-1.8,1.59.64,1.98,3.06,2.1,4.54.14,1.6-.13,3.13-.6,4.66-.13.43.49.72.66.28ZM59.79,6.9c.17.37.34.76.39,1.17.07.54-.2,1.33-.71.52-.37-.58-.44-1.64-.51-2.32-.04-.35-.05-.7-.03-1.06.31.55.6,1.12.86,1.69Z\"><\/path><path d=\"M76.33,11.34c-.47-1.36-2.19-1.01-3.28-.71,0,0,0,0,0-.01.63-1.31.69-3.1-.59-4.05-3.01-2.25-7.58,2.25-8.45,4.92-.08.24.24.47.4.24.88-1.25,1.55-2.47,2.74-3.48,1.07-.92,2.53-1.91,4.02-1.62,1.87.37,2.02,2.32,1.36,3.78-.07.16-.16.32-.25.48-1.31.52-2.45,1.43-3.31,2.53-.15.19.05.44.27.37,1.32-.45,2.48-1.19,3.28-2.3,1.24-.44,4-1.03,3.2,1.05-.43,1.12-1.88,2.04-2.85,2.66-1.08.69-2.28,1.03-3.39,1.62-.14.08-.11.29.07.28,1.64-.13,3.39-1.24,4.67-2.21,1.04-.79,2.61-2.04,2.09-3.55ZM71.44,11.99c-.41.41-.88.75-1.39,1,.43-.39.89-.72,1.39-1Z\"><\/path><path d=\"M73.22,27.56c-.05-.35-.11-.69-.18-1.03.06.06.12.12.18.17,1.13,1,3.22,1.19,3.86-.47.67-1.73-.48-3.98-1.5-5.33-1.43-1.89-3.46-3.33-5.5-4.49-.43-.25-.87.48-.45.76,2.72,1.81,5.86,3.56,6.68,7.01.21.89.34,2.14-.76,2.46-.94.27-1.77-.4-2.31-1.09-.23-.29-.45-.6-.66-.92-.39-1.29-.92-2.53-1.63-3.7-.2-.33-.79-.1-.71.28.28,1.28.89,2.75,1.7,3.98.1.37.2.74.28,1.12.17.8.3,1.62.39,2.43.08.71.56,2.58-.75,2.05-1.38-.56-2.3-2.63-2.77-3.93-.07-.18-.13-.37-.18-.56.5-1.65.48-3.38.04-5.04-.07-.25-.39-.23-.53-.08-.65.66-.6,1.71-.57,2.58.03.95.19,1.89.46,2.8-.14.51-.34,1.02-.62,1.42-.3.42-.68.8-1.29.21-.25-.24-.41-.84-.52-1.18-1.03-3.12.14-6.32,1-9.32,0-.03-.03-.04-.04-.02-.85,2.01-1.59,4.1-1.67,6.3-.04.91.04,1.83.27,2.71.17.66.46,1.82,1.16,2.13.94.42,1.6-.65,1.97-1.51.58,1.59,1.71,3.87,3.4,4.28,2.37.58,1.48-2.75,1.29-4ZM68.52,22.23c.17.92.2,1.86.08,2.79-.03-.21-.06-.41-.09-.62-.07-.62-.18-1.48,0-2.17Z\"><\/path><path d=\"M37.24,20.43c1.1-2.16,2.68-4.01,4.27-5.82.25-.29-.18-.76-.47-.49-1.85,1.67-3.02,3.78-3.92,6.06.04.08.08.17.12.26Z\"><\/path><path d=\"M70.47,33.41c.32-.8.74-1.73.86-2.63-.22-.1-.42-.23-.6-.4-.41.91-.53,2-.88,2.95-.38,1.04-.87,2.04-1.24,3.08-.04.11.11.21.19.11.74-.93,1.24-2.01,1.67-3.11Z\"><\/path><path d=\"M35.76,23.58c-.87.1-1.63.43-2.44-.16-.78-.58-1.02-1.7-.67-2.59.8-2.03,3.51-1.75,4.67-.23.05.07.19.03.17-.07-.59-2.87-4.77-2.35-5.64.09-.41,1.16-.13,2.57.84,3.37.89.73,2.52,1.14,3.42.23.25-.26-.04-.68-.36-.64Z\"><\/path><path d=\"M72.16,39.5c1.02-1.97-1.01-4.6-3.17-3.5-.12.06-.21.17-.19.31,0,.06,0,.1.05.14.2.19.34.1.6.06.53-.08,1.04-.03,1.5.27.92.62.92,2.07.1,2.78-.94.81-2.07.36-2.8-.44-.37-.41-.93-1.01-1.48-.52-.11.1-.16.26-.06.39.16.21.34.27.54.43.25.2.43.48.66.7.42.41.97.66,1.55.75,1.1.15,2.2-.35,2.71-1.35Z\"><\/path><path d=\"M65.02,30.59c.27-.93-.03-1.92-.75-2.58-1.71-1.56-4-.19-4.68,1.69-.04.12.1.19.18.11.94-.91,2.3-2.33,3.68-1.32.61.45.88,1.2.6,1.92-.24.62-.81.77-1.16,1.27-.16.24-.05.53.23.59.9.19,1.66-.93,1.88-1.68Z\"><\/path><path d=\"M46.22,18.98c-2.2-.24-3.93,2.61-2.89,4.5.17.31.65.13.7-.17.11-.77-.08-1.51.29-2.25.35-.68,1.09-1.22,1.89-1.1,2.15.33,1.3,2.77,1.53,4.15,0,.05.06.08.1.04,1.92-1.39.56-4.94-1.62-5.17Z\"><\/path><path d=\"M67.43,39.49c.28-.53-.63-.94-.87-.37-2.49,6.01-9.78,7.77-15.61,6.51-6.34-1.38-12.03-5.89-14.32-12.02-.56-1.5-.92-3.08-1.05-4.68-.13-1.57.04-3.13.01-4.7,0-.09-.13-.1-.17-.02-1.18,2.65-.63,6.08.2,8.75.98,3.17,2.83,5.99,5.25,8.25,4.75,4.42,11.97,6.87,18.34,5.03,3.56-1.03,6.47-3.46,8.21-6.72Z\"><\/path><path d=\"M57.88,35.38c-2.28-.98-4.69-1.69-6.99-2.65-1.09-.46-2.18-.93-3.26-1.42-.59-.27-1.18-.55-1.77-.83-.45-.21-.75-.43-1.25-.35-.05,0-.1.07-.07.12.43.81,1.71,1.15,2.51,1.54,1.18.57,2.36,1.12,3.56,1.63,2.29.98,4.67,2.07,7.08,2.68.42.11.59-.56.2-.72Z\"><\/path><path d=\"M58.16,35.95c.23-.54-.61-.9-.84-.36-.75,1.77-1.94,3.35-3.75,4.14-1.57.68-3.41.66-4.88-.26-3.15-1.98-3.78-5.92-3.63-9.32,0-.21-.31-.34-.39-.11-1.23,3.59.55,8.51,3.92,10.34,3.86,2.1,8.02-.86,9.56-4.43Z\"><\/path><path d=\"M50.45,45.97c.27-.49-.53-.83-.8-.34-.55,1.01-1.24,1.97-2.13,2.72-.8.67-2.11,1.5-3.21,1.35-1.5-.2-1.64-2.52-1.58-3.67.06-1.17.42-2.24.88-3.3.09-.21-.22-.41-.36-.21-.81,1.2-1.16,2.65-1.14,4.09.02,1.27.3,3.08,1.62,3.65,1.18.51,2.72-.17,3.71-.82,1.3-.86,2.26-2.11,3-3.46Z\"><\/path><path d=\"M61.35,50.73c-1.96-.71-3.95-1.34-5.88-2.14-.91-.38-1.81-.77-2.71-1.18-.91-.41-1.8-.91-2.77-1.13-.17-.04-.23.19-.12.29.71.64,1.6,1.03,2.45,1.44.99.48,2,.93,3.01,1.36,1.89.79,3.83,1.57,5.82,2.11.43.12.63-.6.21-.76Z\"><\/path><path d=\"M43.77,43.22c-1.96-1.05-4.08-1.8-6.07-2.81-1.01-.52-2.01-1.07-2.98-1.65-.93-.56-1.81-1.24-2.78-1.74-.41-.21-.72.39-.4.67,1.65,1.44,3.9,2.48,5.86,3.43,1.97.97,4.13,1.98,6.3,2.34.15.03.19-.18.07-.24Z\"><\/path><path d=\"M30.27,40.61c.64-1.1,1.53-2.26,1.83-3.5.03-.14-.17-.26-.27-.16-.96.86-1.55,2.19-2.21,3.28-.62,1.02-1.53,2.11-1.84,3.27-.07.25.3.48.49.3.87-.83,1.39-2.14,2-3.17Z\"><\/path><path d=\"M35.05,48.85c-.92-1.02-2.24-1.74-3.34-2.55-1.21-.89-2.35-1.96-3.62-2.77-.37-.24-.74.23-.42.53,1.07,1.04,2.43,1.87,3.66,2.72,1.11.77,2.33,1.76,3.63,2.18.06.02.15-.05.09-.11Z\"><\/path><path d=\"M60.16,59.15c-1.5-.56-3.18-.81-4.73-1.19-.84-.2-1.67-.41-2.51-.6-.63-.15-1.23-.36-1.87-.2-.07.02-.07.11-.02.15.49.44,1.17.54,1.8.7.77.2,1.55.4,2.32.59,1.58.4,3.22.97,4.83,1.17.36.04.53-.49.17-.62Z\"><\/path><path d=\"M60.4,59.6c.46-1.24.46-2.72.7-4.02.26-1.42.78-2.83.97-4.25.05-.39-.5-.54-.66-.18-.56,1.26-.75,2.82-.99,4.17-.23,1.32-.62,2.91-.36,4.23.03.16.28.23.35.05Z\"><\/path><path d=\"M21.37,70.52c.7-1.07,1.4-2.15,2.1-3.22,1.36-2.1,2.72-4.2,4.07-6.31,1.32-2.06,2.6-4.14,3.9-6.2,1.29-2.05,2.85-4.1,3.78-6.34.06-.15-.13-.25-.23-.14-1.63,1.85-2.82,4.17-4.14,6.24-1.35,2.11-2.72,4.2-4.08,6.3-1.32,2.05-2.65,4.1-3.99,6.14-.7,1.07-1.4,2.15-2.11,3.21-.64.98-1.45,1.94-1.93,3-.16.36.33.61.57.34.8-.88,1.39-2.04,2.04-3.04Z\"><\/path><path d=\"M43.07,86.36c1.44-4.84,3.05-9.62,4.53-14.45.73-2.39,1.45-4.77,2.15-7.16.69-2.35,1.48-4.7,1.86-7.12.02-.15-.19-.21-.25-.07-.99,2.28-1.59,4.72-2.3,7.09-.71,2.39-1.43,4.78-2.16,7.16-1.46,4.77-2.85,9.56-4.49,14.27-.15.44.53.72.66.28Z\"><\/path><path d=\"M29.89,79.33c-1.99-.95-3.93-2.01-5.82-3.15-.86-.52-1.71-1.05-2.56-1.6-.84-.54-1.69-1.31-2.65-1.59-.2-.06-.41.14-.27.34.59.81,1.6,1.33,2.42,1.88.93.62,1.89,1.22,2.85,1.79,1.86,1.11,3.76,2.14,5.68,3.15.5.26.87-.57.35-.82Z\"><\/path><path d=\"M42.85,85.96c-1.78-.65-3.6-1.11-5.35-1.87-1.72-.75-3.34-1.83-5.08-2.48-.26-.1-.46.23-.25.42,1.37,1.25,3.33,2.07,5.02,2.81,1.72.76,3.6,1.58,5.44,1.96.48.1.7-.66.23-.83Z\"><\/path><path d=\"M32.65,82.15c.46-2.04.52-4.16.94-6.22.09-.42-.51-.53-.69-.19-.83,1.57-1.85,2.98-3.06,4.26-.33.35.25.8.58.46.78-.82,1.47-1.7,2.09-2.64-.23,1.44-.36,2.91-.14,4.32.03.17.25.16.29,0Z\"><\/path><path d=\"M47.53,71.06c-3.55-1.58-7.09-3.17-10.64-4.74-1.78-.79-3.55-1.57-5.33-2.35-1.75-.77-3.44-1.76-5.21-2.48-.18-.07-.31.16-.17.29,1.33,1.2,3.19,1.89,4.8,2.62,1.82.83,3.65,1.65,5.47,2.47,3.6,1.62,7.2,3.23,10.8,4.83.41.18.69-.46.28-.65Z\"><\/path><path d=\"M26.65,78.66c.27-.4-.32-.87-.59-.47-1.02,1.55-2.05,3.11-3.23,4.55-1.01,1.23-2.92,3.88-4.75,3.03-.8-.37-1.41-1.13-1.99-1.77-.64-.7-1.27-1.41-1.87-2.15-1.1-1.35-2.02-3.03-3.31-4.2-.04-.03-.09.01-.07.05.36,1.01,1.08,1.88,1.7,2.74.66.91,1.36,1.8,2.05,2.68.96,1.24,2.15,3.12,3.8,3.5,1.69.4,3.12-1.29,4.14-2.39,1.59-1.71,2.87-3.66,4.15-5.6Z\"><\/path><path d=\"M13.05,76.2c.1-.08.09-.2,0-.28-.46-.46-1.27.01-1.64.38-.46.46-.74,1.14-.45,1.76.08.17.33.15.36-.04.09-.47.24-.94.6-1.27.33-.3.78-.29,1.11-.55Z\"><\/path><path d=\"M22.1,81.39c.51-.92,1.02-1.85,1.53-2.77.32-.58.99-1.29.8-1.98-.03-.12-.18-.24-.3-.24-.03,0-.06,0-.09,0-.16,0-.32.06-.38.22,0,.03-.02.05-.03.08-.04.12-.02.23.06.32-.13.52-.81,1.44-.99,1.77-.33.62-.67,1.24-1,1.85-.69,1.29-1.62,3.65-3.35,2.16-1.18-1.01-2.21-2.23-3.14-3.48-.89-1.2-1.58-2.54-2.52-3.69-.04-.05-.11,0-.09.05.56,1.85,1.88,3.53,3.08,5.01.65.8,1.3,1.61,2.03,2.34.45.46.98.94,1.65.97,1.44.08,2.18-1.58,2.76-2.63Z\"><\/path><path d=\"M12.55,79.75c.17-.32-.39-.57-.53-.22-.57,1.46-1.58,3.28-3.09,3.93-.62.27-.93.18-1.18-.52-.1-.3-.14-.65-.16-.96-.07-.76.01-1.52.21-2.26.38-1.45,1.15-2.7,2.11-3.83.63-.74,1.66-1.77,2.61-.78.55.57.41,1.43.85,2.04.07.09.22.08.26-.03.3-.79-.18-2-.78-2.57-.63-.6-1.48-.61-2.2-.2-1.69.97-2.83,3.37-3.31,5.17-.27,1.02-.89,4.75.93,4.74,2.32,0,3.43-2.84,4.29-4.51Z\"><\/path><path d=\"M47.49,93.45c-.03-.75-.75-1.66-1.55-1.26-.08.04-.06.17.04.16.73-.04,1.17.81.87,1.42-.35.7-1.2.72-1.63,1.3-.07.09-.05.25.07.29,1.01.31,2.24-.92,2.2-1.92Z\"><\/path><path d=\"M46.54,94.75c-1.85.28-3.64.89-5.49,1.2-.93.15-1.86.27-2.8.36-.91.09-2.49.45-3.26-.15-.79-.62-.58-2.04-.48-2.91.11-.93.29-1.85.51-2.76.49-1.97,1.25-3.82,1.89-5.74.15-.45-.5-.74-.69-.29-.85,2.06-1.58,4.22-2.07,6.4-.36,1.61-1.02,4.15.24,5.55.55.61,1.34.64,2.1.61,1.16-.04,2.32-.17,3.47-.33,2.18-.3,4.66-.65,6.66-1.61.16-.08.12-.36-.08-.33Z\"><\/path><path d=\"M46.53,91.99c-1.37-.24-3.1.52-4.4.91-1.54.46-3.08.9-4.69.99.46-2.72,1.21-5.39,2.18-7.97.15-.41-.47-.67-.62-.26-1.03,2.76-1.75,5.59-2.2,8.5-.03.2.14.34.32.33,1.6-.04,3.13-.44,4.65-.9.75-.23,1.5-.47,2.26-.68.82-.23,1.76-.3,2.54-.65.13-.06.11-.25-.03-.28Z\"><\/path><path d=\"M48.02,96.76c.92-1.21,2.88-4.09,1.53-5.58-1.11-1.23-3.97-.65-4.49.93-.03.1.07.19.16.13.6-.38,1.05-.86,1.76-1.05.87-.24,2.21-.15,2.42.93.26,1.38-1.05,3.29-1.82,4.3-.85,1.11-2.21,2.62-3.65,2.93-1.38.3-1.75-.89-1.21-1.87.38-.69.97-1.24,1.39-1.9.23-.36-.22-.72-.52-.41-.99,1.02-2.97,3.4-1.06,4.56,1.95,1.18,4.47-1.61,5.49-2.96Z\"><\/path><path d=\"M80.63,50.58c-.72-.15-1.45.1-2.18.19-.82.1-1.64.17-2.46.25-1.64.16-3.28.3-4.93.42-1.64.12-3.29.23-4.94.32-1.62.09-3.34.03-4.92.38-.05.01-.06.09,0,.1,1.5.24,3.12.09,4.63.02,1.71-.07,3.41-.16,5.12-.27,1.65-.11,3.29-.24,4.93-.39.82-.07,1.64-.16,2.46-.24.78-.07,1.62.03,2.34-.31.23-.11.2-.43-.06-.49Z\"><\/path><path d=\"M82.75,50.77c.18-.72.29-1.46.42-2.2.13-.71.34-1.48.39-2.2.04-.64-.22-1.29-1.01-1.13-.93.2-1.28,1.63-1.52,2.39-.31,1.01-.68,2.22-.3,3.24.04.1.17.09.21,0,.61-1.31.35-3.07,1.26-4.27.08-.26.29-.37.62-.35-.04.23-.08.45-.12.68-.07.39-.14.79-.21,1.18-.15.84-.34,1.69-.43,2.54-.05.45.58.53.69.1Z\"><\/path><path d=\"M92.94,49.47c-1.27-1.32-3.22-1.07-4.87-.8-.97.16-1.93.38-2.86.69-.85.28-1.82.56-2.46,1.2-.03.03,0,.07.04.06.75-.05,1.45-.4,2.17-.62.84-.26,1.7-.47,2.56-.63,1.4-.26,3.32-.67,4.6.14-2.61.79-5.23,1.17-7.91,1.67-.34.06-.28.54.06.53,2.86-.1,5.83-.95,8.55-1.82.16-.05.25-.3.13-.43Z\"><\/path><path d=\"M92.67,53.53c-2.68-1.13-5.65-2.06-8.58-2-.08,0-.07.11,0,.13,2.65.59,5.25,1.09,7.77,2.08-2.53.73-5.05-.39-7.39-1.41-.42-.18-.7.48-.28.65,2.6,1.09,5.72,2.17,8.47,1.01.2-.08.21-.38,0-.47Z\"><\/path><path d=\"M90.03,56.34c.05-.1,0-.24-.08-.31-1.63-1.3-3.52-2.62-5.56-3.15-.09-.02-.16.12-.07.17,1.71,1.07,3.47,1.96,5.06,3.2-.28.08-.77-.07-.93-.13-.21-.08-.42-.16-.63-.25-.51-.22-1.01-.46-1.49-.74-.66-.4-1.32-1.19-2.11-1.23-.13,0-.23.1-.18.23.21.63.87.9,1.43,1.21.69.38,1.4.74,2.13,1.05.72.3,1.94.9,2.43-.04Z\"><\/path><path d=\"M84.32,54.16c-.11-.05-.18.1-.1.17.43.44,3.41,2.69,2.53,3.54-1.89-1.35-3.77-2.9-5.81-4.01-.34-.18-.67.37-.35.59.99.68,2.07,1.22,3.07,1.88,1,.66,1.98,1.35,2.93,2.08.1.08.22.07.33,0,2.09-1.17-1.6-3.81-2.59-4.26Z\"><\/path><path d=\"M80.14,53.88c-3.3.24-6.6.45-9.91.61-3.07.14-6.29,0-9.34.43-.02.12-.03.24-.05.36,3.04.35,6.26.02,9.3-.1,3.37-.14,6.73-.33,10.09-.58.46-.03.37-.74-.08-.71Z\"><\/path><path d=\"M31.31,38.7c-.22-.24-1.16-.89-1.55-1.36-.96-1.17-2.19-2.09-3.26-3.16-1.13-1.14-2.25-2.29-3.34-3.47-.96-1.04-1.9-2.37-3.09-3.15-.07-.05-.2.02-.15.11.6,1.28,1.8,2.36,2.75,3.39,1,1.09,2.02,2.16,3.06,3.22,1.1,1.12,2.23,2.23,3.37,3.31,1.05.99,1.29,1.23,1.86,1.63.12-.18.23-.35.35-.52Z\"><\/path><path d=\"M30.02,40.8c-1.18-1.02-.9-.81-2.1-1.82-1.34-1.13-2.67-2.26-4.05-3.35-1.24-.98-2.53-1.88-3.93-2.64-.68-.37-1.37-.69-2.09-.96-.6-.22-1.25-1.27-1.88-1.05-.11.04.13.53.22.63.45.5.88,1.01,1.49,1.24.77.29,1.52.63,2.25,1.01,1.43.75,2.8,1.68,4.07,2.67,2.4,1.86,3.11,3.15,5.84,4.55.06-.09.11-.19.17-.28Z\"><\/path><path d=\"M45.52,29.64c-.38,0-.74.05-1.12.08-.37.03-.75.03-1.12.08-.12.01-.26.1-.29.22-.03.1-.04.17,0,.27.04.11.17.22.29.23.77.05,1.66-.09,2.37-.4.27-.12.16-.49-.12-.48Z\"><\/path><path d=\"M58.95,36.97c.21-.37-.1-.83-.27-1.17-.09-.19-.2-.37-.31-.54-.13-.2-.32-.38-.43-.58-.07-.13-.26-.06-.22.08.06.2.05.43.09.64.04.23.09.45.16.68.12.36.22.92.63,1.04.15.04.27,0,.35-.14Z\"><\/path><path d=\"M56.85,30.47c0-2.25.03-4.51-.1-6.76-.01-.24-.41-.25-.42,0-.14,2.12-.14,4.25-.16,6.38-1.27-.28-2.62-.67-3.9-.56-.23.02-.25.33-.06.42,1.28.61,2.87.69,4.26.91.24.04.39-.17.39-.38Z\"><\/path><path d=\"M20.46,28.41c-.68-.92-1.64-1.83-2.82-1.99-.47-.07-.86.04-1.18.41-.75.82-1.23,2.16-.7,3.16.4.83,1.1,1.54,1.85,2.07l-.34.5c-1.17-.94-2.43-2.33-2.13-3.94.21-.99.76-2.08,1.73-2.51,1.04-.26,2.09.32,2.86.96.39.33.74.68,1.07,1.08l-.35.25h0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15f2f1f e-flex e-con-boxed e-con e-parent\" data-id=\"15f2f1f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27842a1 e-con-full e-flex e-con e-child\" data-id=\"27842a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c411b7e e-con-full e-flex e-con e-child\" data-id=\"c411b7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8ebb09 e-con-full e-flex e-con e-child\" data-id=\"a8ebb09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8711a5d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8711a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Regeln, Rhythmus, Rituale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bd9435 elementor-widget elementor-widget-text-editor\" data-id=\"9bd9435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Regeln, Rhythmus und Rituale pr\u00e4gen den Kindergartenalltag und f\u00f6rdern die Gemeinschaft. Das Einhalten von Regeln, das Wahrnehmen von Tages-, Wochen- und Jahresrhythmen und wiederkehrende Rituale geben den Kindern innere Ruhe, Sicherheit und Geborgenheit. Die Kinder entwickeln ein Bewusstsein daf\u00fcr, dass wir sowohl als Einzelne, als auch als Gemeinschaft Teil eines Ganzen sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a613444 elementor-widget elementor-widget-heading\" data-id=\"a613444\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Jahresthema<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4940907 elementor-widget elementor-widget-text-editor\" data-id=\"4940907\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Jedes Kindergartenjahr steht unter einem bestimmten Thema. Mit abwechslungsreichen Projekten begleitet dieses Thema die Kinder durch das Kindergartenjahr. Es erm\u00f6glicht die intensive Auseinandersetzung zu verschiedenen Schwerpunkten aus Natur, Umwelt und Gesellschaft. Vielf\u00e4ltige Bildungsinhalte, angepasst an den Interessen und Bed\u00fcrfnissen der Kinder, werden ganzheitlich und Erlebnis orientiert vermittelt.<br \/>Zu jedem Jahresthema gestalten die Kinder eine eigene Mappe, die am Jahresende mit nach Hause genommen wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a85ed2 e-con-full e-flex e-con e-child\" data-id=\"1a85ed2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88a3950 elementor-widget elementor-widget-image\" data-id=\"88a3950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"654\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2112-2.png\" class=\"attachment-large size-large wp-image-1245\" alt=\"P\u00e4dagogin mit lockigem Haar spielt Gitarre f\u00fcr ein Kind in einem bunten Gruppenraum des Integrativen Montessori Kindergartens Bayreuth \u2013 t\u00e4gliches Musikritual\" srcset=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2112-2.png 700w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2112-2-300x280.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cbcc7a elementor-absolute elementor-widget elementor-widget-image\" data-id=\"8cbcc7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_love.svg\" class=\"attachment-large size-large wp-image-449\" alt=\"Icon Herz als Symbol f\u00fcr Geborgenheit und liebevolle Betreuung im Kindergarten\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01f8c02 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"01f8c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_house.svg\" class=\"attachment-large size-large wp-image-447\" alt=\"Icon Haus f\u00fcr den Bereich Unser Haus und Geb\u00e4ude\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec0ec6d e-flex e-con-boxed e-con e-parent\" data-id=\"ec0ec6d\" data-element_type=\"container\" data-e-type=\"container\" id=\"ernaehrung\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fba2d7b e-con-full e-flex e-con e-child\" data-id=\"fba2d7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85df192 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"85df192\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_A.png\" class=\"attachment-large size-large wp-image-172\" alt=\"Illustrierter Buchstabe A in Blau mit zwei spielenden Kindern \u2013 eines winkt aus dem Buchstaben, eines f\u00e4hrt auf einem roten Spielzeugauto\" srcset=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_A.png 500w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_A-300x300.png 300w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/KiGa_Circle_A-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0d389e e-con-full e-flex e-con e-child\" data-id=\"e0d389e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05ebe6f elementor-widget elementor-widget-heading\" data-id=\"05ebe6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ern\u00e4hrung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-939321c elementor-widget elementor-widget-image\" data-id=\"939321c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/11\/kiga_icon_apple.svg\" class=\"attachment-large size-large wp-image-450\" alt=\"Icon Apfel f\u00fcr gesunde Ern\u00e4hrung und Verpflegungsangebot im Kindergarten\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c73d4e3 e-con-full e-flex e-con e-child\" data-id=\"c73d4e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebe22b0 elementor-widget elementor-widget-text-editor\" data-id=\"ebe22b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die gesunde Ern\u00e4hrung der Kinder ist uns ein besonderes Anliegen. Sie werden von Beginn an bei der Zubereitung frischer und gesunder Nahrungsmittel mit eingebunden. Auf spielerische Art und Weise wird vermittelt, welche Lebensmittel gut f\u00fcr den K\u00f6rper und unser Wohlbefinden sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90cf337 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"90cf337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M40.94,37.54c-.9-4.19-2.66-8.11-4.37-12.03-1.63-3.72-2.93-8.46-5.51-11.61-.83-1.01-2.14.12-1.97,1.14.64,3.82,3.3,7.79,4.93,11.3,1.86,3.96,3.67,7.96,6.29,11.48.23.31.72.13.64-.27h-.01Z\"><\/path><path d=\"M59.39,5.94c-4.84,2.54-9.81,4.65-14.85,6.73-2.29.95-4.61,1.87-6.93,2.74-2.21.83-4.71,1.34-6.67,2.67-.66.45-.48,1.65.43,1.61,2.53-.12,5-1.36,7.33-2.28,2.24-.88,4.45-1.82,6.63-2.84,4.98-2.31,9.72-5.19,14.36-8.11.33-.21.04-.7-.31-.52h0Z\"><\/path><path d=\"M69.41,1.52C67.1-.22,63.1-.09,60.34.11c-3.12.22-6.2.97-9.06,2.25-3.26,1.46-10.98,6.49-5.98,10.51.28.23.64-.05.49-.38-2.51-5.63,6.18-8.9,10.15-9.9,2.2-.56,4.46-.81,6.74-.75,2.16.05,4.34.83,6.47.59.5-.05.65-.61.25-.92h.01Z\"><\/path><path d=\"M68.39,1.05c-2.81,3.66-4.02,7.98-7.66,11.14-1.82,1.58-3.98,2.81-6.33,3.42-1.65.43-8.73,1.36-8.46-1.99,0-.15-.23-.21-.29-.08-.68,1.5.43,2.63,1.79,3.29,2.87,1.39,6.72.76,9.54-.34,5.73-2.25,11.75-8.64,13.07-14.74.22-1.06-1.05-1.49-1.66-.7h0Z\"><\/path><path d=\"M58.01,80.99c-2.51,3.01-4.09,6.64-6.67,9.63-2.91,3.35-6.45,5.67-10.84,6.57-9.14,1.88-18.11-2.38-24.89-8.25-6.74-5.84-11.17-13.21-10.96-22.33.2-8.51,3.86-17.21,9.98-23.17,7.1-6.92,17.91-9.11,26.72-4.02.83.48,1.44-.69.73-1.24-7.34-5.62-17.68-4.72-25.12.35-7.76,5.29-12.78,14.3-14.24,23.47-1.57,9.87,1.48,18.96,8.48,26.05,6.77,6.87,16.02,12.39,25.97,11.92,10.31-.49,19.21-8.38,22.71-17.9.38-1.03-1.17-1.94-1.87-1.09h0Z\"><\/path><path d=\"M89.68,30.89c-5.71-7.11-15.27-14.04-24.85-12.07-9.85,2.03-20.09,10.14-23.56,19.67-.21.6.64.87.96.4,5.13-7.35,10.83-13.65,19.47-16.87,5.16-1.93,9.87-1.66,14.78.87,3.62,1.86,6.87,4.35,9.65,7.32,11.92,12.7,12.62,33.57-.54,45.77-7.45,6.9-16.88,8.55-26.6,6.86-1.88-.32-2.7,2.34-.8,2.9,8.69,2.54,19.14-.39,26.27-5.62,7.52-5.52,12.03-14.16,13.03-23.35,1.01-9.32-1.95-18.57-7.8-25.87h-.01Z\"><\/path><path d=\"M59.48,88.15c-.07-.6-.4-1.28-1.07-1.4-.27-.05-.51-.1-.77,0-.58.21-1.11.73-1.07,1.4.13,2.42.33,5.59,1.64,7.69.23.39.73.26.88-.11.92-2.23.65-5.24.39-7.58h0Z\"><\/path><path d=\"M63.88,92.51c-.68-1.1-1.24-2.16-2.08-3.16-.87-1.04-1.73-2.09-2.78-2.97-1.42-1.18-3.3.64-2.05,2.04.91,1.02,2,1.84,3.06,2.68,1.04.81,2.13,1.35,3.26,2,.36.21.81-.21.58-.58h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGesundes Fr\u00fchst\u00fcck\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJeden Freitag bereiten wir gemeinsam unser \u201egesundes Fr\u00fchst\u00fcck\u201c zu. Die Auswahl reicht von selbstgebackenen Br\u00f6tchen \u00fcber Obst und Gem\u00fcserohkost bis hin zu verschiedenen Salaten, Smoothies und vielem mehr. An den anderen Tagen achten die Eltern auf eine ausgewogene Brotzeit, die sie den Kindern mitgeben.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef30600 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ef30600\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 500 500\"><path d=\"M300.25,130.03c54.27,6.65,76.98,16.43,93.58,23.63,0,0,29.73,15.68,35.25,32.45,1.81,5.51,1.22,10.48-1.43,14.62-2.15,3.35-4.44,3.96-5.98,4.12-7.66.84-18.9-8.27-21.97-11.28-28.34-31.69-77.78-49.49-105.89-57.56,3.18-1.91,5.18-4.08,6.44-6h0ZM193.21,158.06c19.68.23,99.45,16.29,136.82,42.84,11.38,8.1,17.84,16.33,19.17,24.47,2.55,15.59-.11,18.43-.06,18.43-8,.06-21.55-15.24-22.18-15.76-49.56-42.46-102.84-57.53-139.74-62.62,3.18-2.5,4.99-5.13,6-7.36h0ZM422.12,298.47c1.36.99,3.21,1.01,4.59.03,14.88-10.62,28.92-22.63,41.57-36.27,23.32-25.1,34.75-46.12,30.88-68.7h.01c-4.38-25.45-26.07-48.55-64.06-68.42-.9-.59-21.61-17.96-69.17-17.96-21.19,0-45.41,6.31-70.05,11.76-2.15.48-3.72,1.94-4.08,4.1-.02.08-6.84,8.94-29.29,7.43-33.65-2.25-74.12,16.83-75.71,17.59-1.79.86-2.95,2.4-3.03,4.38-.02.11-1.66,9.24-24.96,10.58-4.92-.13-15.24.02-18.01.36-.13,0-36.32,7.51-59.07,34.47-1.05,1.24.34,10.58-3.58,14.52-7.05,7.11-15.78,7.05-16.31,7.28-.67.32-67.42,31.8-55.83,88.13,6.27,30.45,31.4,81.52,129.35,81.52h.02c23.27,0,47.72-5.06,76.56-10.76,43.97-8.69,123.38-24.39,191.86-65.11,2.31-1.37,2.97-4.42,1.48-6.65h0c-.92-1.38-2.75-1.78-4.18-.93-67.1,40.14-146.84,52.96-190.28,61.55-28.18,5.58-52.88,11.14-75.43,11.14h-.02c-85.77-.02-111.95-39.67-118.79-72.94-9.28-45.08,42.38-72.49,49.07-75.84,5.16-.69,9.55-2.13,13.24-4.19,7.51.83,40.41,4.97,76.75,17.53,2.4.83,5.06-.17,6.33-2.37l.95-1.64c1.25-2.15.22-4.9-2.12-5.73-30-10.58-57.74-15.44-72.23-17.45,2.02-3.83,2.69-7.66,2.82-10.58h0c36.51-10.48,78.16-4.94,115,15.53,25.74,14.29,45.73,34.64,49.7,50.61,2.74,10.9.72,13.17.69,13.19-2.57,1.56-14.6-4.48-23.06-11.59-16.94-14.25-36.74-25.11-56.44-33.36-2.44-1.02-5.25-.16-6.69,2.06h0c-1.63,2.53-.66,5.47,2.15,6.56,20.89,8.11,36.96,18.59,54.04,32.97,2.02,1.7,17.32,14.23,29.1,14.23,2.4,0,4.63-.51,6.59-1.75,8.9-5.56,5.26-20.16,4.06-24.94-4.76-18.98-26.3-41.52-54.94-57.43-34.38-19.11-72.81-25.97-108.16-19.89,16.08-13.09,31.16-16.54,38.02-17.42v.04c.15-.02,80.82-14.28,171.4,56.69,7.32,5.74,26.95,28.85,41.31,22.49,8.88-3.94,7.51-18.27,5.64-29.69-1.81-11.09-9.74-21.7-23.57-31.52-32.3-22.96-90.17-37.54-123.73-42.65,33.84-13.32,58.88-7.79,59.58-7.81,6.92,1.47,83.18,18.48,119.8,59.38,22.6,25.9,41.43,10.82,44.82,5.56,4.4-6.84,5.32-15.02,2.67-23.63-4.52-14.67-26.14-32.01-41.27-39.16-13.09-6.19-31.38-13.57-66.94-20.01,11.76-1.47,23.08-2.27,33.79-2.27,43.96,0,64.08,12.54,64.69,12.92,35.31,18.5,55.11,39.01,58.88,60.96,3.28,19.02-5.28,39.2-26.16,61.7h0c-12.21,13.16-25.8,24.77-40.23,35.03-2.18,1.55-2.19,4.78-.03,6.36h0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBrotzeit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBei der Brotzeit, genauso wie beim Mittagessen sitzen wir alle zusammen am Tisch. Wir legen Wert auf eine ruhige Atmosph\u00e4re und bringen den Kindern unsere Tischkultur nahe.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea11808 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ea11808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 500 500\"><path d=\"M331.67,238.28h68.36l-1.45-4.63c-2.89-9.22-11.25-15.42-20.81-15.42-.74,0-1.49.04-2.23.11-.14.01-.27.02-.41.02-1.99,0-3.68-1.5-3.94-3.48-1.42-10.87-10.74-19.06-21.69-19.06-2.31,0-4.61.37-6.85,1.1-.41.13-.83.2-1.25.2-1.64,0-3.09-.98-3.69-2.51-3.36-8.41-11.32-13.83-20.31-13.83-3.27,0-6.44.72-9.43,2.14-.55.26-1.12.39-1.71.39-1.36,0-2.62-.68-3.37-1.83-4.06-6.27-10.93-10.02-18.38-10.02-4.23,0-8.34,1.23-11.9,3.54-.65.42-1.4.65-2.17.65-1.24,0-2.39-.56-3.16-1.55-4.2-5.41-10.51-8.51-17.3-8.51s-13.11,3.1-17.3,8.5c-.76.98-1.92,1.54-3.17,1.54-.77,0-1.53-.22-2.18-.64-3.55-2.31-7.66-3.53-11.89-3.53-7.45,0-13.92.81-17.99,7.1-.74,1.13-2,1.81-3.36,1.81-.59,0-1.16-.13-1.69-.39-2.99-1.42-6.16-2.14-9.43-2.14-8.99,0-17.36,8.36-20.71,16.75-.61,1.53-2.07,2.52-3.71,2.52-.42,0-.83-.07-1.23-.2-2.17-.71-4.42-1.07-6.7-1.07-4.49,0-8.85,1.37-12.6,3.97l-6.44,4.45,7.65,2.04c25.55,12.61,43.35,44.59,45.44,81.75l.19,3.36h120.91s138.77,0,138.77,0v-23.26c0-12.09-9.8-21.9-21.9-21.9l-74.04-1.7c-2.21,0-20.93-.09-20.93-2.29h0c0-2.21,1.79-4,4-4ZM116.16,252.6c21.04,0,38.79,15.08,42.2,35.85l.49,2.99h18.01l-.24-3.79c-1.32-21.22-8.06-40.95-18.98-55.54-11.27-15.05-26-23.34-41.5-23.34s-30.23,8.29-41.5,23.34c-10.93,14.59-17.67,34.32-18.99,55.54l-.24,3.79h18.05l.49-2.98c3.43-20.78,21.18-35.86,42.2-35.86ZM114.7,258.57c-16.02,0-28.45,12.87-32.32,28.45l-1.1,4.42h69.78l-1.1-4.43c-3.88-15.57-17.8-28.44-33.81-28.44h-1.44ZM296.76,113.81c-17.88,0-33.47,12.09-37.93,29.4l-3.7,14.42h25.73c17.88,0,33.47-12.09,37.93-29.4l-2.13-10.11-19.9-4.31ZM176.96,113.47c.32.22.54.55.64.92l3.55,13.85c4.45,17.31,20.05,29.4,37.93,29.4h25.73l-3.7-14.42c-4.45-17.31-15.07-31.16-32.95-31.16l-31.29.26c-1.72,0-2.76-3.96-2.76-3.96-.85-2.58.05-4,2.76-4l26.35,1.5c19.1,0,36.18,11.41,43.5,29.06l3.29,7.94,3.29-7.94c7.32-17.65,24.39-29.06,43.5-29.06h30.7c1.1,0,2.19.36,2.97,1.13,1.04,1.02,1.44,2.47,1.08,3.85l-5,19.41c-3.6,13.95-13.2,25.33-26.34,31.24l-6.2,2.79,5.82,3.52c2.43,1.47,4.57,3.17,6.37,5.08l1.46,1.54,2.05-.55c2.49-.67,5.06-1,7.65-1,10.2,0,19.57,5.1,25.08,13.63l1.21,1.88,2.22-.27c1.2-.15,2.42-.22,3.62-.22,12.74,0,26.8,5.17,30.95,17.23l.74,2.16,2.27.23c13.4,1.34,21.59,14.53,23.78,27.84l.49,2.99h14.92c16.51,0,29.89,13.38,29.89,29.89v23.26h43.33c1.1,0,2.2.38,2.97,1.17,1.26,1.28,1.49,3.13.75,4.62l-.27.4c-26.1,39.18-69.8,63.96-116.9,66.29l-3.39.17v26.29c0,2.21-1.79,3.99-3.99,3.99l-89.38-2.51-125.24,2.51c-2.45,0-4.32-2.17-3.96-4.6h0c.29-1.97,1.98-3.42,3.96-3.42,0,0,64.78-3.2,105.08-4.39,40.3-1.19,105.55,4.39,105.55,4.39v-22.24h-242.12v22.24h11.28c1.52,0,2.92.87,3.59,2.23h0c1.32,2.66-.62,5.78-3.59,5.78h-15.25c-2.21,0-3.99-1.79-3.99-3.99v-26.29l-3.39-.17c-37.62-1.84-73.09-18.04-99.14-44.48-1.75-1.78-1.44-4.72.66-6.08l.05-.03c1.58-1.02,3.65-.77,4.96.57,26.48,26.99,55.42,42.41,93.65,42.41l271.26-5.24c42.17,0,67.81-13.47,94.71-45.83l4.86-5.84s-90.72-.47-165.96,1.12c-75.24,1.58-311.2-1.12-311.2-1.12l2.46,2.95c1.35,1.62,1.19,4.01-.36,5.43h0c-1.7,1.56-4.36,1.34-5.79-.47-2.47-3.12-4.82-6.36-7.04-9.7-.99-1.5-.88-3.52.4-4.93.78-.86,1.95-1.29,3.12-1.29h43.34s.19-3.36.19-3.36c2.76-48.93,27.72-87,63.37-87,2.29,0,9.73-.1,12.2.24l2.09.29,1.26-1.7c5.68-7.66,14.37-12.05,23.85-12.05,1.22,0,2.45.08,3.67.22l2.22.27,1.21-1.88c5.49-8.54,14.86-13.64,25.04-13.64,2.6,0,5.18.34,7.68,1.01l2.05.55,1.46-1.55c1.83-1.94,3.97-3.64,6.36-5.07l5.87-3.51-6.23-2.8c-13.14-5.9-22.74-17.29-26.34-31.24l-4.96-19.27s0-.02,0-.03c-.35-1.4,1.31-2.45,2.49-1.63l5.98,4.16ZM239.04,260.37l-21.47-1.04c-1.07-.05-2.05-.51-2.76-1.31-.71-.79-1.07-1.8-1.02-2.85v-.12c.14-2.12,1.82-3.71,3.93-3.71h.22s21.57,1.05,21.57,1.05c1.07.05,2.05.51,2.76,1.31.71.79,1.07,1.8,1.02,2.85-.1,2.15-1.85,3.82-3.97,3.82h-.28ZM256.19,223.99c-1.44,0-2.73-.74-3.47-1.98-1.09-1.88-.45-4.34,1.44-5.45l18.6-10.92c.6-.35,1.3-.54,2-.54,1.44,0,2.73.74,3.46,1.98,1.1,1.89.45,4.34-1.44,5.46l-18.6,10.92c-.49.29-1.03.47-1.57.53h-.43Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMittagessen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnser Mittagessen wird frisch in der Einrichtung zubereitet. Dabei legen wir Wert auf saisonale und regionale Produkte, vorzugsweise in Bio-Qualit\u00e4t.\nDie Mahlzeit besteht immer aus einem Obst- und Gem\u00fcseteller, einer Hauptspeise und einem Nachtisch. Wenn m\u00f6glich werden W\u00fcnsche der Kinder bez\u00fcglich des Speiseplans ber\u00fccksichtigt. Schlie\u00dflich soll gesunde Nahrung Schmecken und Spa\u00df machen!\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c1ec5 elementor-widget elementor-widget-text-editor\" data-id=\"07c1ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir beteiligen uns am EU Schulprogramm und beziehen unsere Lebensmittel vom Hutzelhof, einem Lieferanten f\u00fcr \u00f6kologisches Obst und Gem\u00fcse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1626a79 elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1626a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M80.31,67.88c-.88-.79-1.94-1.4-2.87-2.13-.94-.74-1.84-1.52-2.71-2.34-1.77-1.69-3.39-3.54-4.82-5.54-1.39-1.94-2.6-4-3.64-6.15-.53-1.09-1.01-2.2-1.44-3.33-.44-1.16-.75-2.38-1.25-3.52-.11-.25-.57-.25-.53.09.28,2.35,1.38,4.74,2.37,6.87,1.05,2.28,2.32,4.45,3.77,6.5,1.4,1.98,2.95,3.86,4.65,5.58.87.89,1.78,1.74,2.72,2.56.95.82,1.96,1.77,3.09,2.34.57.29,1.15-.49.66-.93Z\"><\/path><path d=\"M48.2,49.86c-.05-.06-.15-.06-.17.03-.25,1.12.3,2.58.54,3.68.28,1.31.55,2.62.82,3.93.56,2.8,1.08,5.61,1.58,8.42.5,2.83.95,5.66,1.37,8.5.41,2.82.7,5.67,1.15,8.48.11.67,1.15.69,1.09-.03-.48-5.58-1.57-11.19-2.59-16.69-.51-2.74-1.06-5.48-1.65-8.21-.31-1.42-.62-2.85-.95-4.26-.27-1.18-.41-2.88-1.19-3.84Z\"><\/path><path d=\"M79.24,68.51c-.64,1.28-1.4,2.77-2.81,3.33-1.25.49-2.66.07-3.85.82-.9.57-1.38,1.54-2.04,2.34-1.1,1.33-2.59.9-4.11,1.15-1.29.21-2.5.77-3.5,1.62-1.03.87-1.7,2.45-3.09,2.79-1.34.33-2.63,0-3.92.64-.99.49-1.95,1.32-2.24,2.42-.07.28.29.45.48.26,1.09-1.12,2.02-2.08,3.67-2.2,1.28-.1,2.51.07,3.57-.79,1.07-.86,1.67-2.09,2.86-2.84.66-.41,1.39-.71,2.16-.85.81-.15,1.63-.05,2.45-.14,1.16-.13,1.97-.72,2.66-1.63.86-1.14,1.44-2.08,2.99-2.24,1.33-.13,2.45-.21,3.52-1.11.95-.81,1.6-1.94,2.21-3.02.36-.64-.68-1.19-1.01-.53Z\"><\/path><path d=\"M70.09,60.04c-2.78,2.1-5.77,3.95-8.98,5.33-1.57.68-3.17,1.26-4.81,1.76-1.63.49-3.32.78-4.93,1.32-.2.07-.16.38.06.38,1.72-.03,3.44-.52,5.09-.99,1.7-.48,3.36-1.08,4.98-1.77,3.23-1.38,6.31-3.08,9.12-5.19.51-.38-.02-1.23-.54-.84Z\"><\/path><path d=\"M44.38,11.6c-1.27,0-2.64.65-3.76,1.22-1.24.63-2.41,1.39-3.5,2.26-2.11,1.68-3.89,3.75-5.21,6.1-2.76,4.94-3.17,10.59-1.81,16.01.13.5.93.26.77-.24-1.61-5.02-.85-10.84,1.69-15.42,1.29-2.33,3.07-4.4,5.16-6.05,1.02-.8,2.1-1.49,3.24-2.1,1.12-.6,2.39-.97,3.44-1.67.05-.03.02-.1-.03-.1Z\"><\/path><path d=\"M33.04,38.87c-1.25.19-1.87,2.13-3.38,1.64-.79-.26-1.02-1.3-.64-1.97.44-.77,1.35-.86,2.08-1.17.09-.04.14-.16.05-.23-.83-.67-2.11-.22-2.75.52-.72.83-.8,2.1-.18,3.02.6.9,1.76,1.14,2.74.81.88-.29,2.48-1.19,2.46-2.27,0-.18-.18-.39-.38-.36Z\"><\/path><path d=\"M69.89,23.09c-2.7-4.39-6.73-8.5-11.36-10.82-4.28-2.14-10.14-3.19-14.51-.69-.19.11-.04.4.16.35,2.62-.71,5.12-1.3,7.86-.96,2.29.29,4.51,1.05,6.53,2.16,2.16,1.17,4.09,2.73,5.8,4.49,1.8,1.85,3.18,3.93,4.66,6.02.38.54,1.22.02.87-.55Z\"><\/path><path d=\"M73.46,23.76c-.48-.94-1.49-1.49-2.54-1.26-.78.17-1.87.91-1.6,1.84.03.1.17.13.24.05.45-.51.76-.96,1.5-1.02.81-.06,1.44.43,1.64,1.21.49,1.88-1.41,2.94-3.01,2.91-.82-.01-.78,1.34.04,1.27,2.41-.19,5.08-2.38,3.73-5Z\"><\/path><path d=\"M42.54,12.42c-.58-.57-1.51-.74-2.15-1.29-.7-.59-1.22-1.34-1.61-2.17-.13-.28-.53-.05-.46.21.25,1.04.79,1.95,1.6,2.66.64.57,1.62,1.3,2.51,1.08.23-.06.27-.35.11-.5Z\"><\/path><path d=\"M43.64,11.28c-.34-.61-1.05-.98-1.56-1.43-.61-.55-1.21-1.21-1.59-1.94-.06-.12-.26-.03-.22.1.47,1.35,1.44,3.65,3.15,3.7.22,0,.32-.25.23-.43Z\"><\/path><path d=\"M44.67,6.2c-.46.57-.67,1.29-.77,2.01-.09.65-.25,1.47.28,1.96.13.13.38.13.5-.02.41-.49.27-1.12.29-1.72.03-.69.14-1.4.08-2.09-.01-.18-.26-.3-.39-.14Z\"><\/path><path d=\"M45.07,14.48c-.18-.22-.48-.23-.64.02-.41.67-.15,1.73-.2,2.5-.06,1.01-.21,2.02-.44,3-.46,1.91-1.19,3.81-2.09,5.55-.07.13.12.28.22.16,1.35-1.57,2.29-3.33,2.83-5.34.27-.98.44-1.97.53-2.97.08-.84.35-2.23-.22-2.92Z\"><\/path><path d=\"M46.55,16.11c-.14-.27-.64-.27-.76.03-.25.67-.12,1.38-.13,2.09-.02.78-.05,1.57-.15,2.34-.19,1.54-.55,3.06-.81,4.59-.03.15.16.22.24.09.87-1.38,1.34-2.99,1.6-4.6.12-.76.21-1.53.24-2.3.03-.75.13-1.56-.23-2.24Z\"><\/path><path d=\"M48.41,17.59c-.16-.24-.52-.23-.66.03-.51.91-.17,2.33-.16,3.35.01,1.28.04,2.56.13,3.84.01.15.21.16.25.03.38-1.21.6-2.45.68-3.72.07-1.04.37-2.63-.24-3.52Z\"><\/path><path d=\"M44.38,14.95c-.48.65-.58,1.54-.83,2.31-.31.94-.67,1.86-1.09,2.77-.81,1.76-1.8,3.43-2.95,4.98-1.1,1.47-2.34,2.82-3.68,4.08-1.46,1.37-3.09,2.49-4.65,3.74-.09.07-.03.25.09.2,3.57-1.36,6.64-4.41,8.9-7.4,1.16-1.53,2.17-3.17,3.01-4.9.43-.88.81-1.79,1.14-2.71.31-.84.85-1.92.72-2.82-.04-.29-.44-.55-.67-.25Z\"><\/path><path d=\"M68.71,21.96c-3.68.49-7.22.73-10.87-.2-1.78-.45-3.5-1.12-5.12-1.99-.78-.42-1.55-.87-2.28-1.37-.67-.46-1.34-1.23-2.15-1.39-.19-.04-.4.14-.32.34.28.74,1.07,1.18,1.7,1.62.8.56,1.64,1.08,2.51,1.52,1.7.86,3.5,1.51,5.35,1.94,3.58.83,7.72,1.06,11.2-.27.1-.04.09-.21-.03-.2Z\"><\/path><path d=\"M38.66,29.76c-.64.79-.77,1.86-.34,2.78.35.75,1.29,1.7,2.17,1.14.16-.1.22-.33.11-.49-.28-.4-.75-.58-1.03-.98-.4-.57-.32-1.28.15-1.78,1.1-1.17,2.73-.37,3.67.57.16.16.43-.02.37-.23-.67-2.25-3.62-2.82-5.11-.99Z\"><\/path><path d=\"M60.2,25.79c-.35-.85-1.12-1.55-2.03-1.71-1.8-.32-3.63,1.67-2.82,3.41.12.24.49.09.48-.15-.03-1.18,1.01-2.82,2.38-2.17.5.24.85.75.96,1.28.12.52-.19,1.03.07,1.5.1.17.31.22.49.18.93-.21.72-1.72.45-2.35Z\"><\/path><path d=\"M59.79,33.12c-.14-.29-.59-.29-.79-.07-.43.48-.4,1.16-.59,1.76-.23.71-.57,1.39-.98,2.01-.78,1.17-1.87,2.14-3.13,2.77-2.85,1.41-5.99.88-8.66-.65-.23-.13-.45.2-.27.38,2.38,2.32,6.36,2.76,9.32,1.39,1.47-.68,2.74-1.76,3.67-3.09.73-1.04,2.05-3.21,1.42-4.49Z\"><\/path><path d=\"M70.31,17.79c-1.1-1.41-4.05-.94-5.32-.03-.25.18-.08.66.24.53.82-.34,1.63-.62,2.53-.59.83.02,1.55.45,2.35.47.18,0,.32-.23.2-.38Z\"><\/path><path d=\"M72.63,15.35c-.15-.18-.41-.2-.54.02-.27.48-.21,1.01-.29,1.55-.11.68-.32,1.32-.66,1.92-.74,1.31-1.71,1.85-2.95,2.57-.12.07-.05.26.08.25,1.38-.05,2.77-1.19,3.54-2.27.67-.93,1.71-2.98.83-4.04Z\"><\/path><path d=\"M70.56,13.94c-1.31.65-2.27,2.1-2.13,3.58.03.34.58.44.63.06.16-1.21.65-2.39,1.85-2.9.58-.25,1.26-.3,1.88-.17.48.1.86.38,1.35.35.17-.01.36-.2.28-.39-.57-1.29-2.82-1.05-3.85-.53Z\"><\/path><path d=\"M77.44,12.25c-.15-.17-.45-.13-.59.02-.33.36-.28.8-.43,1.24-.19.58-.57,1.13-1.03,1.53-.44.38-.97.65-1.54.76-.47.1-.92.04-1.32.33-.06.05-.08.12-.04.19.7,1.2,2.86.1,3.62-.5.86-.67,2.3-2.52,1.34-3.59Z\"><\/path><path d=\"M75.39,9.98c-1.16.58-2.67,2.77-1.64,4,.05.06.16.04.2,0,.41-.46.48-1.11.78-1.65.32-.59.74-1,1.25-1.43.54-.44.05-1.24-.58-.92Z\"><\/path><path d=\"M30.89,25.45c-.46-.88-2.03-1.03-2.92-.96-1.19.09-2.04.62-2.72,1.58-.09.12.06.28.18.17.67-.67,1.75-1.05,2.67-1.07.49-.01.96.07,1.4.3.36.18.61.44,1,.54.33.09.53-.29.39-.55Z\"><\/path><path d=\"M30.1,28.85c-.51-.02-.99.17-1.5.18-.6,0-1.19-.11-1.74-.35-1.07-.46-1.78-1.31-2.4-2.26-.1-.15-.38-.09-.35.11.19,1.33,1.17,2.35,2.33,2.96,1.04.55,2.91,1.06,3.94.26.38-.29.22-.88-.27-.89Z\"><\/path><path d=\"M23.96,23.77c-1.42.08-2.55.72-3.3,1.92-.05.07.07.15.12.09.82-.9,2.17-1.33,3.37-1.21.56.06,1.11.23,1.59.53.42.26.68.61,1.18.65.19.02.34-.19.34-.36-.02-1.32-2.32-1.69-3.3-1.63Z\"><\/path><path d=\"M24.81,27.34c-.95.61-2.21.75-3.3.49-.48-.12-.96-.28-1.38-.53-.51-.3-.81-.76-1.27-1.12-.41-.32-1.11.02-.92.58.44,1.27,2.13,2.05,3.38,2.16,1.42.12,2.66-.35,3.65-1.37.1-.11-.04-.28-.17-.2Z\"><\/path><path d=\"M18.92,22.49c-1.2-.05-3.21.39-3.42,1.84-.03.22.15.41.38.35,1.11-.29,1.85-1.02,3.07-.97,1.05.05,2.05.55,2.92,1.1.15.1.33-.08.28-.23-.43-1.41-1.85-2.03-3.24-2.09Z\"><\/path><path d=\"M18.72,26.9c-.37,0-.74-.05-1.11-.05-.41,0-.83-.04-1.2-.23-.26-.14-.48-.36-.61-.63-.11-.23-.14-.41-.28-.56-.03-.06-.06-.12-.1-.19-.1-.14-.28-.18-.43-.09-.94.52-.27,1.85.52,2.34.47.29,1.02.4,1.57.35.68-.06,1.15-.3,1.74-.6.17-.09.06-.33-.1-.33Z\"><\/path><path d=\"M56.36,47.96c-1.14.26-2.2.77-3.35,1.02-1.19.27-2.45.41-3.68.44-2.37.05-4.78-.34-6.98-1.22-2.04-.81-3.92-2-5.53-3.48-.8-.74-1.54-1.55-2.18-2.42-.34-.46-.66-.94-.96-1.43-.28-.46-.47-.96-.89-1.31-.36-.3-.98-.08-.96.44.05,1.08,1,2.21,1.63,3.05.72.97,1.53,1.88,2.42,2.7,1.74,1.6,3.79,2.86,6.01,3.68,2.38.87,4.94,1.22,7.47,1.01,1.27-.11,2.49-.34,3.71-.71,1.16-.35,2.45-.74,3.4-1.52.11-.09.04-.27-.11-.24Z\"><\/path><path d=\"M69.36,28.56c-.1.45-.01.87-.01,1.33,0,.54-.03,1.08-.08,1.62-.09,1.08-.27,2.15-.53,3.21-.49,2.01-1.27,3.94-2.35,5.7-1.14,1.84-2.67,3.53-4.43,4.78-.87.62-1.82,1.15-2.8,1.56-1.02.43-2.11.62-3.13,1.02-.2.08-.16.36.06.38,2.11.12,4.45-1.11,6.16-2.23,1.89-1.24,3.51-2.8,4.79-4.67,1.24-1.82,2.13-3.87,2.69-6,.3-1.14.51-2.31.64-3.48.11-1,.38-2.28.12-3.25-.15-.57-1-.51-1.13.04Z\"><\/path><path d=\"M58.45,47.8c-.35-.6-1.27-.02-.91.58.71,1.16.11,2.88-1.27,3.2-1.49.35-2.4-.95-2.69-2.21-.07-.28-.51-.26-.57.02-.34,1.86,1.88,3.48,3.6,3.1,2.04-.45,2.85-2.99,1.84-4.69Z\"><\/path><path d=\"M76.83,8.39c-.68.14-2.07,1.28-1.06,1.93.03.02.08.03.12.03.22.96.48,2.1,1.59,2.15,1.18.06,1.67-1.44,1.52-2.39-.17-1.07-1.03-1.96-2.17-1.72ZM78.28,10.28c.15.76-.5,2.25-1.36,1.33-.4-.43-.47-1.04-.64-1.6.17-.21.32-.44.59-.57.66-.31,1.28.16,1.41.83Z\"><\/path><path d=\"M76.13,8.65c-.77-.54-1.61-.95-2.43-1.4-.37-.2-.74-.42-1.1-.65-.4-.25-.67-.53-1.16-.47-.31.03-.51.29-.43.6.21.83,1.53,1.31,2.23,1.68.87.45,1.78.78,2.76.88.38.04.38-.47.15-.64Z\"><\/path><path d=\"M75.45,2.56c-.14-.16-.37-.06-.46.08-.51.76-.08,2.01.08,2.86.21,1.1.51,2.21,1.07,3.19.16.28.7.15.64-.2-.17-1.06-.48-2.08-.68-3.13-.17-.88-.03-2.1-.65-2.8Z\"><\/path><path d=\"M75.68,2.33c-.87.27-1.55,1.18-2.2,1.79-.82.76-1.71,1.5-2.4,2.38-.18.23.07.59.35.41.87-.57,1.63-1.3,2.4-2,.7-.62,1.82-1.32,2.18-2.2.09-.21-.08-.47-.33-.4Z\"><\/path><path d=\"M78.56,11.08c-.05-.3-.47-.31-.48.01-.05,1.22.14,2.41.44,3.58.25.97.52,2.37,1.27,3.07.15.14.41.02.4-.18-.05-.97-.69-1.98-.95-2.93-.32-1.16-.49-2.36-.68-3.55Z\"><\/path><path d=\"M81.12,12.83c-.77-.55-1.57-1.05-2.4-1.51-.26-.15-.5.21-.3.42.71.72,1.46,1.41,2.25,2.05.6.48,1.22,1.21,2.02,1.24.23,0,.39-.24.32-.45-.24-.79-1.26-1.28-1.91-1.74Z\"><\/path><path d=\"M83.32,13.63c-.85.14-1.44.73-2.06,1.3-.73.67-1.34,1.37-1.77,2.27-.09.19.12.39.3.28.74-.46,1.36-1.02,2.02-1.58.64-.55,1.43-1.02,1.8-1.8.09-.19-.04-.51-.29-.47Z\"><\/path><path d=\"M84.57,0c-.9-.02-1.77,1.03-2.34,1.6-1.49,1.49-3.18,3.6-3.56,5.74-.05.29.34.56.55.29.94-1.2,1.63-2.57,2.62-3.75.48-.57,1-1.11,1.55-1.62.31-.29.64-.66,1.01-.87.11-.08.24-.13.38-.16.03,0,.05,0,.07-.01.17.11.44.07.53-.13.25-.56-.21-1.08-.8-1.09Z\"><\/path><path d=\"M86.44,3.39c-1.02-.6-2.8.63-3.64,1.22-1.05.74-2.22,1.78-2.5,3.08-.03.13.11.22.22.16,1.11-.61,2-1.59,3.09-2.26.57-.35,1.17-.65,1.8-.89.5-.19.92-.3,1.19-.8.1-.19.02-.41-.16-.52Z\"><\/path><path d=\"M86.97,7.06c-.9-.35-1.78-.02-2.64.33-.91.37-1.85.85-2.46,1.64-.21.27,0,.76.39.62.83-.31,1.59-.79,2.42-1.1.77-.29,1.65-.33,2.31-.85.2-.15.26-.53-.03-.64Z\"><\/path><path d=\"M15.38,23.8c-.69-1.26-2.46-1.01-3.18.07-.75,1.13-.51,2.84.93,3.22.59.16,1.2.04,1.65-.39.36-.35.68-.95.47-1.44.26-.44.34-1.06.12-1.46ZM13.64,26.5c-.91-.03-1.2-1.07-.95-1.8.23-.68.88-1.2,1.61-.94,1.08.39.47,1.43-.27,1.76-.06.02-.07.09-.01.13.2.13.38.17.56.15-.16.39-.36.72-.93.7Z\"><\/path><path d=\"M14.72,18.04c-.19.03-.31.22-.37.39-.32.99-.52,2-.59,3.04-.04.65-.2,1.69.41,2.11.04.03.1,0,.13-.02.39-.33.33-.86.39-1.34.09-.79.18-1.56.36-2.34.13-.54.78-2.04-.33-1.84Z\"><\/path><path d=\"M18.59,20.15c-.77.33-1.37,1.07-1.95,1.67-.73.75-1.39,1.55-2.05,2.36-.06.08.03.2.12.14.76-.57,1.5-1.14,2.21-1.77.67-.6,1.56-1.25,1.95-2.06.08-.16-.08-.42-.27-.33Z\"><\/path><path d=\"M17.58,18.59c-.8-.63-1.76-.97-2.78-.81-.28.04-.39.47-.06.54.82.16,1.64.47,2.28,1.03.53.47.76,1.36,1.35,1.69.14.08.37.02.43-.13.35-.85-.61-1.84-1.22-2.32Z\"><\/path><path d=\"M12.39,26.36c-.92.79-1.46,1.83-1.96,2.92-.37.81-1.12,2.01-.85,2.91.04.15.24.23.37.14.79-.58.96-1.9,1.35-2.77.46-1.03.99-2,1.25-3.1.02-.1-.1-.15-.16-.09Z\"><\/path><path d=\"M14.05,29.67c-.28-.98-.48-1.99-.64-3-.02-.12-.21-.17-.23-.02-.14.98-.13,1.95.05,2.93.17.88.37,2.15,1.1,2.74.19.15.46.03.47-.21.02-.8-.52-1.66-.74-2.43Z\"><\/path><path d=\"M14.8,31.7c-.77-.18-1.6.15-2.37.23-.87.09-1.75.11-2.63.1-.25,0-.26.34-.04.41.93.29,1.89.42,2.86.39.8-.03,1.72-.05,2.34-.59.19-.17.05-.48-.16-.53Z\"><\/path><path d=\"M10.95,23.47c-.82-.9-1.77-1.63-2.73-2.37-.86-.66-1.79-1.57-2.8-1.97-.61-.24-1.09.43-.65.92.72.82,1.87,1.39,2.79,1.99,1.01.66,2.01,1.32,3.13,1.8.25.11.45-.18.27-.38Z\"><\/path><path d=\"M9.88,24.02c-.89-.48-1.84-.69-2.82-.89-.69-.14-1.75-.6-2.28.03-.07.09-.11.21-.07.32.29.79,1.36.71,2.08.82,1.01.15,1.98.28,3,.13.21-.03.31-.31.1-.42Z\"><\/path><path d=\"M10.03,25.69c-.89-.2-1.79-.17-2.7-.21-.88-.04-1.88-.29-2.7.09-.21.1-.32.36-.12.54.72.64,1.78.59,2.69.59,1.01,0,2-.1,2.91-.55.2-.1.12-.41-.08-.46Z\"><\/path><path d=\"M82.85,34.66c-.72.5-1.21,1.29-1.8,1.92-.68.72-1.39,1.4-2.14,2.06-1.5,1.32-3.1,2.5-4.83,3.51-3.28,1.92-6.75,3.09-10.42,3.93l.2.64c3.68-.58,7.29-2.01,10.51-3.82,1.76-1,3.48-2.13,5.05-3.41.76-.62,1.5-1.27,2.21-1.95.68-.66,1.55-1.33,1.97-2.2.21-.44-.29-.99-.74-.68Z\"><\/path><path d=\"M87.37,36.2c-.8.62-1.41,1.44-2.14,2.14-.86.83-1.76,1.63-2.69,2.38-1.72,1.39-3.55,2.64-5.45,3.75-1.92,1.12-3.93,2.09-6,2.91-2.1.83-4.36,1.28-6.42,2.17-.19.08-.17.39.06.39,2.24-.06,4.54-.96,6.61-1.74,2.1-.8,4.13-1.77,6.08-2.89,2.01-1.15,3.93-2.46,5.73-3.91.87-.7,1.72-1.43,2.54-2.19.81-.75,1.72-1.47,2.32-2.41.24-.37-.29-.86-.64-.59Z\"><\/path><path d=\"M84.62,33.44c-1.16-1.56-2.79-2.77-4.52-3.64-.28-.14-.59.12-.51.42.56,2.07,2.02,4.35,4.21,4.93.1.03.17-.11.09-.17-1.41-1.25-2.65-2.4-3.33-4.1,1.33.82,2.43,1.84,3.5,3.02.27.3.8-.13.55-.46Z\"><\/path><path d=\"M91.21,25.23c-1.55,1-2.95,2.21-4.13,3.64-1.03,1.24-2.34,2.95-2.62,4.57-.04.23.28.47.45.24.44-.61.71-1.33,1.09-1.98.48-.82,1.03-1.59,1.64-2.32.86-1.03,1.83-1.95,2.9-2.75-.31.64-.67,1.26-1.09,1.84-.63.88-1.42,1.59-2.15,2.38-.27.29.11.78.46.55,1.92-1.3,3.25-3.63,4.04-5.76.12-.33-.32-.59-.59-.42Z\"><\/path><path d=\"M93.79,27.72c-1.14.38-2.24.84-3.3,1.39-1,.52-2.2,1.12-2.87,2.05-.1.14,0,.38.2.31.99-.34,1.86-1.05,2.79-1.54.74-.39,1.5-.73,2.29-1.02-.45.57-.97,1.07-1.58,1.49-.65.44-1.72.58-2.12,1.27-.06.1-.01.24.09.29.84.42,2.08-.51,2.74-1,.95-.71,1.7-1.6,2.27-2.64.17-.31-.15-.7-.49-.59Z\"><\/path><path d=\"M95.16,30.99c-1.9.13-4.01.33-5.76,1.15-.23.11-.09.49.14.46,1.68-.15,3.32-.54,4.99-.72-.74,1.32-2.54,1.37-3.93,1.51-.55.06-.54.87.02.87,1.97-.03,4.38-.59,4.95-2.75.07-.26-.15-.53-.42-.52Z\"><\/path><path d=\"M90.9,34.21s-.08.04-.05.08c.26.35,2.02,1.9,1.86,2.22-.15.29-.86-.27-.96-.38-.17-.17-.32-.33-.52-.46-.25-.17-.54-.28-.84-.34-1.37-.27-3.61.57-3.84,2.09-.04.23.14.38.36.34,1.26-.24,1.74-1.8,3.15-1.8,1.1,0,1.56,1.51,2.66,1.27,1.86-.41-1.05-2.82-1.83-3.02Z\"><\/path><path d=\"M49,53.82c-.91,0-1.89.66-2.66,1.1-.98.56-1.91,1.21-2.78,1.93-1.41,1.17-2.75,2.62-2.94,4.52-.17,1.66.46,3.38,1.75,4.46,1.02.86,2.95,1.59,4.22.86.07-.04.05-.16-.03-.17-.72-.18-1.45-.14-2.16-.43-.59-.24-1.19-.62-1.64-1.07-1.12-1.12-1.49-2.86-.99-4.36.55-1.64,2.08-2.87,3.44-3.83.63-.45,1.29-.87,1.97-1.24.7-.38,1.54-.6,2.12-1.16.24-.24.02-.63-.29-.63Z\"><\/path><path d=\"M46.66,66.08c-.48.39-.65.9-1.3,1.13-.76.27-1.6.12-2.38,0-.3-.05-.42.41-.11.47.94.19,1.95.39,2.88.03.57-.22,1.37-.74,1.28-1.43-.02-.16-.21-.33-.37-.2Z\"><\/path><path d=\"M48.22,51.55c-4.91,1.32-8.91,5.13-10.27,10.06-.65,2.35-.75,4.86-.52,7.28.22,2.37.67,4.82,1.67,6.98.04.09.16.01.15-.07-.43-2.31-1.09-4.56-1.28-6.92-.18-2.25-.05-4.52.58-6.7,1.38-4.79,5.08-8.53,9.95-9.73.59-.14.31-1.05-.27-.9Z\"><\/path><path d=\"M39.26,69.25c-.12-.13-.33-.06-.41.07-.49.84-.04,2.21.02,3.14.07,1.12-.02,2.33.29,3.42.06.2.33.17.39-.01.35-1.14.21-2.43.18-3.61-.03-.94.18-2.26-.47-3.01Z\"><\/path><path d=\"M40.75,68.88c-.14-.29-.62-.06-.52.24.64,1.92,1.17,3.76,1.35,5.76-1.22-1.51-1.85-3.23-2.28-5.17-.05-.21-.35-.14-.36.06-.01,2.32,1.2,4.57,2.79,6.21.19.19.53.02.52-.24-.08-2.31-.49-4.77-1.51-6.86Z\"><\/path><path d=\"M42,67.91c-.25-.41-.89,0-.63.4,1.08,1.68,1.91,3.44,2.51,5.32-1.56-1.11-2.47-2.83-2.81-4.74-.03-.19-.31-.12-.32.05-.07,2.41,1.44,4.54,3.52,5.67.25.13.52-.11.45-.37-.6-2.23-1.52-4.37-2.73-6.34Z\"><\/path><path d=\"M44.61,69c-.48-.79-1.12-1.88-2.02-2.23-.37-.14-.68.19-.5.54.39.81,1.28,1.42,1.84,2.13.43.55.78,1.15,1.07,1.78-1.35-.87-2.23-2.1-3.07-3.54-.09-.16-.32-.03-.28.13.41,2,2.13,3.61,3.9,4.49.25.13.59-.11.49-.4-.36-1.02-.85-1.97-1.41-2.9Z\"><\/path><path d=\"M61.66,80.3c-.16-.18-.48-.09-.58.1-.28.54-.11.99-.02,1.57.11.74.18,1.49.23,2.24.1,1.44.12,2.88-.18,4.29-.25,1.18-.7,2.32-1.37,3.34-.76,1.14-1.76,1.81-2.84,2.6-.2.15-.06.45.18.39,2.4-.58,3.99-3.44,4.61-5.62.41-1.46.55-3.02.54-4.53,0-.83-.07-1.65-.14-2.48-.05-.71.04-1.35-.44-1.9Z\"><\/path><path d=\"M59.16,95.04c-.37-.12-.74.21-1.11-.04-.3-.2-.33-.74-.16-1.03.06-.1-.08-.25-.18-.17-.25.21-.42.36-.47.71-.05.37.05.76.31,1.04.26.28.64.44,1.02.41.36-.03.84-.23.81-.66,0-.13-.09-.23-.22-.27Z\"><\/path><path d=\"M64.41,77.75c-.38-.64-1.35-.02-.97.62,1.8,3.03,1.13,6.62.18,9.82-.42,1.39-.88,2.77-1.64,4.02-.79,1.3-1.85,2.04-3.07,2.9-.16.12-.1.4.12.39,3.06-.18,4.66-4.35,5.44-6.78,1.12-3.5,1.92-7.62-.07-10.97Z\"><\/path><path d=\"M61.62,96.59c-.45-.16-.91-.22-1.38-.31-.64-.12-1.14-.35-1.72-.63-.3-.14-.76.14-.6.5.39.89,1.33,1.06,2.22,1.14.66.06,1.62.07,1.98.75.47.89-.65,1.13-1.3,1.07-1.3-.11-2.58-.94-3.45-1.88-.44-.48-.83-1.05-1.06-1.65-.11-.29-.25-.7-.15-1.01.21-.7.79-.57,1.14-.17.12.14.35.04.38-.12.16-.63-.49-1.04-1.07-1.02-.8.02-1.29.71-1.32,1.46-.1,2.05,1.99,4.02,3.7,4.79,1.23.55,3.98,1.05,4.2-.97.11-.98-.74-1.66-1.57-1.96Z\"><\/path><path d=\"M86.15,88.38c-2.99-1.25-5.5-2.97-7.85-5.21-1.2-1.15-2.4-2.31-3.49-3.56-1.37-1.57-2.24-3.17-2.74-5.19-.07-.3-.55-.22-.53.09.17,3.62,3.72,6.59,6.15,8.9,2.32,2.21,5.11,4.7,8.42,5.07.05,0,.09-.07.04-.09Z\"><\/path><path d=\"M86.21,86.46c-.45-.61-1.23-.98-1.84-1.39-.91-.61-1.78-1.26-2.62-1.97-1.57-1.32-3-2.83-4.18-4.51-1.2-1.72-1.98-3.66-2.65-5.63-.19-.57-1.06-.31-.9.28.81,2.97,2.67,5.69,4.71,7.95,1.09,1.21,2.31,2.32,3.61,3.31.59.45,1.2.88,1.83,1.28.62.4,2.91,1.74,1.1,2.45-.15.06-.21.3-.04.38.46.21.87.02,1.13-.41.35-.56.23-1.22-.15-1.73Z\"><\/path><path d=\"M88.88,81.59c-.81.2-1.2.98-1.45,1.71-.22.63-.34,1.29-.55,1.93-.21.67-.47,1.29-.57,1.99-.09.6.76.81.92.22.33-1.23.41-2.49.75-3.72.09-.32.17-.69.35-.98.43-.7,1.22-.91,1.54.22.13.48,0,1.23-.07,1.69-.18,1.09-.61,2.12-1.27,3.01-.4.55-.92,1.15-1.59,1.36-.93.29-1.48-.36-1.56-1.2-.01-.12-.17-.2-.25-.1-.36.45-.16,1.01.21,1.39.51.52,1.23.6,1.89.35,1.72-.64,2.77-2.88,3.1-4.55.22-1.11.45-3.79-1.45-3.33Z\"><\/path><path d=\"M53.08,55.51c-.49.16-.87.58-1.04,1.06-.16.46-.03,1.05.48,1.21,0,0,0,0,0,0,.2.25.48.44.77.53.88.24,1.56-.53,1.53-1.37-.03-.9-.8-1.74-1.75-1.43ZM54.26,56.92c.06.5-.29,1.04-.85.89-.23-.07-.42-.22-.55-.42.03-.12.08-.25.13-.36.07-.19.17-.35.34-.48.41-.32.87-.15.93.38Z\"><\/path><path d=\"M61.28,51.3c-.88.19-1.91,1.43-1.03,2.21.08.07.18.07.25.03.15.32.43.59.77.73.9.37,1.68-.41,1.73-1.28.06-.99-.67-1.92-1.72-1.69ZM62.33,52.88c.05.5-.31,1.02-.86.89-.32-.07-.6-.33-.74-.63.14-.32.36-.65.67-.8.44-.22.88.06.93.54Z\"><\/path><path d=\"M57.78,58.24c-.94.17-1.91,1.46-1.09,2.29.15.15.4.05.45-.13.14.25.37.47.63.6.81.4,1.59-.27,1.63-1.1.05-.92-.62-1.83-1.61-1.66ZM58.9,59.78c.04.53-.36,1.07-.93.84-.33-.13-.59-.47-.64-.82.11-.26.28-.49.56-.63.49-.25.97.09,1.01.61Z\"><\/path><path d=\"M65.67,58.58c-.53-.07-1.14.19-1.25.75-.01.07.08.13.13.07.21-.28.58-.49.95-.42.37.07.59.45.47.8-.11.33-.41.42-.71.29-.13-.06-.24-.15-.36-.23-.04-.03-.08-.06-.13-.09.04.03.05.03.02-.02-.06-.07-.12-.15-.18-.21-.09-.09-.29-.09-.36.02-.5.7.27,1.54,1,1.6.75.06,1.32-.51,1.37-1.24.05-.61-.29-1.22-.94-1.31Z\"><\/path><path d=\"M56.66,63.42c-.42-.29-.95-.32-1.41-.13-.14.06-.28.15-.4.26-.04,0-.08,0-.12.03-.09.05-.17.14-.23.21-.15.17-.24.36-.29.58-.1.45-.03.96.24,1.34.55.79,1.72.79,2.41.18.77-.67.64-1.93-.19-2.49ZM56.23,65.39c-.39.28-1.01.25-1.24-.23-.09-.19-.1-.39-.06-.59.34-.27.76-.76,1.25-.46.48.29.49.98.05,1.29Z\"><\/path><path d=\"M46.48,38c-.5.14-.81.53-1.23.82-.39.27-.82.45-1.25.64,0-.03,0-.05,0-.08,0-.03-.04-.05-.05-.03-.11.09-.21.18-.32.27-.2.1-.07.39.12.4,1.01.04,2.82-.6,3.01-1.74.03-.17-.12-.33-.3-.28Z\"><\/path><path d=\"M61.34,32.71c-.35-.29-.79-.07-1.2-.04-.49.04-.96-.03-1.44-.04-.21,0-.35.32-.17.45.45.33,1.01.45,1.56.46.47,0,1.19-.01,1.34-.55.03-.1-.01-.22-.09-.29Z\"><\/path><path d=\"M54.31,31.48c-2.55,1.19-5.04-.82-5.06-3.47,0-.11-.17-.13-.19-.02-.44,2.94,2.5,5.01,5.14,4.08-.02.64-.28,1.22-.73,1.69-.41.43-.97.59-1.4.98-.18.16-.07.52.17.55,1.77.21,2.63-2.21,2.47-3.61-.02-.21-.21-.29-.39-.21Z\"><\/path><path d=\"M59.46,35.95c-.11.02-.23.12-.18.25.23.54.76.84,1.04,1.37.4.77.46,1.7.05,2.48-.43.82-1.31,1.21-2.2,1.22-.99,0-1.64-.47-2.35-1.09-.05-.05-.16,0-.13.08.76,1.92,3.79,1.77,4.95.38.63-.76.77-1.82.57-2.76-.16-.77-.79-2.07-1.75-1.92Z\"><\/path><path d=\"M59.01,39.21c-.19.04-.33-.07-.49-.19-.19-.13-.33-.38-.55-.47-.18-.07-.48-.02-.5.23-.05.44.32.76.72.86.15.04.34.07.5.03.02,0,.07-.02.07-.03.04,0,.08-.01.12-.02.08-.03.16-.06.24-.08.22-.07.11-.38-.1-.33Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-085211b e-flex e-con-boxed e-con e-parent\" data-id=\"085211b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-38c1ac7 e-con-full e-flex e-con e-child\" data-id=\"38c1ac7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d314c4b elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d314c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M50.43,39.07c-.75-.82-2.09-.8-2.66.07-.11.08-.21.17-.29.29-.29.41-.38.95-.3,1.44.2,1.18,1.44,1.68,2.48,1.22,1.18-.52,1.68-2.01.76-3.02Z\"><\/path><path d=\"M62.84,40.99c-.68-.34-1.47-.19-2.03.26-1.02.49-1.55,2.01-.78,2.99,1.03,1.31,3.44.86,3.87-.77.25-.94-.18-2.05-1.07-2.48Z\"><\/path><path d=\"M63.04,52.65c-.06-.45-.65-.87-1.02-.42-.72.87-.9,1.94-1.43,2.95-.58,1.13-1.31,2.16-2.21,3.05-2.13,2.11-5.26,3.27-8.25,2.6-6.16-1.38-8.18-8.69-7.27-14.12.04-.27-.31-.46-.46-.19-3.18,5.49.85,13.89,6.73,15.68,3.11.94,6.59.17,9.16-1.76,2.04-1.53,5.11-5.03,4.75-7.79Z\"><\/path><path d=\"M42.1,27.08c-.17,0-.34,0-.51,0-.14,0-.25-.03-.35.09-.04.05-.04.1,0,.15.09.12.2.09.35.09.17,0,.34,0,.51,0,.2,0,.2-.32,0-.32Z\"><\/path><path d=\"M75.43,37.17c-1.75-4.21-4.97-7.73-8.85-10.09-8.18-4.98-19.29-4.14-27.16,1.28.23-.25.47-.49.71-.73.08-.09-.04-.2-.13-.13-.85.7-1.65,1.46-2.42,2.26-.85.72-1.66,1.5-2.4,2.34-.16.18-.13.39,0,.52-4.64,6.29-6.76,14.38-4.6,22.09,1.24,4.41,3.96,8.49,7.7,11.15,4.42,3.15,10.19,4.23,15.54,4.15,4.9-.07,9.94-1.26,13.97-4.13,4.19-2.98,6.82-7.54,8.14-12.44,1.42-5.28,1.63-11.15-.5-16.27ZM75.49,49.64c-.76,4.77-2.59,9.6-6,13.12-3.33,3.44-7.99,5.24-12.69,5.79-9.6,1.12-19.82-2.08-24.15-11.3-4.06-8.64-1.64-17.71,3.57-24.99,3.7-3.04,7.53-5.55,12.25-6.76,4.59-1.18,9.46-1.04,13.9.65,4.25,1.62,8.07,4.59,10.52,8.45,2.84,4.47,3.42,9.88,2.6,15.04Z\"><\/path><path d=\"M91.24,16.18c-2.05.71-3.62,3.02-5.08,4.56-1.69,1.78-3.43,3.54-4.78,5.6-.12.18.12.41.29.29,2.08-1.33,3.87-3.04,5.68-4.71,1.56-1.45,3.88-2.97,4.63-5.02.15-.42-.32-.87-.73-.73Z\"><\/path><path d=\"M71.33,4.31c-1.35,1.83-1.97,4.25-2.6,6.4-.65,2.2-1.17,4.43-1.36,6.72-.03.4.53.42.66.09.86-2.21,1.53-4.49,2.28-6.74.69-2.04,1.65-4.07,1.93-6.22.07-.54-.66-.58-.91-.25Z\"><\/path><path d=\"M50.9,6.89c-.52-2.21-1-4.46-2.12-6.46-.21-.37-.8-.2-.8.22,0,2.29.68,4.5,1.31,6.69.62,2.19,1.25,4.34,2.22,6.4.13.28.6.14.58-.16-.16-2.28-.67-4.47-1.19-6.69Z\"><\/path><path d=\"M26.92,28.52c-1.84-3.01-3.8-5.47-6.62-7.66-1.37-1.07-2.84-2.02-4.37-2.84-1.39-.74-3.06-1.75-4.67-1.76-.56,0-.98.8-.49,1.19,1.15.94,2.66,1.3,3.98,1.98,1.46.74,2.85,1.61,4.17,2.58,2.66,1.93,5.35,4.4,7.38,6.99.28.35.84-.1.61-.47Z\"><\/path><path d=\"M18.63,47.14c-3.41.37-6.65,1.08-9.86,2.36-2.87,1.14-6.3,2.47-8.56,4.62-.58.55.16,1.28.78,1.02,3.02-1.27,5.71-3.26,8.79-4.5,2.89-1.16,5.91-2.16,8.93-2.92.31-.08.26-.61-.08-.58Z\"><\/path><path d=\"M24.21,59.39c-2.72,2.21-5.44,4.41-8.07,6.72-1.26,1.11-2.52,2.23-3.77,3.35-1.18,1.06-2.53,2.04-3.28,3.46-.23.44.22.81.64.63,1.47-.63,2.58-1.92,3.74-3.01,1.23-1.15,2.44-2.3,3.65-3.47,2.52-2.42,4.92-4.94,7.34-7.45.15-.16-.07-.38-.24-.24Z\"><\/path><path d=\"M44.45,77.25c-1.09,3.45-1.86,6.91-2.28,10.5-.21,1.82-.35,3.65-.42,5.47-.07,1.74-.26,3.56.37,5.22.12.31.56.34.67,0,.47-1.46.33-2.97.36-4.48.03-1.83.13-3.66.29-5.48.32-3.72.81-7.44,1.44-11.11.05-.28-.35-.4-.44-.12Z\"><\/path><path d=\"M67.03,99.21c-.54-1.61-1.8-2.98-2.68-4.43-1-1.63-1.92-3.31-2.76-5.04-1.68-3.45-2.76-7.09-4.26-10.6-.12-.28-.55-.12-.56.15,0,.36,0,.72,0,1.09,0,.12.11.18.21.18.61,3.29,1.98,6.52,3.39,9.51.86,1.84,1.83,3.63,2.88,5.36.89,1.47,1.75,3.23,3.15,4.27.31.23.76-.15.64-.5Z\"><\/path><path d=\"M90.22,81.39c-1.11-1.27-2.67-2.03-4.05-2.96-1.54-1.04-3.06-2.13-4.54-3.27-2.93-2.25-5.61-4.88-8.64-6.99-.2-.14-.48.14-.34.33,2.18,2.98,5.26,5.45,8.16,7.71,1.33,1.04,2.69,2.04,4.08,3.01,1.53,1.07,3.1,2.38,4.94,2.84.4.1.66-.37.39-.67Z\"><\/path><path d=\"M99.68,48.45c-2.63-.95-5.69-.85-8.46-.9-2.27-.04-4.65-.11-6.92.2.02-.01.05-.03.07-.04.11-.07.01-.22-.1-.17-.25.15-.51.26-.78.34-.25.05-.49.09-.74.15-.38.06-.39.73,0,.78,2.79.38,5.65.18,8.46.29,2.78.11,5.69.62,8.46.23.48-.07.36-.73,0-.86Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d55a83 elementor-absolute elementor-hidden-tablet elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6d55a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><g><path d=\"M57.6,33.4s-.02-.12-.08-.08c-1.15.83-1.91,2.08-2.4,3.4-.24.65-.43,1.32-.53,2.01-.09.62-.21,1.44.05,2.03.09.19.34.17.4-.03.16-.59.04-1.28.1-1.89.07-.68.21-1.36.44-2.01.45-1.27,1.21-2.35,2.01-3.42Z\"><\/path><path d=\"M70.84,51.24s.13,0,.1-.06c-.56-1.3-1.62-2.32-2.79-3.08-.58-.38-1.2-.71-1.84-.96-.58-.22-1.36-.52-1.99-.39-.21.04-.24.3-.05.4.54.29,1.24.32,1.82.51.65.22,1.28.5,1.86.87,1.14.71,2.03,1.7,2.89,2.71Z\"><\/path><path d=\"M38.49,38.18c-.06.02-.11-.06-.06-.1,1.14-.83,2.57-1.17,3.97-1.23.69-.03,1.39,0,2.08.12.62.11,1.44.24,1.91.68.15.14.05.38-.16.37-.61-.03-1.23-.36-1.83-.49-.67-.14-1.36-.22-2.04-.2-1.34.03-2.61.43-3.87.86Z\"><\/path><path d=\"M57.16,39.38c-.01-.61.01-1.21.09-1.82.14-1.23.42-2.46.92-3.6.03-.06-.06-.1-.09-.04-.58,1.13-1.04,2.31-1.24,3.57-.18,1.11-.34,2.55.05,3.62.06.16.35.17.36-.03.04-.56-.08-1.13-.09-1.69Z\"><\/path><path d=\"M60.02,41.01c-.05-.51-.35-.98-.5-1.47-.18-.59-.27-1.21-.28-1.82-.03-1.22.33-2.31.69-3.45.03-.1-.11-.15-.17-.08-.78.96-1.04,2.28-1.05,3.48,0,.63.08,1.26.24,1.87.15.55.32,1.26.79,1.62.11.09.29,0,.28-.14Z\"><\/path><path d=\"M62.83,40.5c-.15-.46-.48-.85-.7-1.28-.24-.47-.43-.97-.57-1.47-.31-1.07-.42-2.25-.29-3.36,0-.08-.11-.11-.13-.02-.25,1.14-.3,2.26-.03,3.41.22.93.65,2.32,1.47,2.91.12.09.3-.02.25-.17Z\"><\/path><path d=\"M52.89,41.31c.38.15.83.12,1.24.21.44.09.87.23,1.27.42.86.39,1.66.99,2.26,1.74.04.06.13-.02.1-.08-.54-.86-1.2-1.54-2.08-2-.71-.38-1.85-.86-2.73-.57-.13.04-.18.24-.05.29Z\"><\/path><path d=\"M59.59,32.84c-2.68.76-5.35,1.03-8.12,1.12-1.37.05-2.73.07-4.1.1-.74.02-1.49.03-2.23.05-.7.02-1.48-.07-2.12.24-.1.05-.14.22-.01.27.61.25,1.28.15,1.93.14.74-.02,1.48-.05,2.23-.07,1.49-.05,2.99-.09,4.48-.17,2.69-.14,5.52-.43,8.03-1.46.14-.06.07-.27-.08-.22Z\"><\/path><path d=\"M66.4,34.71c-2.25-2.49-5.24-4.37-8.54-5.07-3.6-.76-7.11.27-10.4,1.72-3.02,1.33-6.41,3.37-7.62,6.62.06.05.12.1.18.16,1.53-2.72,3.85-4.59,6.65-5.93,2.96-1.42,6.37-2.58,9.69-2.24,6.38.65,11.82,5.96,13.35,12.06.96,3.81.37,7.77-1.4,11.25-.15.3.31.52.47.23,3.44-5.99,2.17-13.76-2.38-18.79Z\"><\/path><path d=\"M70.19,47.97c-.07-1.22-.77-2.49-1.37-3.54-.71-1.23-1.58-2.35-2.46-3.46-.88-1.1-1.78-2.18-2.62-3.31-.86-1.15-1.49-2.41-2.28-3.6-.05-.07-.14,0-.12.06.34,1.26,1.22,2.43,1.97,3.48.8,1.12,1.68,2.18,2.54,3.26.85,1.06,1.66,2.15,2.37,3.31.38.62.72,1.26,1.01,1.93.27.63.42,1.3.7,1.93.06.14.28.1.27-.06Z\"><\/path><path d=\"M40.2,37.94c-.99-1.34-3.05-.87-3.51.69-.21.72-.05,1.5.49,2.04.48.49,1.36.88,2.01.53.17-.09.08-.35-.08-.39-.53-.11-.99-.06-1.44-.45-.45-.4-.6-.99-.43-1.55.36-1.24,1.83-1.42,2.77-.69.12.09.3-.05.2-.18Z\"><\/path><path d=\"M68.59,53.34c-.13-.03-.19.16-.07.23.83.43,1.35,1.5.7,2.31-.76.96-1.75.43-2.55-.13-.29-.2-.6.16-.36.42.92.99,2.64,1.09,3.4-.14.65-1.05.08-2.44-1.13-2.69Z\"><\/path><path d=\"M57.52,52.23c-1.76-1.17-3.8-2.04-5.72-2.92-1-.46-2.02-.9-3.04-1.31-.8-.32-1.82-.91-2.7-.86-.02,0-.03.03-.01.04.65.63,1.82.9,2.65,1.25.98.41,1.95.84,2.91,1.29.93.43,1.84.87,2.75,1.33.98.5,1.93,1.08,2.94,1.53.2.09.43-.21.23-.34Z\"><\/path><path d=\"M57.83,52.55c.01-.3-.45-.38-.46-.08-.09,1.94-1.83,2.99-3.48,3.56-.93.32-1.93.59-2.92.41-.85-.15-1.63-.68-2.27-1.24-1.09-.96-1.87-2.26-2.27-3.66-.42-1.46-.3-2.85-.03-4.31.02-.12-.16-.18-.21-.07-1.37,2.97.22,6.94,2.73,8.78.73.54,1.55.95,2.47,1,1.01.06,2.03-.24,2.97-.59,1.69-.63,3.37-1.83,3.47-3.8Z\"><\/path><path d=\"M66.2,55.55c-1.7,1.94-4.18,3.33-6.61,4.13-2.57.86-5.33,1.08-8,.61-5.48-.97-10.17-4.71-12.11-9.96-1.14-3.07-1.18-6.32-.31-9.46.03-.12-.16-.18-.21-.07-2.25,5.12,0,11.61,3.77,15.39,4.08,4.1,10.27,5.67,15.84,4.24,3.09-.79,5.61-2.43,7.96-4.53.27-.24-.09-.63-.33-.36Z\"><\/path><path d=\"M49.29,60.08c-.33.53-.38,1.2-.63,1.77-.28.65-.94,1.49-1.76,1.3-1.74-.4-.49-3.06-.28-4.14.01-.07-.08-.1-.11-.04-.56,1.21-1.72,3.9.19,4.59,1.8.66,2.87-2.04,3.14-3.31.07-.34-.39-.44-.55-.18Z\"><\/path><path d=\"M20.75,40.82c-.23-.44-.54-.88-.57-1.39-.04-.6.36-1.02.76-1.4.68-.65,1.26-1.25,1.62-2.14.36-.91.5-1.88.57-2.85.08-1.18.22-2.32.37-3.49.05-.39-.47-.46-.59-.11-.33,1.02-.26,2.19-.32,3.25-.06.97-.15,1.95-.49,2.86-.33.89-.9,1.47-1.57,2.11-.51.49-.94,1.07-.88,1.81.07.83.66,1.47,1,2.19.42.9.55,1.94.39,2.92-.32,1.98-1.83,3.45-3.62,4.21-.04.02-.03.09.02.09,1.65-.28,2.98-1.4,3.66-2.93.75-1.69.51-3.54-.33-5.14Z\"><\/path><path d=\"M25.2,29.47c-.54-1.22-1.02-2.5-1.66-3.67-.14-.26-.54-.03-.45.23.02.05.04.1.06.15-.6.98-1.14,2-1.73,2.99-.08.14.04.29.17.33,1.12.3,2.24.41,3.4.32.16-.01.29-.2.22-.35ZM21.98,29.12c.49-.85.94-1.75,1.27-2.68.38.98.86,1.94,1.31,2.89-.87.05-1.73-.02-2.58-.21Z\"><\/path><path d=\"M22.49,42.08c-.71.07-2.66.47-2.51,1.51.17,1.22,1.77.44,2.38.26.05-.02.05-.1,0-.11-.23-.02-.45-.02-.68.03-.19.03-.38.12-.57.14-.51.04-.62-.63-.23-.89.53-.36,2.46-.97,2.58,0,.07.6-.47,1.36-.76,1.84-.43.71-.93,1.38-1.5,1.98-.16.17.11.4.27.23.94-.95,1.89-2.11,2.31-3.4.33-1.01-.23-1.71-1.29-1.6Z\"><\/path><path d=\"M22.37,43.81c.01-.15-.17-.21-.25-.08-.22.39-.52,1.01-.45,1.47.02.12.16.17.25.08.32-.35.42-1.02.45-1.47Z\"><\/path><path d=\"M20.87,45.42c.04-.86-.49-1.94-1.09-2.64.09-.03.13-.13.08-.22-.19-.32-.58-.4-.94-.3-.41.11-.42.51-.44.89-.06.91.29,1.93,1,2.53.48.4,1.35.64,1.39-.25ZM20.21,45.77c-.14.04-.43-.26-.52-.35-.42-.44-.71-.98-.8-1.58-.03-.24-.07-.56,0-.79.11-.34.31-.35.55-.31.29.47.58.93.79,1.45.11.28.3.7.3,1,0,.19-.09.53-.32.59Z\"><\/path><path d=\"M20.16,45.9c-.03-.1-.15-.1-.22-.04-.21.19-.29.41-.6.47-.37.07-.7-.09-.91-.39-.21-.29-.28-.66-.32-1.01-.03-.31-.05-1.41.57-1.06.05.03.12-.04.08-.09-.33-.42-.83-.16-.98.28-.2.57-.07,1.41.21,1.94.28.52.79.84,1.39.75.39-.06.94-.37.79-.83Z\"><\/path><path d=\"M18.76,46.35c-.06-.07-.15-.07-.21.02-.18.28-.38.55-.73.31-.24-.16-.36-.5-.38-.77-.04-.41.14-.96.57-1.1.06-.02.06-.12-.01-.13-.99-.13-1.13,1.21-.81,1.88.2.41.6.75,1.08.65.36-.08.81-.49.49-.85Z\"><\/path><path d=\"M17.49,45.55c-.32-.34-.56-.87-1-1.07-.29-.13-.71-.12-.95.11-.28.28-.15.68.1.92.23.22.51.4.76.6.22.17.42.4.71.42.1,0,.19-.08.15-.18-.12-.33-.49-.5-.76-.7-.18-.14-1.06-.7-.5-.84.35-.09.59.24.78.46.18.2.36.38.63.46.11.04.15-.12.09-.18Z\"><\/path><path d=\"M33.22,57.62c.04-.16.09-.31.14-.46-.6-.22-1.24-.37-1.84-.6-.69-.27-1.36-.58-2.01-.92-1.31-.7-2.56-1.54-3.67-2.52-2.33-2.05-3.88-4.56-5.27-7.29-.03-.06-.13-.03-.11.04.8,2.9,2.83,5.51,5.04,7.49,1.11,1,2.33,1.89,3.63,2.61.7.39,1.43.73,2.18,1.03.6.24,1.26.52,1.91.64Z\"><\/path><path d=\"M32.57,60.12c-3.04-1.02-5.74-2.5-8.02-4.78-2.28-2.27-3.93-5.08-4.91-8.14-.02-.05-.11-.04-.1.02,1.32,6.23,6.63,11.89,12.86,13.44.31.08.48-.44.18-.54Z\"><\/path><path d=\"M80.11,61c-.51-1.08-1.23-2.1-1.85-3.13-.29-.47-.75-1.31-1.37-.75-.51.46-.36,1.3-.1,1.84.43.9,1.28,1.53,1.9,2.29.05.07.17.01.14-.07-.2-.45-.47-.8-.8-1.16-.39-.43-1.39-1.43-1.09-2.1-.04-.24.09-.31.38-.22.23-.14.37-.11.43.07.11.09.19.32.26.44.2.33.4.66.59.99.39.65.75,1.35,1.21,1.96.11.15.38.03.3-.15Z\"><\/path><path d=\"M85.94,56.12c-.04-.37-.37-.42-.67-.38-1.13.17-2.24,1.04-3.05,1.79-.49.46-.95.96-1.38,1.47-.35.43-.82.92-.95,1.47,0,.03.03.05.06.04.77-.42,1.33-1.44,1.94-2.08.72-.76,1.54-1.45,2.49-1.91.19-.09.42-.22.63-.26.15-.09.3-.08.44.04-.1.14-.21.27-.35.38-.44.43-.9.84-1.36,1.26-.97.9-1.94,1.8-2.9,2.71-.21.2.13.48.34.29,1.29-1.21,2.58-2.41,3.87-3.62.31-.29.95-.71.89-1.22Z\"><\/path><path d=\"M87.5,57.91c-.92-.4-1.81-.1-2.65.34-1.05.55-2.06,1.21-3.02,1.91-.04.03,0,.1.04.08.84-.36,1.65-.76,2.45-1.2.77-.43,1.67-.97,2.57-.82-1.56,1.2-3.22,2.14-4.96,3.07-.24.13-.03.52.22.42,1.95-.8,3.77-2.06,5.39-3.39.13-.11.15-.34-.03-.41Z\"><\/path><path d=\"M87.87,60.14c-2-.75-3.74.25-5.38,1.31-.05.03,0,.13.05.1,1.41-.71,3.11-1.51,4.7-1.13-1.57.99-3.25,1.5-5.09,1.81-.28.05-.25.47.04.45,2.03-.14,4.05-1,5.71-2.15.13-.09.13-.33-.03-.39Z\"><\/path><path d=\"M85.82,62.81c-.94-.51-2.36-.83-3.3-.16-.04.03-.02.09.03.09.53,0,1.05-.11,1.59-.06.42.04.81.16,1.18.34-.55.33-1.16.5-1.81.53-.61.03-1.35-.2-1.92.02-.19.07-.2.33-.02.42.61.32,1.62.11,2.28,0,.73-.12,1.42-.36,2.01-.82.13-.1.11-.28-.03-.36Z\"><\/path><path d=\"M78.63,61.01c-1.14.55-2.15,1.37-3.26,1.98-1.28.71-2.64,1.3-4.08,1.58-1.53.3-3.12.24-4.67.15-.78-.04-1.55-.1-2.32-.23-.34-.06-.67-.13-1.01-.2-.07.19-.14.39-.21.58.42.04.85.06,1.26.1.82.06,1.64.14,2.46.18,1.54.08,3.11.12,4.63-.19,1.25-.26,2.45-.74,3.58-1.33,1.27-.66,2.67-1.42,3.74-2.38.1-.09.03-.32-.13-.24Z\"><\/path><path d=\"M81.8,63.58c-1.71.05-3.27.52-4.88,1.08-1.71.59-3.41,1.11-5.19,1.43-1.79.31-3.62.47-5.44.35-1.19-.08-2.35-.29-3.5-.54-.06.23-.12.46-.18.69,1.13.19,2.3.26,3.43.3,1.84.06,3.68,0,5.51-.27,1.71-.26,3.37-.74,5-1.31,1.71-.6,3.47-1.28,5.28-1.49.14-.02.12-.22-.02-.22Z\"><\/path><path d=\"M61.95,70.61c.16-.49.18-1.05.27-1.55.11-.59.24-1.18.37-1.76.23-.98.67-2,.82-3.01-.16-.03-.33-.05-.49-.07-.45.87-.65,1.95-.88,2.86-.16.62-.29,1.25-.41,1.89-.1.54-.28,1.13-.23,1.69.18-.03.36-.04.55-.03Z\"><\/path><path d=\"M33.97,55.21c-.6,1.08-.92,2.33-1.26,3.51-.36,1.26-.71,2.53-.98,3.81-.07.32.43.41.5.09.27-1.24.55-2.48.89-3.7.34-1.21.81-2.41,1.03-3.65.02-.11-.13-.15-.18-.06Z\"><\/path><path d=\"M63.59,64.02c-1.14-.43-2.44-.58-3.62-.85-1.19-.27-2.38-.56-3.56-.85-1.18-.3-2.37-.6-3.55-.92-1.14-.3-2.4-.81-3.58-.84-.1,0-.11.14-.03.18.95.57,2.21.77,3.28,1.06,1.22.33,2.44.65,3.67.95,1.18.3,2.37.58,3.56.86,1.19.28,2.48.71,3.71.79.21.01.36-.3.13-.39Z\"><\/path><path d=\"M46.47,59.79c-.95-.58-2.04-.92-3.07-1.32-1-.38-2.01-.75-3.03-1.1-.95-.33-1.91-.65-2.87-.95-1.11-.34-2.38-.53-3.33-1.21-.37-.26-.74.3-.34.52.86.48,1.91.65,2.85.93,1.18.34,2.34.72,3.5,1.12,1.06.37,2.1.75,3.15,1.14,1.02.38,2.02.84,3.09,1.04.1.02.14-.12.05-.17Z\"><\/path><path d=\"M37.57,63.94c-.33-.25-.67-.28-1.07-.36-.54-.11-1.08-.23-1.61-.35-.9-.2-1.8-.46-2.72-.59.01-.01.01-.03,0-.04-.22-.17-.4-.2-.57.06-.06.1-.06.25.06.3.96.39,1.99.6,3,.83.5.12.99.23,1.49.34.46.1.9.26,1.36.15.14-.03.17-.25.06-.34Z\"><\/path><path d=\"M61.83,70.37c-.5-.08-1.02-.03-1.52-.04-.67-.02-1.32-.1-1.98-.23-.59-.12-1.17-.27-1.74-.45-.54-.17-1.08-.44-1.65-.47-.07,0-.11.07-.06.12.76.75,2.24,1.01,3.25,1.23,1.11.24,2.55.6,3.68.36.27-.06.34-.48.02-.52Z\"><\/path><path d=\"M37.49,63.8c-.85,1.53-1.5,3.16-2.21,4.75-.73,1.64-1.47,3.27-2.23,4.89-.73,1.59-1.47,3.17-2.22,4.75-.77,1.62-1.62,3.2-2.35,4.84-.15.34.34.58.52.25.84-1.57,1.55-3.24,2.31-4.85.76-1.62,1.51-3.25,2.25-4.88.72-1.59,1.43-3.19,2.13-4.79.7-1.61,1.45-3.21,1.97-4.89.03-.1-.12-.14-.17-.06Z\"><\/path><path d=\"M56.85,88.92c-.31-.76-.8-1.45-1.15-2.2-.34-.75-.65-1.53-.9-2.32-.52-1.62-.82-3.32-.93-5.02-.11-1.7-.02-3.41.28-5.09.28-1.64.9-3.16,1.29-4.77.02-.08-.1-.14-.15-.07-.91,1.36-1.34,3.16-1.63,4.75-.31,1.69-.41,3.41-.31,5.13.1,1.71.4,3.41.89,5.06.26.86.56,1.7.92,2.53.33.74.67,1.63,1.2,2.26.19.23.62.06.49-.25Z\"><\/path><path d=\"M53.16,79.21c-3.55.17-7.14-.2-10.57-1.13-1.73-.47-3.42-1.07-5.06-1.81-1.62-.73-3.1-1.71-4.69-2.46-.07-.03-.13.06-.07.11,1.32,1.15,3.03,1.94,4.62,2.66,1.63.74,3.31,1.34,5.03,1.82,3.52.98,7.14,1.4,10.79,1.24.28-.01.24-.45-.04-.43Z\"><\/path><path d=\"M44.16,84.98c-.32-.26-.67-.3-1.07-.41-.49-.13-.99-.28-1.48-.42-.97-.29-1.94-.65-2.93-.86-.14-.03-.18.16-.07.22.88.53,1.86.85,2.83,1.18.43.14.86.28,1.3.4.43.12.87.32,1.31.23.16-.03.25-.23.11-.34Z\"><\/path><path d=\"M39.52,83.66c-.34.21-.5.54-.71.87-.27.43-.54.87-.82,1.31-.53.85-1.2,1.7-1.57,2.64-.05.13.1.23.2.13.71-.72,1.2-1.68,1.76-2.51.29-.43.57-.85.86-1.28.22-.33.45-.61.51-1.01.02-.13-.12-.22-.23-.15Z\"><\/path><path d=\"M48.1,92.05c-.34-.62-.9-1.14-1.34-1.68-.43-.54-.83-1.1-1.2-1.68-.4-.62-.76-1.27-1.06-1.94-.21-.47-.3-1.18-.77-1.44-.06-.03-.17,0-.19.07-.19.57.33,1.24.58,1.74.32.63.67,1.25,1.05,1.85.41.64.86,1.25,1.35,1.83.42.5.89,1.07,1.48,1.38.08.04.14-.06.11-.12Z\"><\/path><path d=\"M36.6,88.35c-1.35-.87-2.7-1.75-4.06-2.61-1.34-.86-2.67-1.82-4.13-2.46-.07-.03-.14.06-.08.12,1.17,1.05,2.57,1.85,3.89,2.7,1.39.9,2.78,1.78,4.17,2.68.25.16.45-.26.2-.42Z\"><\/path><path d=\"M56.88,88.94c-1.51.46-3.02.92-4.52,1.38-.71.22-1.42.44-2.13.67-.38.12-.75.23-1.13.35-.21.07-.41.15-.62.22,0,0-.23.09-.36.18-.01-.03-.04-.05-.07-.06-.02,0-.04,0-.06,0-.06,0-.1.02-.13.07-.01.02-.02.03-.03.05-.04.06,0,.13.04.17.3.32,1.06-.05,1.41-.14.89-.24,1.77-.52,2.65-.78,1.72-.51,3.44-1.04,5.16-1.56.36-.11.16-.66-.2-.55Z\"><\/path><path d=\"M30.46,84.78c-.55,1.04-.97,2.16-1.48,3.22-.56,1.15-1.14,2.28-1.76,3.4-.6,1.08-1.21,2.15-1.86,3.2-.66,1.08-1.42,2.12-1.99,3.25-.07.14.12.26.22.15.85-.92,1.51-2.02,2.17-3.07.68-1.08,1.34-2.18,1.96-3.29.62-1.12,1.21-2.25,1.76-3.4.49-1.02,1.04-2.05,1.42-3.12-.15-.1-.3-.21-.44-.34Z\"><\/path><path d=\"M32.25,85.88c-1.14,2.45-2.27,4.86-3.63,7.21-.66,1.15-1.35,2.28-2.07,3.39-.73,1.13-1.63,2.22-2.17,3.45-.02.04.03.09.07.06.96-.85,1.64-1.99,2.35-3.05.75-1.12,1.47-2.26,2.15-3.42,1.39-2.37,2.74-4.84,3.83-7.37-.18-.09-.35-.18-.53-.27Z\"><\/path><path d=\"M66.96,92.47c-1.12.55-2.15,1.1-3.38,1.36-1.2.25-2.44.29-3.65.11-1.17-.17-2.33-.54-3.36-1.14-.56-.32-1.07-.8-1.49-1.28-.38-.43-.6-.89-.8-1.39-.22.09-.43.16-.66.23.29,1.01,1.26,1.88,2.14,2.34,1.21.65,2.38,1.21,3.74,1.46,2.43.45,5.61.1,7.55-1.57.06-.05.02-.19-.07-.14Z\"><\/path><path d=\"M67.6,93.95c-2.53,1.49-5.25,1.94-8.14,1.46-1.56-.26-3.12-.71-4.45-1.58-1.21-.79-2.06-1.85-2.74-3.09-.23.06-.46.12-.68.19,1.4,3.01,4.68,4.39,7.8,4.9,2.76.45,6.14.2,8.29-1.8.05-.04-.02-.11-.07-.08Z\"><\/path><path d=\"M67.89,93.48c-.09-.22-.23-.43-.41-.58-.1-.08-.21-.16-.33-.2-.11-.03-.19,0-.29-.03-.02,0-.03.02,0,.03.31.12.59.58.69.87.06.2.1.41.07.62-.03.18-.11.33-.1.51,0,.07.09.14.17.11.44-.21.38-.94.23-1.32Z\"><\/path><path d=\"M70.37,96.5c-.09-.77-.34-1.55-.6-2.27-.23-.64-.51-1.37-.99-1.86-.65-.67-2.2-.79-2.18.45,0,.21.28.21.37.07.7-1.1,1.7.22,2.02.88.4.82.77,1.7.93,2.61.03.17.05.33.05.5,0,.11,0,.22-.03.32-.24.14-.49.27-.73.41-.39-.04-.84-.84-1.02-1.14-.43-.7-.68-1.46-.94-2.23-.03-.1-.17-.06-.17.04.05,1.21.7,2.86,1.74,3.57,1.05.72,1.67-.38,1.55-1.33Z\"><\/path><path d=\"M25.06,98.57c-.37.07-.69.13-.99-.17-.29-.29-.39-.72-.54-1.09-.05-.11-.2-.07-.2.04,0,.57.14,1.22.63,1.57.35.25,1.04.36,1.25-.13.04-.1-.03-.25-.16-.23Z\"><\/path><path d=\"M24.4,99.48c-1.17-.32-2.36-.43-3.48-.96-.93-.44-1.79-1.13-2.27-2.05-.77-1.47,1.5-1.09,2.2-.78,1.05.46,2,1.12,2.89,1.84.08.06.21-.04.13-.12-.9-1.01-2.09-1.91-3.39-2.32-.73-.23-2.25-.35-2.49.69-.1.46.26,1.01.5,1.37.37.56.88,1.01,1.44,1.38,1.25.82,2.9,1.28,4.38,1.38.27.02.35-.35.08-.42Z\"><\/path><path d=\"M32.95,2.61c-4.06-3.22-10.03-3.4-14.48-.88-4.53,2.56-7.04,7.99-6.36,13.11.74,5.58,5.59,10.56,11.28,10.95,0,0,.01,0,.02,0-.17.1-.34.2-.51.3-.2.12-.03.45.19.36,2.58-.99,5.09-2.58,7.24-4.32,2.08-1.69,3.92-3.75,5.03-6.21,2-4.45,1.63-10.11-2.4-13.3ZM35.22,14.7c-.95,2.65-2.75,4.89-4.89,6.69-2.11,1.79-4.51,3-6.88,4.36.03-.04.02-.09-.04-.11-4.8-.98-9.09-4.34-10.48-9.15-1.41-4.85.45-10.5,4.5-13.53C21.35.04,26.93-.35,31.18,2.07c2.21,1.26,3.84,3.23,4.47,5.71.58,2.27.35,4.73-.44,6.92Z\"><\/path><path d=\"M54.71,42.23c-.33.59-.65,1.19-.94,1.8-.26.54-.58,1.1-.66,1.7-.02.14.15.23.25.12.39-.46.58-1.07.8-1.63.25-.63.47-1.28.69-1.92.03-.09-.09-.15-.13-.06Z\"><\/path><path d=\"M52.49,45.57c0-.07-.02-.12-.06-.17.01-.04.01-.08-.02-.12-.06-.07-.15-.11-.24-.08-.04,0-.08.03-.11.06-.09.05-.17.14-.15.26.01.08.04.17.11.22.09.07.19.08.29.05.1-.02.16-.14.17-.23Z\"><\/path><path d=\"M54.3,46.25c-.05-.07-.13-.12-.22-.14-.09-.02-.18,0-.25.06-.11.07-.14.18-.15.31,0,.12-.02.24.06.34.11.13.26.16.4.07.11-.06.14-.19.18-.3.04-.11.05-.24-.03-.34Z\"><\/path><path d=\"M50.24,39.71c-.97-.64-3.17-.16-3.23,1.21,0,.22.27.28.42.2.36-.2.56-.57.93-.77.42-.23.96-.32,1.42-.12.85.38,1.01,1.48.5,2.19-.07.1.04.23.15.16,1.02-.64.73-2.27-.18-2.86Z\"><\/path><path d=\"M61.39,44.57c-.7-.49-1.61-.49-2.34-.05-.14.08-1.26,1.12-.68,1.21.07.01.09-.09.02-.11,0,0,0,0,0,0,.22-.19,1.03-.69,1.17-.75.54-.2,1.15-.13,1.6.25.45.37.67.98.4,1.53-.25.51-.72.61-1.2.8-.16.06-.18.3-.02.37.75.34,1.57-.4,1.82-1.08.3-.81-.08-1.7-.77-2.18Z\"><\/path><\/g><path d=\"M52.68,41.92c-1.6,2.96-5.96,2.64-6.88-.67-.55-1.93.63-4.11,2.54-4.71,3.27-1.05,5.94,2.42,4.34,5.38h0ZM52.18,41.65c1.35-2.51-.9-5.45-3.67-4.59-1.66.5-2.68,2.39-2.18,4.05.81,2.79,4.5,3.05,5.86.54h0Z\"><\/path><path d=\"M64.48,47.48c-1.58,2.86-5.87,2.38-6.8-.74-.61-1.86.54-4.03,2.43-4.58,3.17-.98,5.95,2.39,4.37,5.32h0ZM63.92,47.18c1.3-2.47-.97-5.3-3.67-4.55-1.68.45-2.71,2.32-2.19,3.99.84,2.74,4.52,3.07,5.86.55h0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-684239b elementor-widget elementor-widget-heading\" data-id=\"684239b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bewegung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71a82fa elementor-widget elementor-widget-heading\" data-id=\"71a82fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u201eDie Bewegung ist von wesentlicher Bedeutung f\u00fcr das Leben<br>und somit wesentlicher Faktor beim Aufbau der Intelligenz.\u201c<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b392d68 elementor-widget elementor-widget-heading\" data-id=\"b392d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Maria Montessori<\/div>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53817ba e-con-full e-flex e-con e-child\" data-id=\"53817ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-98c5987 e-con-full e-flex e-con e-child\" data-id=\"98c5987\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40f0fab elementor-widget elementor-widget-image\" data-id=\"40f0fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"654\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2730-2.png\" class=\"attachment-large size-large wp-image-1237\" alt=\"Kinder spielen und klettern auf dem Au\u00dfengel\u00e4nde des Integrativen Montessori Kindergartens Bayreuth mit Spielhaus, Schaukel und Kletterger\u00fcst\" srcset=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2730-2.png 700w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2730-2-300x280.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb23711 e-con-full e-flex e-con e-child\" data-id=\"eb23711\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4cb17 elementor-widget elementor-widget-text-editor\" data-id=\"ef4cb17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Alle Kinder haben von Natur aus ein gro\u00dfes Bewegungsbed\u00fcrfnis. Sie erlernen dabei nicht nur vielf\u00e4ltige motorische F\u00e4higkeiten und Fertigkeiten, sondern sie entwickeln auch ein gutes K\u00f6rpergef\u00fchl. Sie erkennen eigene Grenzen und gewinnen an Sicherheit und Selbstvertrauen. Wissenschaftliche Studien belegen, dass Bewegung eng mit dem Lernen verbunden ist. Sie f\u00f6rdert den Aufbau des Gehirns durch Vernetzung der Nervenzellen und Bildung von Synapsen, welche f\u00fcr die Entwicklung der Intelligenz notwendig sind.<\/p><p>Die Einbeziehung der Motorik ist in der Montessori-P\u00e4dagogik etwas sehr Grundlegendes. Die Arbeit mit dem Montessori-Material erm\u00f6glicht eine Einbeziehung der k\u00f6rperlichen Aktivit\u00e4t des Kindes. Alle \u00dcbungen sind mit Bewegungen verkn\u00fcpft und sprechen das Muskelged\u00e4chtnis des Kindes an. Vielf\u00e4ltige Bewegungs-und Balance\u00fcbungen wie z. B. das Gehen auf der Linie unterst\u00fctzen die bewusste Bewegungskoordination.<\/p><p>Die Bewegungsm\u00f6glichkeiten im Alltag der Kinder haben sich seit geraumer Zeit drastisch verringert. F\u00fcr uns ist es deshalb wichtig, an allen Tagen den Kindern abwechslungsreiche und vielf\u00e4ltige Bewegungsm\u00f6glichkeiten zu bieten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8eda806 e-flex e-con-boxed e-con e-parent\" data-id=\"8eda806\" data-element_type=\"container\" data-e-type=\"container\" id=\"elternarbeit\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-72b1b77 e-con-full e-flex e-con e-child\" data-id=\"72b1b77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-11e2af5 e-con-full e-flex e-con e-child\" data-id=\"11e2af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-066ad4c elementor-widget elementor-widget-heading\" data-id=\"066ad4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Elternarbeit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-619111e elementor-absolute elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"619111e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M23.28,72c-1.86-2.92-3.72-5.84-5.59-8.77-1.75-2.75-3.19-5.71-6.05-7.61-.6-.4.16-1.15.76-.99,2.8.78,4.08,3.86,5.41,5.97l6.01,9.52c2,3.17,4.03,6.33,5.98,9.53,1.8,2.94,3.93,5.84,5.11,9.09.04.1-.14.22-.22.14-2.26-2.3-3.82-5.14-5.57-7.79-1.99-3.01-3.91-6.07-5.85-9.11Z\"><\/path><path d=\"M11.4,79.18c-1.72-2.85-3.46-5.69-5.21-8.52-1.82-2.93-3.94-5.78-5.49-8.85-.38-.75.76-1.5,1.3-.81,4.28,5.4,7.52,11.8,11.04,17.67,3.38,5.63,7.36,11.4,9.56,17.61.08.22-.28.36-.42.2-4.28-5.22-7.31-11.56-10.78-17.29Z\"><\/path><path d=\"M.43,60.48c3.66-2.37,3.72-2.18,7.55-4.27,2.72-1.49,2.41-2.02,5.67-1.84.28.01.39.34.17.52-2.85,2.26-2.02,1.14-5.19,2.94-3.5,1.98-3.57,2.45-7.21,4.18-1.02.48-2-.87-.99-1.52Z\"><\/path><path d=\"M21.36,95.59c3.66-2.37,3.72-2.18,7.55-4.27,2.72-1.49,2.41-2.02,5.67-1.84.28.01.39.34.17.52-2.85,2.26-2.02,1.14-5.19,2.94-3.5,1.98-3.57,2.45-7.21,4.18-1.02.48-2-.87-.99-1.52Z\"><\/path><g><path d=\"M68.61,43.68c-7.05-6.67-13.61-13.45-17.56-21.27-2.01-3.99-3.75-8.48-1.3-12.56,1.15-1.91,3.97-4.78,7.55-4.35,3.45.42,4.75,3.21,6.27,4.98.08.1.35.06.34-.06-.5-3.5-4.65-7.66-10.5-5.59-6.13,2.17-7.49,7.63-6.64,11.82,1.02,5.06,4.22,10.1,7.68,14.61,3.56,4.66,8.08,9.05,13.85,12.57.16.1.46-.03.32-.16Z\"><\/path><path d=\"M81.11,3.1c-5.98-1.22-11.86,1.29-15.4,4.39-4.74,4.16-5.64,9.33-3.7,14.29.07.17.35.23.56.15.84-.3,1.06-.51,1.11-1.15,0-.03-.07-.04-.08,0-.97.08-1.35-.18-1.13-.76-.02-.29-.01-.57.01-.86.02-.67.03-1.34.13-2.01.18-1.29.66-2.53,1.27-3.75,1.27-2.54,3.28-4.96,6.27-6.76,3.05-1.84,7.07-2.82,11.09-1.98,5.34,1.11,6.23,5.02,5.77,8.31-.86,6.17-6.43,11.85-10.36,17.31-2.01,2.78-4.01,5.57-6.02,8.35-1.52,2.11-3.4,4.35-2.53,6.76.26.71,2.01.58,1.94-.18-.29-3.06,2.34-5.77,4.23-8.45,1.98-2.79,3.96-5.59,5.95-8.38,3.3-4.66,7.15-9.59,8.12-14.78.77-4.09-.59-9.16-7.24-10.52Z\"><\/path><\/g><path d=\"M16.92,59.15c2.12-1.34,6.31-3.97,8.39-5.25,2.44-1.45,5-2.66,7.59-3.81,1.88-.82,3.78-1.6,5.77-2.22,1.09-.31,2.05-.62,3.25-.63.67-.01,1.08.3,1.62.54.49.21,1.02.16,1.54.21.5.09.99.26,1.48.39,5.35,1.54,10.77,3.19,16.02,5.03,2.9,1.07,5.9,2.01,8.63,3.51,2.5,1.83,4.33,5.58,3.4,8.66-1.2,3.7-8.33,3.72-11.51,3.19-2.04-.33-4-1.11-5.95-1.78-2.39-.85-4.71-1.86-7.07-2.72-1.42-.49-2.77-.82-4.2-1.51-.16-.08-.14-.33.03-.38,3.17-1.04,6.2.71,9.06,1.86,1.63.69,3.96,1.7,5.59,2.35.89.37,1.84.73,2.79.94,2.75.71,9.48,1.1,10.6-2.17.55-1.85-.45-3.8-1.61-5.22-.57-.7-1.25-1.41-1.98-1.91-.83-.47-1.75-.81-2.64-1.17-6.61-2.44-13.41-4.61-20.16-6.68-.82-.26-2.1-.59-2.9-.87-.46-.21-.89-.52-1.41-.56-.25-.03-.51,0-.76,0-.73-.05-1.16-.03-1.91.15-2.4.59-4.69,1.58-6.98,2.58-2.5,1.14-5.02,2.29-7.39,3.67-2.08,1.27-6.36,3.83-8.49,5.1-.84.49-1.66-.74-.8-1.31h0Z\"><\/path><path d=\"M69.68,54.6c1.15-.84,2.71-2,3.89-2.78,1.31-.85,2.61-1.79,4.11-2.29,2.47-.53,5.81,1.34,7.37,3.08.57.61,1.08,1.25,1.53,1.95.15.23.08.54-.15.69-.19.12-.43.1-.6-.04-1.14-.91-2.37-2.03-3.63-2.66-1.45-.62-2.82-1.83-4.41-1.5-2.02.68-3.87,1.85-5.73,2.89,0,0-2.1,1.22-2.1,1.22-.38.2-.67-.35-.28-.56h0Z\"><\/path><path d=\"M31.03,81.85c2.04-1.44,4.44-2.5,6.98-2.49,2.41.14,4.68.8,7.01,1.3,3.51.81,6.98,1.83,10.44,2.76.36.11.73.1,1.1.16.58.1,1.16.26,1.74.68.11.08.13.22.05.33-.56.46-1.2.63-1.79.73-.4.07-.86.06-1.26-.01-1.39-.26-2.75-.65-4.08-1.02-3.6-1.02-7.16-2.25-10.8-3.08-.75-.15-1.71-.34-2.43-.36-1.05-.02-2.11.25-3.07.68-.96.42-1.92,1.01-2.68,1.73-.96.89-2.24-.59-1.21-1.42h0Z\"><\/path><path d=\"M75.48,60.9c2.81-1.63,5.77-3.38,8.49-5.15,0,0,4.21-2.68,4.21-2.68.94-.55,1.87-1.27,2.92-1.65,1.97-.51,3.96-.58,5.98-.44.39.04.79.09,1.17.21,3.03,1.29,1.35,6.29.65,8.61,0,0-.4,1.21-.4,1.21-.65,2.16-2.68,3.53-4.43,4.73-3.48,2.27-7.32,4.03-11.03,5.87-.7.36-1.46.73-2.09,1.16-7.07,4.38-14.47,8.19-21.74,12.21-.66.34-1.28-.62-.57-1.05,7.22-4,14.59-7.81,21.6-12.16.74-.5,1.48-.85,2.26-1.24,3.68-1.8,7.57-3.47,10.96-5.7,1.28-.87,2.65-1.87,3.45-3.17.36-.62.52-1.47.68-2.2.33-1.85.5-3.89.05-5.69-.07-.29-.23-.47-.2-.42,0,0,.03.02.05.03,0,0,.01,0,.02,0,0,0-.03,0-.05,0-1.35-.24-2.77-.19-4.14-.13-.77.06-1.6.12-2.03.34-3.44,1.7-7.5,4.01-10.9,5.88-1.46.8-2.9,1.62-4.34,2.46-.67.37-1.26-.62-.58-1.02h0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8fae84 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a8fae84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir verstehen uns als eine die Familie erg\u00e4nzende und unterst\u00fctzende Einrichtung, die gemeinsam mit den Eltern die Entwicklung des Kindes individuell und ganzheitlich f\u00f6rdert. Ein regelm\u00e4\u00dfiger Austausch mit der Familie des Kindes und die Transparenz unserer p\u00e4dagogischen Arbeit sind uns deshalb sehr wichtig.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00a429f e-con-full e-flex e-con e-child\" data-id=\"00a429f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9e617 elementor-widget elementor-widget-image\" data-id=\"1c9e617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"654\" src=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2768-2.png\" class=\"attachment-large size-large wp-image-1249\" alt=\"Eingangsflur des Integrativen Montessori Kindergartens Bayreuth mit buntem KINDER GARTEN Schriftzug aus Einzelbuchstaben an der Wand und Glaseingangst\u00fcr\" srcset=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2768-2.png 700w, https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/12\/DSC2768-2-300x280.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-888162c e-flex e-con-boxed e-con e-parent\" data-id=\"888162c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-249d97b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-n-accordion\" data-id=\"249d97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;multiple&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3830\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3830\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Bildungs- und Erziehungspartner<\/div><div class=\"more\">Mehr erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3830\" class=\"elementor-element elementor-element-730ae64 e-con-full e-flex e-con e-child\" data-id=\"730ae64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a924997 elementor-widget elementor-widget-text-editor\" data-id=\"a924997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr die Bildungs- und Erziehungspartnerschaft ist es uns wichtig, dass Eltern und Kindergarten-Team die gleichen Ziele verfolgen und sich gegenseitig akzeptieren und respektieren. Wir sehen die Eltern als die Experten f\u00fcr ihr Kind an und gehen davon aus, dass sie ihre Verantwortung gegen\u00fcber ihrem Kind ernst nehmen. Im Mittelpunkt der partnerschaftlichen Zusammenarbeit stehen das Wohl und die Entwicklung des Kindes.<\/p><p>Zus\u00e4tzlich sehen wir die aktive Unterst\u00fctzung der Eltern als Gewinn f\u00fcr das Gelingen unserer p\u00e4dagogischen Arbeit an und freuen uns, dass sich die Eltern aktiv an der Gestaltung der Kindergartenarbeit beteiligen.<\/p><p>F\u00fcr unsere Kinder packen alle mit an: sei es ein unterst\u00fctzender Beitrag zum Buffet an unseren Festen, die Erneuerung des Spielsandes im Garten oder stets saubere Handt\u00fccher f\u00fcr jedes Kind.<\/p><p>Um das lebendige Miteinander aller Kindergartenfamilien zu f\u00f6rdern, findet einmal im Jahr eine Familienfreizeit statt. Alle Kindergartenkinder verbringen gemeinsam mit ihren Eltern und Geschwistern und dem Kindergartenteam ein Wochenende in einem nahegelegenen Freizeitheim.<br \/>Mit verschiedenen Ausfl\u00fcgen, Aktionen und Spielen unter einem bestimmten Thema st\u00e4rken wir die Zusammengeh\u00f6rigkeit und unterst\u00fctzen das Gruppengef\u00fchl.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3831\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3831\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Elterndienst<\/div><div class=\"more\">Mehr erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3831\" class=\"elementor-element elementor-element-7307a39 e-con-full e-flex e-con e-child\" data-id=\"7307a39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abb1d55 elementor-widget elementor-widget-text-editor\" data-id=\"abb1d55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Es besteht die M\u00f6glichkeit, dass Eltern eine Woche oder einzelne Tage ihr Kind im Kindergartenalltag in Form eines Elterndienstes begleiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3832\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3832\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Eltern- und Entwicklungsgespr\u00e4che<\/div><div class=\"more\">Mehr erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3832\" class=\"elementor-element elementor-element-3a9f6a0 e-con-full e-flex e-con e-child\" data-id=\"3a9f6a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd39c96 elementor-widget elementor-widget-text-editor\" data-id=\"bd39c96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Einmal im Kindergartenjahr findet f\u00fcr jedes Kind ein Entwicklungsgespr\u00e4ch statt. Zus\u00e4tzlich ergeben sich h\u00e4ufig \u201eT\u00fcr- und Angelgespr\u00e4che\u201c zwischen dem Team und den Eltern. Bei Bedarf und Wunsch durch die Eltern sind wir offen f\u00fcr weitere Gespr\u00e4che<\/p><p>F\u00fcr Kinder mit erh\u00f6htem F\u00f6rderbedarf finden zweimal im Jahr Entwicklungsgespr\u00e4che in Zusammenarbeit mit dem Kindergartenteam, den Eltern und den jeweiligen Therapeuten statt. Dabei werden der aktuelle Entwicklungsstand des Kindes ermittelt sowie Nah- und Fernziele f\u00fcr die weitere Entwicklung gemeinsam festgelegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3833\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3833\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> <div>Elternabend<\/div><div class=\"more\">Mehr erfahren<\/div> <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3833\" class=\"elementor-element elementor-element-7b566f5 e-con-full e-flex e-con e-child\" data-id=\"7b566f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2a18f5 elementor-widget elementor-widget-text-editor\" data-id=\"c2a18f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Im Abstand von 8 bis 12 Wochen trifft sich die Elternschaft zusammen mit dem Kindergartenteam und dem Tr\u00e4gervertreter zum Elternabend.<\/p><p>Der Abend wird von einem Elternpaar moderiert und durchgef\u00fchrt. Die Vorbereitungen hierf\u00fcr werden zusammen mit dem Team getroffen.<\/p><p>Die Elternabende dienen der gemeinsamen Reflexion, Planung und Vorbereitung von anstehenden Aktivit\u00e4ten, Festlegung von Terminen und der Auseinandersetzung mit p\u00e4dagogischen Themen.<\/p><p>Nach Wunsch und Bedarf werden auch Referenten eingeladen oder das Kindergartenteam stellt Schwerpunkte der p\u00e4dagogischen Arbeit vor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-603bda2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"603bda2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 100 100\"><path d=\"M36.25,57.26c4.46,3.27,8.65,6.98,12.86,10.57,4.09,3.49,8.35,7.14,11.44,11.57.1.14-.09.29-.22.22-4.67-2.52-8.78-6.13-12.86-9.51-4.29-3.56-8.79-6.9-13.02-10.53-1.26-1.08.43-3.33,1.8-2.33Z\"><\/path><path d=\"M59.57,77.43c6.63-9.46,13.07-19.04,19.55-28.6,6.48-9.55,12.75-19.31,19.79-28.45.27-.35.84-.05.61.35-5.87,9.92-12.6,19.34-19.05,28.89-6.46,9.56-12.97,19.09-19.3,28.75-.66,1-2.29.04-1.6-.94Z\"><\/path><path d=\"M35.85,55.57c10.67-5.21,21.11-10.92,31.47-16.7,10.36-5.78,20.45-12.08,30.85-17.78.54-.3.98.48.48.81-9.8,6.65-20.22,12.5-30.43,18.5-10.23,6.01-20.59,11.81-30.83,17.8-1.71,1-3.28-1.78-1.54-2.63Z\"><\/path><path d=\"M21.4,38.32c2.37-1.6,6.08-1.79,8.86-2.33,3.39-.66,6.74-1.47,10.1-2.25,6.56-1.51,13.14-2.94,19.69-4.47,13.11-3.06,26.18-6.46,39.45-8.68.5-.08.72.62.21.78-12.84,3.97-26.04,6.78-39.11,9.92-6.38,1.53-12.73,3.17-19.11,4.71-3.35.81-6.71,1.57-10.03,2.5-2.84.8-6.52,2.41-9.46,2.05-1.16-.15-1.66-1.53-.61-2.23Z\"><\/path><path d=\"M1.35,23.2c16.59-.07,33.16-.68,49.73-1.2,8.13-.26,16.25-.5,24.38-.75,4.23-.13,8.45-.25,12.68-.38,3.38-.1,7.61-.87,10.78.5.07.03.07.15,0,.19-3.07,1.57-7.42,1.08-10.78,1.19-4.07.14-8.13.28-12.19.42-8.29.28-16.58.56-24.87.84-16.59.54-33.17,1-49.73,1.99-1.79.11-1.82-2.79,0-2.8Z\"><\/path><path d=\"M1.7,23.49c2.18.8,4.05,2.39,5.96,3.69,1.97,1.34,3.94,2.68,5.91,4.03,3.91,2.67,7.68,5.35,11.1,8.63.46.44-.12,1.05-.64.82-4.4-1.97-8.35-4.5-12.35-7.16l-5.56-3.7c-1.91-1.27-4.16-2.4-5.71-4.1-.82-.9-.04-2.69,1.28-2.21Z\"><\/path><path d=\"M20.4,78.74c1.6-4.11,4.29-7.88,6.8-11.48,2.53-3.63,5.2-7.42,8.33-10.56.69-.69,2.03.26,1.39,1.08-2.7,3.49-5.65,6.76-8.23,10.35-2.58,3.58-4.67,7.52-7.33,11.02-.32.42-1.2.2-.96-.41Z\"><\/path><path d=\"M19.94,58.27c.14-3.53.3-7.06.44-10.59.13-3.13-.27-6.88.7-9.87.27-.82,1.59-.94,1.79,0,.68,3.08-.05,6.73-.22,9.87-.2,3.69-.39,7.38-.59,11.07-.37,6.91-.67,13.92-1.85,20.75-.04.25-.41.17-.42-.06-.53-7.02-.14-14.14.15-21.18Z\"><\/path><path d=\"M19.46,79.02c3.53-3.01,7.82-5.2,11.86-7.45,4.11-2.29,8.3-4.61,12.67-6.38,1.21-.49,2.05,1.53.89,2.12-4.27,2.17-8.69,4.03-12.96,6.2-4.01,2.04-7.88,4.51-12.04,6.23-.4.16-.74-.45-.42-.72Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Konzept Wie wir dieKinder betreuen Grundkonzept&amp; Gruppen Tagesablauf Ern\u00e4hrung &amp;Bewegung Elternarbeit Grundkonzept Unsere Grundprinzipien Unsere grunds\u00e4tzliche Haltung ist es, jeden Menschen so anzunehmen wie er ist. Jedes Kind wird mit seinen individuellen F\u00e4higkeiten und Bed\u00fcrfnissen akzeptiert, gesch\u00e4tzt und respektiert und hat das Recht in der Gemeinschaft zu leben, zu spielen und zu lernen. InklusionMehr \u00fcber [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1390,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1918","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inklusiver Kindergarten Bayreuth \u2013 Montessori &amp; Inklusion - Integrativer Montessori Kindergarten Bayreuth<\/title>\n<meta name=\"description\" content=\"Montessori-P\u00e4dagogik und Inklusion seit \u00fcber 45 Jahren: Im Integrativen Montessori Kindergarten Bayreuth lernen alle Kinder gemeinsam \u2013 nach ihren individuellen St\u00e4rken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integrativer-kiga-bayreuth.de\/en\/konzept\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inklusiver Kindergarten Bayreuth \u2013 Montessori &amp; Inklusion - Integrativer Montessori Kindergarten Bayreuth\" \/>\n<meta property=\"og:description\" content=\"Jedes Kind ist willkommen \u2013 mit und ohne Beeintr\u00e4chtigung. Unser inklusiver Montessori-Kindergarten in Bayreuth steht seit 1970 f\u00fcr gemeinsames Aufwachsen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integrativer-kiga-bayreuth.de\/en\/konzept\/\" \/>\n<meta property=\"og:site_name\" content=\"Integrativer Montessori Kindergarten Bayreuth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T11:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/Logo-KiGa.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2396\" \/>\n\t<meta property=\"og:image:height\" content=\"2288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/\",\"url\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/\",\"name\":\"Inklusiver Kindergarten Bayreuth \u2013 Montessori & Inklusion - Integrativer Montessori Kindergarten Bayreuth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IKB_Kind5.svg\",\"datePublished\":\"2026-07-03T12:45:12+00:00\",\"dateModified\":\"2026-07-14T11:04:44+00:00\",\"description\":\"Montessori-P\u00e4dagogik und Inklusion seit \u00fcber 45 Jahren: Im Integrativen Montessori Kindergarten Bayreuth lernen alle Kinder gemeinsam \u2013 nach ihren individuellen St\u00e4rken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/#primaryimage\",\"url\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IKB_Kind5.svg\",\"contentUrl\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IKB_Kind5.svg\",\"width\":500,\"height\":500,\"caption\":\"Icon Kind-Silhouette als Navigationselement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/konzept\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konzept\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#website\",\"url\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/\",\"name\":\"Integrativer Montessori Kindergarten Bayreuth\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#organization\",\"name\":\"Integrativer Montessori Kindergarten Bayreuth\",\"url\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-KiGa.webp\",\"contentUrl\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-KiGa.webp\",\"width\":2396,\"height\":2288,\"caption\":\"Integrativer Montessori Kindergarten Bayreuth\"},\"image\":{\"@id\":\"https:\\\/\\\/integrativer-kiga-bayreuth.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inklusiver Kindergarten Bayreuth \u2013 Montessori & Inklusion - Integrativer Montessori Kindergarten Bayreuth","description":"Montessori-P\u00e4dagogik und Inklusion seit \u00fcber 45 Jahren: Im Integrativen Montessori Kindergarten Bayreuth lernen alle Kinder gemeinsam \u2013 nach ihren individuellen St\u00e4rken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integrativer-kiga-bayreuth.de\/en\/konzept\/","og_locale":"en_GB","og_type":"article","og_title":"Inklusiver Kindergarten Bayreuth \u2013 Montessori & Inklusion - Integrativer Montessori Kindergarten Bayreuth","og_description":"Jedes Kind ist willkommen \u2013 mit und ohne Beeintr\u00e4chtigung. Unser inklusiver Montessori-Kindergarten in Bayreuth steht seit 1970 f\u00fcr gemeinsames Aufwachsen.","og_url":"https:\/\/integrativer-kiga-bayreuth.de\/en\/konzept\/","og_site_name":"Integrativer Montessori Kindergarten Bayreuth","article_modified_time":"2026-07-14T11:04:44+00:00","og_image":[{"width":2396,"height":2288,"url":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/Logo-KiGa.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/","url":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/","name":"Inklusiver Kindergarten Bayreuth \u2013 Montessori & Inklusion - Integrativer Montessori Kindergarten Bayreuth","isPartOf":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/#primaryimage"},"image":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/#primaryimage"},"thumbnailUrl":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2026\/01\/IKB_Kind5.svg","datePublished":"2026-07-03T12:45:12+00:00","dateModified":"2026-07-14T11:04:44+00:00","description":"Montessori-P\u00e4dagogik und Inklusion seit \u00fcber 45 Jahren: Im Integrativen Montessori Kindergarten Bayreuth lernen alle Kinder gemeinsam \u2013 nach ihren individuellen St\u00e4rken.","breadcrumb":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integrativer-kiga-bayreuth.de\/konzept\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/#primaryimage","url":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2026\/01\/IKB_Kind5.svg","contentUrl":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2026\/01\/IKB_Kind5.svg","width":500,"height":500,"caption":"Icon Kind-Silhouette als Navigationselement"},{"@type":"BreadcrumbList","@id":"https:\/\/integrativer-kiga-bayreuth.de\/konzept\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/integrativer-kiga-bayreuth.de\/"},{"@type":"ListItem","position":2,"name":"Konzept"}]},{"@type":"WebSite","@id":"https:\/\/integrativer-kiga-bayreuth.de\/#website","url":"https:\/\/integrativer-kiga-bayreuth.de\/","name":"Integrated Montessori Kindergarten Bayreuth","description":"","publisher":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integrativer-kiga-bayreuth.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/integrativer-kiga-bayreuth.de\/#organization","name":"Integrated Montessori Kindergarten Bayreuth","url":"https:\/\/integrativer-kiga-bayreuth.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/integrativer-kiga-bayreuth.de\/#\/schema\/logo\/image\/","url":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/Logo-KiGa.webp","contentUrl":"https:\/\/integrativer-kiga-bayreuth.de\/wp-content\/uploads\/2025\/10\/Logo-KiGa.webp","width":2396,"height":2288,"caption":"Integrativer Montessori Kindergarten Bayreuth"},"image":{"@id":"https:\/\/integrativer-kiga-bayreuth.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/pages\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/pages\/1918\/revisions"}],"predecessor-version":[{"id":1919,"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/pages\/1918\/revisions\/1919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/integrativer-kiga-bayreuth.de\/en\/wp-json\/wp\/v2\/media?parent=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}